{"id":9681,"date":"2014-07-26T12:02:00","date_gmt":"2014-07-26T15:02:00","guid":{"rendered":"https:\/\/espacocriativo.net\/acervo\/historia\/historia-sem-nome\/rascunho-automatico\/"},"modified":"2026-02-08T12:03:20","modified_gmt":"2026-02-08T15:03:20","slug":"capitulo-33","status":"publish","type":"capitular","link":"https:\/\/espacocriativo.net\/acervo\/historia\/big-change\/capitulo-33\/","title":{"rendered":"Cap\u00edtulo 33"},"content":{"rendered":"\n<p>&emsp;&emsp;<strong>Liam\u2019s POV<\/strong><br \/>\n&emsp;&emsp;Acordei de madrugada, com uma enorme dor de cabe\u00e7a. Fui at\u00e9 a cozinha beber um copo de \u00e1gua, e quando volto, percebo que L\u00ea ainda est\u00e1 acordada; virada na cama, solu\u00e7ando. Ent\u00e3o me lembro da minha terr\u00edvel cagada na noite anterior. Sobre aquele acidente do qual ningu\u00e9m deveria estar sabendo. Talvez isso afete minha amizade com Fer; mas preciso explicar o que de fato aconteceu para L\u00ea.<br \/>\n&emsp;&emsp;Me sentei na cama, e coloquei minha m\u00e3o nas suas costas. Fazendo-a virar.<br \/>\n&emsp;&emsp;- Quer conversar m\u00f4r? \u2013perguntei, e pude ver um leve sorriso surgir em seu rosto. \u2013 Olha, o que eu falei, foi uma situa\u00e7\u00e3o constrangedora entre mim e a Fer, quando nem nos conhec\u00edamos ainda. Foi um acidente, entende?<br \/>\n&emsp;&emsp;- Acho que sim Liam. Mas sabe o que me deixa assim? N\u00e3o ter a certeza se \u00e9 s\u00f3 isso mesmo. <br \/>\n&emsp;&emsp;- L\u00ea! Como voc\u00ea pode pensar algo assim? \u2013realmente me surpreendi com Let\u00edcia dizendo aquilo.<br \/>\n&emsp;&emsp;- Voc\u00eas s\u00e3o muito pr\u00f3ximos Liam, aquela bagun\u00e7a que fizeram na cozinha antes de virmos para c\u00e1? Voc\u00eas est\u00e3o sempre conversando&#8230; <br \/>\n&emsp;&emsp;- N\u00e3o chega! Eu e ela, somos apenas amigos, vivemos na mesma casa; e apenas encontramos um no outro algu\u00e9m para conversarmos. \u2013 estava come\u00e7ando a suar com essa conversa desconfort\u00e1vel.<br \/>\n&emsp;&emsp;- Voc\u00ea tem raz\u00e3o, estou sendo rid\u00edcula. Mas \u00e9 s\u00f3 que&#8230; Sei l\u00e1. Mas n\u00e3o vou ficar chateada com ela, voc\u00eas realmente n\u00e3o t\u00eam culpa do acontecido.<br \/>\n&emsp;&emsp;- Obrigado m\u00f4r, sabia que voc\u00ea iria entender. \u2013disse. L\u00ea se sentou no meu colo me fazendo deitar na cama. Tirou sua blusinha do pijama, e ent\u00e3o comecei a tirar minha bermuda e sua calcinha. <br \/>\n&emsp;&emsp;Ela come\u00e7ou a beijar meu peito delicadamente, quando se posicionou em cima de mim. Segurei sua cintura e entrei devagar nela, fazendo-a e contorcer. <br \/>\n&emsp;&emsp;- Liam, eu te&#8230; amo <br \/>\n&emsp;&emsp;- Eu tamb\u00e9m. \u2013L\u00ea se abaixou para me beijar, enquanto eu for\u00e7ava os movimentos e acariciava seus lindos seios. At\u00e9 que ela estava sem f\u00f4lego, assim como eu; e atingimos um orgasmo juntos. Podia sentir seu cora\u00e7\u00e3o acelerado.<\/p>\n\n<p align=\"center\">&#8230;<\/p>\n\n<p>&emsp;&emsp;<strong>Zayn\u2019s POV<\/strong><br \/>\n&emsp;&emsp;Depois do clima pesado de ontem anoite, o medo de todos, era que o resto da viagem fosse arruinada. Mas agora na van indo buscar as crian\u00e7as para ir \u00e0 praia, percebo que est\u00e1 tudo bem. Fer e Liam, conversaram sobre o assunto, acho. E est\u00e3o normais um com o outro. Niall e Liam, assim como L\u00ea e Fer tamb\u00e9m; parece que nada foi modificado.<br \/>\n&emsp;&emsp;As crian\u00e7as entraram na van gritando, loucas para colocarem os p\u00e9s na areia. <br \/>\n&emsp;&emsp;- Princesas, o que est\u00e3o achando sobre ir \u00e0 praia?<br \/>\n&emsp;&emsp;- Aah papai, queremos chegar logo! \u2013Sasha disse tentando colocar o cinto.<br \/>\n&emsp;&emsp;- Amor, acho que elas n\u00e3o v\u00e3o \u00e0 praia, uns 2 anos hahaha. \u2013Perrie me lembra, deitada em meu peito.<br \/>\n&emsp;&emsp;- Tudo isso?<br \/>\n&emsp;&emsp;- Ahaam. <br \/>\n&emsp;&emsp;Descemos da van, pisando naquela areia branca. Por incr\u00edvel que pare\u00e7a Niall conseguiu mesmo, fechar um bom peda\u00e7o da praia para n\u00f3s. E logo os guarda sois estavam montados, e as crian\u00e7as na \u00e1gua.<br \/>\n&emsp;&emsp;Perrie tirou seu vestido ficando apenas com o biqu\u00edni, e mesmo depois de anos, ainda consigo ficar com cara de bobo olhando seu corpo. <\/p>\n\n<p align=\"center\">&#8230;<\/p>\n\n<p>&emsp;&emsp;<strong>Harry\u2019s POV<\/strong><br \/>\n&emsp;&emsp;- Harry, pode passar protetor nas minhas costas? \u2013Samy senta entre minhas pernas.<br \/>\n&emsp;&emsp;- Vem c\u00e1, pequena. \u2013massageio seus ombros, e a sinto estremecer com meu toque.<br \/>\n&emsp;&emsp;Fomos com Ally para a \u00e1gua, e o que mais me emociona, \u00e9 perceber que elas s\u00e3o as mulheres mais importantes na minha vida. E que do jeito que ela est\u00e1 n\u00e3o poderia estar melhor.<br \/>\n&emsp;&emsp;- A \u00e1gua ta boa Harry?<br \/>\n&emsp;&emsp;- Aham, vai l\u00e1 Nialler! \u2013e logo Niall se levanta, pega Fer no colo segurando suas pernas e sua cabe\u00e7a, e sai correndo em dire\u00e7\u00e3o \u00e0 \u00e1gua.<br \/>\n&emsp;&emsp;- E voc\u00eas? N\u00e3o v\u00e3o? \u2013ent\u00e3o Zayn, Liam e Louis me olham.<br \/>\n&emsp;&emsp;- Vamos! \u2013Louis levanta e arrasta todo mundo para a \u00e1gua, inclusive eu e Samy de novo.<br \/>\n&emsp;&emsp;Sa\u00edmos da praia atarde e fomos para o hotel, cansados e cheirando \u00e0 sal. <\/p>\n\n<p>&emsp;&emsp;<strong>Niall\u2019s POV<\/strong><br \/>\n&emsp;&emsp;Desde que chegamos no hotel, percebi que Fer ficou calada. Talvez seje porque amanh\u00e3 j\u00e1 voltamos para Inglaterra? Estranho ela estar assim de repente. Ou \u00e9 pelo ocorrido de ontem? <br \/>\n&emsp;&emsp;- Amor? Por que essa carinha? \u2013pergunto me juntando a ela na sacada, admirando a cidade.<br \/>\n&emsp;&emsp;- \u00c9 porque, agora, aqui vendo a cidade; me deu um certo remorso pela morte da minha m\u00e3e. Voc\u00ea lembra Niall? \u2013como poderia esquecer, eu estava naquela hora, e fui no enterro.<br \/>\n&emsp;&emsp;- Claro amor. Voc\u00ea est\u00e1 pensando em ir no t\u00famulo dela?<br \/>\n&emsp;&emsp;- O que voc\u00ea acha? \u2013ela perguntou me olhando, com uma l\u00e1grima descendo pelo seu rosto.<br \/>\n&emsp;&emsp;- Acho uma boa ideia, eu vou com voc\u00ea. \u2013ela me abra\u00e7ou, com um leve sorriso.<br \/>\n&emsp;&emsp;Gabi j\u00e1 estava organizando as malas para que no dia seguinte, n\u00e3o tivesse muito o que fazer; j\u00e1 que sair\u00edamos cedo. E foi o que todos come\u00e7aram a fazer.<br \/>\n&emsp;&emsp;Eu e Fer, descemos e chamamos um t\u00e1xi para nos levar at\u00e9 o cemit\u00e9rio. Ao chegar, pedi que ele esperasse.<br \/>\n&emsp;&emsp;Foi t\u00e3o doloroso, v\u00ea-la andar at\u00e9 o t\u00famulo com o nome de sua m\u00e3e, e n\u00e3o poder fazer nada para acabar com seu sofrimento. Fiquei ali, atr\u00e1s para que ela pudesse ter algum momento a s\u00f3s. Mas ela logo se virou para tr\u00e1s, fazendo um sinal com a cabe\u00e7a. Caminhei at\u00e9 seu lado e ent\u00e3o consegui ler o que estava escrito na l\u00e1pide.<\/p>\n\n<p>&emsp;&emsp;Fer se apoiou em mim, solu\u00e7ando. Abracei-a e pude sentir ela abafar o choro no meu peito; e sem perceber vi uma l\u00e1grima descer pelo meu rosto, caindo no cabelo dela.<br \/>\n&emsp;&emsp;- Voc\u00ea sabe que pode contar comigo para tudo n\u00e3o \u00e9? Eu sempre vou estar aqui. <br \/>\n&emsp;&emsp;- Eu sei Niall. Voc\u00ea \u00e9 o melhor marido do mundo. \u2013 ela disse limpando as l\u00e1grimas que ainda estavam em seu rosto.<\/p>\n\n<p align=\"center\">&#8230;<\/p>\n\n<p>&emsp;&emsp;<strong>L\u00ea\u2019s POV<\/strong><br \/>\n&emsp;&emsp;Niall e Fer chegaram, e resolvemos pedir pizza. Niall, Louis e Liam apostaram quem comeria mais e no fim Louis acabou ganhando 200 pratas nessa inocente aposta.<br \/>\n&emsp;&emsp;Fomos para a cama cedo, depois do longo dia na praia, e eu s\u00f3 podia querer me aconchegar na cama com Liam. <br \/>\n&emsp;&emsp;Acordamos cedo, e j\u00e1 estavam colocando as malas na van l\u00e1 em baixo. Fui para a cozinha, e vi Gabi ainda tomando seu caf\u00e9.<br \/>\n&emsp;&emsp;- Bom dia, animada para voltar \u00e0 Inglaterra L\u00ea?<br \/>\n&emsp;&emsp;- Quando uma viagem acaba n\u00e3o t\u00e3o legal assim, mas eu quero nossa casa de volta hahaha.<br \/>\n&emsp;&emsp;- Concordo, deixa eu ir l\u00e1; Louis fica perdido tendo que arrumar o cabelo de Catherine. \u2013ela levantou quando ouvio um gritinho da filha.<br \/>\n&emsp;&emsp;Fomos para o aeroporto, que estava igualmente lotado, e logo est\u00e1vamos dentro do jatinho. Aproveitei a oportunidade de todos estarem juntos; me levantei e puxei Liam comigo segurando suas m\u00e3os. Ficamos na frente de todos e ent\u00e3o anunciei:<br \/>\n&emsp;&emsp;- Liam, voc\u00ea vai ser pai. \u2013todos come\u00e7aram a berrar nos seus assentos, e a n\u00f3s parabenizar. Liam com os olhos brilhando me puxou delicadamente pela cintura e me beijou suavemente, com l\u00e1grimas escorrendo em seu rosto. A \u00faltima vez que o vi com os olhos brilhantes como estavam agora foi em nosso casamento.<br \/> \n<p align=\"center\">&#8230;<\/p>\n\n<p>&emsp;&emsp;Chegamos em casa, e claro que todos n\u00f3s comemoramos, a fam\u00edlia Direction ganharia mais um membro.<\/p><\/p>\n\n<p align=\"center\"><strong><em>Fim. <\/em><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>&emsp;&emsp;Liam\u2019s POV &emsp;&emsp;Acordei de madrugada, com uma enorme dor de cabe\u00e7a. Fui at\u00e9 a cozinha beber um copo de \u00e1gua, e quando volto, percebo que L\u00ea ainda est\u00e1 acordada; virada na cama, solu\u00e7ando. Ent\u00e3o me lembro da minha terr\u00edvel cagada na noite anterior. Sobre aquele acidente do qual ningu\u00e9m deveria estar sabendo. Talvez isso afete [&hellip;]<\/p>\n","protected":false},"author":160,"featured_media":0,"parent":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":true,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"historias":[2527],"class_list":["post-9681","capitular","type-capitular","status-publish","format-standard","hentry","historias-big-change"],"acf":[],"_links":{"self":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular\/9681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular"}],"about":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/types\/capitular"}],"author":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/users\/160"}],"replies":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/comments?post=9681"}],"wp:attachment":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/media?parent=9681"}],"wp:term":[{"taxonomy":"historias","embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/historias?post=9681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}