{"id":9436,"date":"2026-01-09T14:17:36","date_gmt":"2026-01-09T17:17:36","guid":{"rendered":"https:\/\/espacocriativo.net\/acervo\/historia\/historia-sem-nome\/rascunho-automatico\/"},"modified":"2026-01-09T14:24:51","modified_gmt":"2026-01-09T17:24:51","slug":"capitulo-35","status":"publish","type":"capitular","link":"https:\/\/espacocriativo.net\/acervo\/historia\/vincere\/capitulo-35\/","title":{"rendered":"Cap\u00edtulo 35"},"content":{"rendered":"\r\n<p align=\"right\"><strong><em>%Pietra% Perroni<\/em><\/strong><\/p>\r\n<p>\u2003\u2003<span class=\"versalete\">O cheiro era de<\/span> terra \u00famida, eu olhava para a sepultura que tinha sido cavada, o c\u00e9u estava nublado, nuvens carregadas de chuva acima de n\u00f3s apenas esperando o seu momento para derramar \u00e1gua. Parecia que o universo tamb\u00e9m lamentava a morte de Luna, assim como eu e minhas irm\u00e3s que segu\u00edamos de m\u00e3os dadas, esperando o padre terminar de falar e aguardando o momento do enterro. Eu nem sequer estava ouvindo o que ele falava, meu corpo parecia fraco demais, anestesiado era a palavra, tinha a sensa\u00e7\u00e3o que a qualquer momento eu desmaiaria. N\u00f3s tr\u00eas dormimos juntas nos \u00faltimos dois dias, sempre com ajuda de um rem\u00e9dio para dormir, foi o \u00fanico jeito de descansarmos. Mal t\u00ednhamos comido, apenas ficamos juntos durante todo o tempo, compartilhando aquela dor que parecia rasgar o peito. Luna tinha uma vida inteira pela frente e pela minha falta de confian\u00e7a em acertar aquele tiro, sua vida foi ceifada em minha frente.<br>\u2003\u2003Acordei dos meus pensamentos quando %Matteo% me abra\u00e7ou de lado e beijou minha t\u00eampora. Levantei a cabe\u00e7a percebendo que o sil\u00eancio se fazia presente e atrav\u00e9s das lentes dos meus \u00f3culos escuros, vi meu pai deixar a rosa vermelha, caracter\u00edstica em nossos funerais, em cima do caix\u00e3o. Vi Beatrice beijar a rosa em sua m\u00e3o e tamb\u00e9m deixar na madeira, em seguida Giulia fez o mesmo, tirando tamb\u00e9m o anel que ela e Luna usavam como s\u00edmbolo de sua irmandade e deixou junto da flor. Dei dois passos chegando em frente ao caix\u00e3o e fechei os olhos sentindo as l\u00e1grimas descerem sem qualquer dificuldade. Beijei a rosa e coloquei na madeira, passando a palma em cima dele tamb\u00e9m.<br>\u2003\u2003\u2014 <em>Mi dispiace, sorellina (Me desculpe, irm\u00e3zinha) <\/em>\u2014 disse baixo, com pesar.<br>\u2003\u2003%Matteo% tamb\u00e9m deixou sua rosa e ent\u00e3o me puxou pela m\u00e3o, caminhamos lentamente em dire\u00e7\u00e3o ao nosso carro, onde o soldado j\u00e1 estava no volante, aguardando. Durante todo o caminho pra casa eu mantive meus olhos na janela, eu nem queria pensar, queria simplesmente voltar no tempo e fazer diferente. Era sufocante sentir aquela culpa. Assim que o carro estacionou em frente \u00e0 mans\u00e3o eu desci, entrei em casa e o sil\u00eancio me abra\u00e7ou. Segui caminho para o meu quarto, assim que passei pela porta sentei na minha cama e joguei os \u00f3culos escuros em cima do edredom. Respirei fundo e soltei o ar com for\u00e7a, como se aquilo fosse tirar o peso dos meus ombros. Cruzei as pernas e tirei meu sapato, fazendo o mesmo com o outro e ent\u00e3o vi %Matteo% escorado no batente da porta.<br>\u2003\u2003\u2014 Voc\u00ea est\u00e1 bem?<br>\u2003\u2003\u2014 Imposs\u00edvel estar bem\u2026<br>\u2003\u2003\u2014 Eu sei, s\u00f3 queria ter a certeza de que n\u00e3o h\u00e1 nada que eu possa fazer.<br>\u2003\u2003\u2014 Se voc\u00ea n\u00e3o tem uma m\u00e1quina do tempo, n\u00e3o, n\u00e3o tem nada que voc\u00ea possa fazer. \u2014 Levantei da cama e caminhei at\u00e9 o meu banheiro, me pus diante do espelho e peguei um disco de algod\u00e3o, colocando demaquilante nele para poder tirar a maquiagem que fiz pra esconder as olheiras fundas em meus olhos.<br>\u2003\u2003\u2014 Fizemos o que pod\u00edamos, %Tita%, n\u00e3o fa\u00e7a o que eu sei que est\u00e1 fazendo. \u2014 Ele se aproximou de mim e massageou meus ombros, fazendo eu parar de passar o algod\u00e3o em meu rosto e fechar os olhos. \u2014 Eu sei que d\u00f3i, eu, mais do que ningu\u00e9m, sei disso. Falhei com todas voc\u00eas.<br>\u2003\u2003\u2014 Eu podia ter evitado\u2026 Eu podia\u2026 \u2014 Minha voz embargou com o choro que insistia em querer sair.<br>\u2003\u2003\u2014 Essa dor vai passar, eu prometo. \u2014 %Matteo% segurou na minha cintura e me virou para si, olhando em meus olhos com carinho.<br>\u2003\u2003A pior parte era ter que seguir minha vida sem ela. Quando perdemos algu\u00e9m nos damos conta de que n\u00e3o somos nada perante o mundo. Os dias ainda v\u00e3o passar, sua fam\u00edlia ainda vai trabalhar pela manh\u00e3, assim como os anos passar\u00e3o e voc\u00ea ser\u00e1 esquecido em algum momento. <strong>Todos choram a nossa morte, mas ningu\u00e9m morre com a gente.<\/strong> A grande verdade era que eu sabia que passaria e talvez esse fosse o meu maior medo, eu n\u00e3o queria esquecer minha irm\u00e3, n\u00e3o queria esquecer seu rosto, seu sorriso, suas manias e a sua voz. Luna era vida, deveria ser proibido termos que lidar com sua morte.<br>\u2003\u2003\u2014 Engra\u00e7ado \u00e9 que nunca me preocupei, sempre achei que morreria primeiro. \u2014 Ri sem qualquer humor abaixando a cabe\u00e7a.<br>\u2003\u2003%Matteo% afastou meu cabelo para tr\u00e1s da orelha e ent\u00e3o levantou meu rosto pelo queixo para encar\u00e1-lo. Senti seus l\u00e1bios nos meus, macios e leves, um beijo carinhoso, que fez com que eu me sentisse um pouco melhor. Fechei os olhos e uma l\u00e1grima teimosa rolou por minha bochecha, fazendo eu limp\u00e1-la rapidamente.<br>\u2003\u2003\u2014 Presenciar o que eu presenciei s\u00f3 me fez ver o quanto eu n\u00e3o posso garantir que nada aconte\u00e7a, mas se depender de mim, vou sempre proteger voc\u00eas com a minha vida. \u2014 Virei pro espelho novamente e o encarei s\u00e9ria pelo reflexo.<br>\u2003\u2003\u2014 Voc\u00ea j\u00e1 fez isso antes e eu n\u00e3o gostei da sensa\u00e7\u00e3o. \u2014 Segui retirando a maquiagem do meu rosto.<br>\u2003\u2003\u2014 Me desculpe, <em>cari\u00f1o.<\/em><br>\u2003\u2003\u2014 Temos soldados o suficiente para nos proteger, agora voc\u00ea \u00e9 o Don, aja como tal.<br>\u2003\u2003\u2014 Logo voc\u00ea dizendo isso pra mim?<br>\u2003\u2003\u2014 \u00c9 a realidade, n\u00e3o? Temos que seguir com as obriga\u00e7\u00f5es. \u2014 Engoli o choro mais uma vez e mantive minha express\u00e3o impass\u00edvel. \u2014 Alguma novidade de como Luca se infiltrou na mans\u00e3o?<br>\u2003\u2003\u2014 Estou dando tempo ao tempo, Giulia precisa respirar um pouco.<br>\u2003\u2003\u2014 Precisamos descobrir se tem mais algum traidor.<br>\u2003\u2003\u2014 N\u00f3s tamb\u00e9m precisamos respirar um pouco\u2026 \u2014 Ele me abra\u00e7ou por tr\u00e1s e beijou meu pesco\u00e7o colocando a cabe\u00e7a apoiada em meu ombro e em seguida olhando em meus olhos pelo reflexo do espelho. \u2014 Sinta o luto, %Pietra%, faz parte da vida aceitarmos que \u00e0s vezes precisamos apenas sofrer.<br>\u2003\u2003\u2014 N\u00e3o me parece algo \u00fatil ficar sofrendo no meu quarto enquanto n\u00e3o matarmos todos os respons\u00e1veis pela morte da Luna. \u2014 Senti minha voz embargar, eu n\u00e3o queria chorar, n\u00e3o queria mais ser fraca.<br>\u2003\u2003\u2014 Seja paciente. \u2014 Ele se colocou ao meu lado e me virou pra ele, senti seu polegar acariciar minha bochecha, mordi meu l\u00e1bio com for\u00e7a, fechando os olhos me controlando pra n\u00e3o cair em prantos. \u2014 Eu n\u00e3o quero que voc\u00ea se sinta no dever de ficar forte, perdemos nossa irm\u00e3, est\u00e1 tudo bem cair\u2026 eu estarei aqui todas as vezes pra te levantar. \u2014 Abri os olhos e o encarei com ternura.<br>\u2003\u2003\u2014 Eu\u2026 a verdade \u00e9 que eu n\u00e3o sei seguir faltando um peda\u00e7o meu, %Matteo%, minhas irm\u00e3s s\u00e3o meu mundo e me sinto incompleta sem a Luna. \u2014 L\u00e1grimas come\u00e7aram a escorrer pelo meu rosto e ent\u00e3o ele me puxou para seu peito, fazendo com que eu me entregasse \u00e0quele choro angustiante e segurasse com for\u00e7a em sua camisa. \u2014 D\u00f3i tanto\u2026<br>\u2003\u2003\u2014 Eu sei\u2026<\/p>\r\n<p align=\"center\">[&#8230;]<\/p>\r\n<p>\u2003\u2003Eu simplesmente deitei ali na grama, sozinha, apreciando a lua cheia no c\u00e9u e tentando lidar com aquele espa\u00e7o vazio que ainda parecia estar presente em meu peito. Th\u00e9o deitou logo em seguida com a cabe\u00e7a em minha coxa, ele era um companheiro e tanto, n\u00e3o tinha me deixado sozinha em nenhum momento que fosse, ent\u00e3o realmente, eu nunca estava sozinha. Seria at\u00e9 desrespeitoso falar isso quando tinha a companhia do meu cachorro leal que estava sempre presente. Respirei fundo e fechei os olhos, aproveitei a brisa fresca que corria pelo meu corpo e arrepiava cada poro meu, n\u00e3o chegava a estar frio, mas a temperatura j\u00e1 dava ind\u00edcio de baixar nos primeiros dias do outono. Senti que algo se aproximava e virei a cabe\u00e7a de lado, vendo Beatrice me olhando esquisito.<br>\u2003\u2003\u2014 T\u00e1 tudo bem, %Tita%?<br>\u2003\u2003\u2014 Sim, s\u00f3 aproveitando o jardim. \u2014 Ela pareceu pensar um pouco e sentou-se antes de se deitar tamb\u00e9m, mantendo a cabe\u00e7a perto da minha. \u2014 O que est\u00e1 fazendo?<br>\u2003\u2003\u2014 O mesmo que voc\u00ea. \u2014 Senti ela buscar minha m\u00e3o e apenas entrela\u00e7amos os dedos. \u2014 O c\u00e9u t\u00e1 lindo.<br>\u2003\u2003\u2014 Estaria mais se n\u00e3o tivesse tantas luzes. \u2014 Passou-se alguns minutos e as luzes do jardim se apagaram. \u2014 Mas o que\u2026 \u2014 Olhei pra cima e vi mais uma cabe\u00e7a.<br>\u2003\u2003\u2014 Ouvi o seu pedido. \u2014 Giulia curvou os l\u00e1bios com o celular na m\u00e3o. Fazia algumas semanas que n\u00e3o via ela sorrir.<br>\u2003\u2003\u2014 Obrigada, Sorella. \u2014 Sorri e assisti ela deitar junto com a gente, nossas cabe\u00e7as perto uma das outras e os nossos corpos um pra cada lado. \u2014 Posso ser sincera sem julgamento?<br>\u2003\u2003\u2014 Sim \u2014 as duas responderam em un\u00edssono.<br>\u2003\u2003\u2014 Eu estou feliz, mas ao mesmo tempo n\u00e3o me sinto no direito de estar.<br>\u2003\u2003\u2014 N\u00e3o diga isso, %Tita% \u2014 Bea foi a primeira a se manifestar. \u2014 Eu tenho certeza que a Luna, de onde ela est\u00e1, quer o seu bem e n\u00e3o ficaria satisfeita com voc\u00ea se proibindo de curtir sua felicidade. Voc\u00ea e %Matteo% merecem isso depois de tanto, %Tita%, se permita.<br>\u2003\u2003\u2014 Preciso concordar com a Bea, ela sempre quis o melhor pra todas n\u00f3s, morreu nos protegendo, n\u00e3o fa\u00e7a ter sido em v\u00e3o.<br>\u2003\u2003\u2014 Ainda sinto um buraco em meu peito \u2014 disse, sentindo uma l\u00e1grima escorrer do meu olho.<br>\u2003\u2003\u2014 Esse vazio vamos sempre sentir, nada vai preench\u00ea-lo, esse lugar \u00e9 dela, devemos apenas nos acostumar com ele. \u2014 Giulia pareceu fria, mas eu entendia o que ela queria dizer, ela mais do que ningu\u00e9m sentia esse vazio com propriedade. As duas sempre foram conectadas al\u00e9m do que podia ser considerado algo normal, g\u00eameos tinham esse poder quase sobrenatural. \u2014 Temos que seguir, precisamos seguir.<br>\u2003\u2003\u2014 Eu amo voc\u00eas, com todo o meu cora\u00e7\u00e3o. \u2014 Busquei a m\u00e3o da Giulia, que tamb\u00e9m entrelacei nossos dedos e ela apertou a minha.<br>\u2003\u2003\u2014 Eu tamb\u00e9m \u2014 as duas falaram juntas.<br>\u2003\u2003Eu precisava parar de pensar no que me faltava e sim no que eu tinha, Bea e Giulia estavam ali, estavam t\u00e3o em sofrimento quanto eu, por\u00e9m, ainda est\u00e1vamos juntas e isso deveria importar ainda mais. Todos estavam sentindo o luto de uma forma, mas segu\u00edamos juntos, apoiando um ao outro.<\/p>\r\n<p align=\"center\">[&#8230;]<\/p>\r\n<p>\u2003\u2003Acordei em um rompante, meu peito subia e descia pelo pesadelo que j\u00e1 durava algumas semanas, meu c\u00e9rebro estava me punindo me fazendo ver Luna morrer v\u00e1rias e v\u00e1rias vezes em pesadelos. Olhei para o lado e vi %Matteo% dormindo tranquilamente, respirei fundo e me sentei na cama. Passei a m\u00e3o pelo rosto antes de levantar e pegar meu robe para vestir. Abri a gaveta da mesa de cabeceira com cuidado para n\u00e3o fazer barulho e peguei a carteira de cigarro e o isqueiro. Assim que cheguei na varanda, peguei um da caixa e o acendi, puxando a fuma\u00e7a para os meus pulm\u00f5es. Cruzei os bra\u00e7os em frente ao peito e olhei longe, vendo algumas luzes da cidade ainda acesas.<br>\u2003\u2003Fechei os olhos e senti algumas l\u00e1grimas brotarem, aquela dor conhecida inundava meu peito mais uma vez. Mais uma festa nossa que terminou em trag\u00e9dia, eu estava come\u00e7ando a odiar festas, principalmente as da m\u00e1fia. Os dias j\u00e1 tinham se tornado semanas, o clima na mans\u00e3o estava p\u00e9ssimo, meu pai tinha decidido ficar na Espanha por algum tempo, mas n\u00e3o sa\u00eda do escrit\u00f3rio, nem as refei\u00e7\u00f5es que ele tanto prezava por todos na mesa, estava fazendo conosco. Est\u00e1vamos em um luto doloroso demais pra conseguirmos fazer algo al\u00e9m de sofrer. Nosso inimigo estava morto, era verdade, mas minha irm\u00e3 tamb\u00e9m, ent\u00e3o era imposs\u00edvel comemorar ou sentir algo al\u00e9m de dor, tristeza e \u00f3dio. Do\u00eda tanto. Traguei o cigarro novamente enquanto sentia mais l\u00e1grimas escorrerem pelo meu rosto.<br>\u2003\u2003\u2014 <em>Cari\u00f1o<\/em>\u2026 \u2014 Virei para tr\u00e1s ao ouvir a voz sonolenta de %Matteo%, ele vestia apenas uma cal\u00e7a fina de tecido e seus cabelos medianos estavam bagun\u00e7ados. Sorri minimamente olhando para ele, o \u00fanico que conseguia me deixar melhor durante toda essa tempestade nas nossas vidas. \u2014 O que est\u00e1 fazendo aqui fora?<br>\u2003\u2003\u2014 Perdi o sono\u2026 \u2014 Virei para frente novamente e segui olhando o horizonte. Apaguei o cigarro no cinzeiro que sempre estava ali \u00e0 disposi\u00e7\u00e3o e acendi outro cigarro.<br>\u2003\u2003Senti seus bra\u00e7os em volta do meu corpo e seu nariz em minha nuca, fechei os olhos apreciando o carinho das suas m\u00e3os acariciando-me e seus l\u00e1bios em meu pesco\u00e7o.<br>\u2003\u2003\u2014 Pesadelo de novo? \u2014 perguntou me abra\u00e7ando de maneira firme e eu apenas assenti. \u2014 J\u00e1 disse pra me acordar quando isso acontecer.<br>\u2003\u2003\u2014 Voc\u00ea estava dormindo t\u00e3o bem\u2026<br>\u2003\u2003\u2014 Imposs\u00edvel dormir bem sem voc\u00ea ao meu lado. \u2014 Ele me virou e me olhou nos olhos, seus dedos deslizaram pela minha bochecha descendo para o maxilar e ent\u00e3o seu polegar secou minhas l\u00e1grimas. Senti meus l\u00e1bios serem selados pelos seus logo em seguida, arrancando um curvar de l\u00e1bios meu.<br>\u2003\u2003Seus olhos negros voltaram a me olhar com carinho, era incr\u00edvel estar com algu\u00e9m que te ama at\u00e9 com os olhos. Ele roubou o cigarro de mim e o tragou, ele deu dois passos em dire\u00e7\u00e3o ao guarda corpo e virou pra me olhar. Eu sentia uma mistura de emo\u00e7\u00f5es, eu e %Matteo% finalmente juntos, assumidos e noivos. Ter ele por inteiro, principalmente na minha cama, era algo que me deixava feliz, nem sabia da capacidade que eu tinha em me sentir t\u00e3o bem assim. Aquilo era novo. No entanto, sentia que era errado eu estar feliz ou me sentir bem, j\u00e1 que minha irm\u00e3 estava morta. Eu tentava me libertar da culpa, mas toda vez que eu sentia o m\u00ednimo de felicidade, minha mente me repreendia.<br>\u2003\u2003\u2014 \u00c9 dif\u00edcil entender tudo que passa aqui dentro. \u2014 Passei a m\u00e3o pelo peito desviando os olhos dos dele.<br>\u2003\u2003\u2014 Quer tentar me contar?<br>\u2003\u2003\u2014 Eu e as garotas tivemos uma conversa reveladora h\u00e1 alguns dias, mesmo que racionalmente eu entenda que eu posso ser feliz, algo em mim ainda me diz que n\u00e3o.<br>\u2003\u2003\u2014 Voc\u00ea acha realmente que a Luna ia querer que voc\u00ea estivesse se culpando? Ela fez o que achou que deveria, poderia ter sido qualquer um de n\u00f3s.<br>\u2003\u2003\u2014 Eu sei, mas\u2026<br>\u2003\u2003\u2014 N\u00e3o, %Tita%\u2026 \u2014 %Matteo% me interrompeu \u2014 voc\u00ea n\u00e3o teve culpa, nem voc\u00ea, nem eu e nem Beatrice. \u2014 Ele me entregou o cigarro e eu me aproximei para peg\u00e1-lo, puxei a fuma\u00e7a e a soltei em seguida. \u2014 Luca matou nossa irm\u00e3, a culpa \u00e9 toda dele, e ele vai ter toda a eternidade no inferno pra pagar por isso.<br>\u2003\u2003\u2014 A morte me parece uma op\u00e7\u00e3o boa demais pra ele. \u2014 Dei mais um trago no cigarro e soltei a fuma\u00e7a.<br>\u2003\u2003\u2014 Talvez voc\u00ea tenha raz\u00e3o.<br>\u2003\u2003\u2014 S\u00f3 queria que essa dor passasse. \u2014 Puxei a fuma\u00e7a novamente, fechando os olhos e ent\u00e3o soltei, tentando dissipar aquele sentimento que ainda me perseguia.<br>\u2003\u2003\u2014 O que eu posso fazer pra ajudar?<br>\u2003\u2003\u2014 Queria sentir algo al\u00e9m disso\u2026 \u2014 n\u00e3o finalizei minha frase ao sentir sua m\u00e3o acariciar meu bra\u00e7o e descer para a minha m\u00e3o.<br>\u2003\u2003\u2014 Venha, vamos entrar. \u2014 Ele me puxou com carinho.<br>\u2003\u2003Assenti apagando o cigarro no cinzeiro, %Matteo% foi me guiando e assim que est\u00e1vamos do lado de dentro, ele se manteve \u00e0s minhas costas e come\u00e7ou a tirar meu robe enquanto beijava meu ombro, clav\u00edcula, pesco\u00e7o, fechei os olhos sentindo seus l\u00e1bios descerem mais um pouco enquanto o tecido escorregava pelos meus bra\u00e7os.<br>\u2003\u2003\u2014 N\u00e3o sei se\u2026 \u2014 N\u00e3o fui capaz de terminar a frase com sua m\u00e3o apertando meu seio, fazendo com que eu fechasse os olhos, aproveitando a sensa\u00e7\u00e3o gostosa que se instaurava no meu corpo.<br>\u2003\u2003\u2014 Se quiser que eu pare \u00e9 s\u00f3 pedir, <em>cari\u00f1o<\/em>.<br>\u2003\u2003\u2014 %Matteo%\u2026<br>\u2003\u2003\u2014 Hm\u2026? \u2014 murmurou enquanto beijava meu pesco\u00e7o.<br>\u2003\u2003\u2014 Me ama.<br>\u2003\u2003Encostei a cabe\u00e7a em seu ombro enquanto suas m\u00e3os desciam devagar pela minha barriga, resvalando os dedos de maneira sensual, assim que ele chegou ao final da minha camisola, senti sua m\u00e3o na parte interna da minha coxa. Ele me virou para si e seus beijos voltaram a subir, pendi a cabe\u00e7a para tr\u00e1s enquanto seus l\u00e1bios tra\u00e7aram um caminho at\u00e9 minha boca, fazendo nossas l\u00ednguas se encontrarem lentamente, saboreando o gosto um do outro. Eu estava completamente extasiada, n\u00e3o conseguia fazer nada al\u00e9m de respirar e ficar ansiosa pra saber o pr\u00f3ximo lugar que ele me tocaria. Sua m\u00e3o invadiu minha calcinha por tr\u00e1s, devagar, apertando minha n\u00e1dega, seus dedos resvalaram em minha entrada, mas ele sabia pra onde estava indo, soube disso quando senti a press\u00e3o em meu ponto inchado, fazendo com que eu soltasse um gemido.<br>\u2003\u2003Minhas duas m\u00e3os foram para o seu peitoral, acariciando-o com desejo, passei a l\u00edngua entre meus l\u00e1bios antes de morder o inferior ao t\u00ea-lo me masturbando devagar; torturante. Puxei alguns fios de sua nuca com a m\u00e3o direita e ele me levantou, colocando-me em seu colo fazendo eu suspirar em seu ouvido. Afastei o rosto para olh\u00e1-lo e ent\u00e3o o beijei, dessa vez mais afoita, com voracidade, senti o colch\u00e3o em minhas costas quando ca\u00edmos na cama sem parar os beijos sedentos. Abracei seu tronco com minhas pernas, minha coxa foi agarrada com for\u00e7a e eu senti sua ere\u00e7\u00e3o ro\u00e7ar em meu monte de v\u00eanus. Seus l\u00e1bios desceram para o meu peito e logo ele puxou minha camisola fazendo eu erguer o corpo e os bra\u00e7os para ajud\u00e1-lo a tirar. Sua boca voltou ao meu seio, onde ele deixou uma mordida, arqueei a coluna com a mistura de dor e prazer que ondulou em meu corpo.<br>\u2003\u2003\u2014 %Matteo%\u2026 \u2014 gemi seu nome e vi ele me olhar com sede de algo que s\u00f3 eu poderia dar, mordi o l\u00e1bio inferior sorrindo.<br>\u2003\u2003Seus l\u00e1bios desceram pela minha barriga enquanto uma de suas m\u00e3os ainda massageava meu seio esquerdo. Ele lambeu e mordeu minha buceta por cima do tecido, eu me remexia buscando aplacar todo aquele tes\u00e3o acumulado. Olhei pra baixo e vi ele olhando pra mim enquanto estimulava meu clit\u00f3ris ainda com a calcinha no meio do caminho e mesmo assim ele me levava \u00e0 loucura toda maldita vez. Foi assim que gozei, na minha calcinha e eu via pelo sorriso libidinoso que ele adorava o poder que tinha sobre meu corpo, mas eu iria mostrar quem tinha o controle sobre quem.<br>\u2003\u2003Puxei ele para mim e o beijei, senti meu peito esquentar como nunca antes, cheguei a sorrir entre nossos l\u00e1bios da felicidade que senti me preencher apenas por estarmos juntos. Rebolei meu quadril, me esfregando contra ele, levei a m\u00e3o at\u00e9 sua cal\u00e7a do pijama, incitando que o queria dentro de mim. Invertemos nossas posi\u00e7\u00f5es na cama, sentei bem em cima dele e o vi sorrir de maneira arteira. Eu me apoiava em seu peito e o olhei por completo, aquele homem que eu neguei durante tantos anos, agora era meu noivo, o homem que eu tinha absoluta certeza de que eu queria envelhecer ao lado. <strong>Nunca acreditei que fosse poss\u00edvel, mas com ele, eu queria o at\u00e9 que a morte nos separe.<\/strong><br>\u2003\u2003Voltei a beij\u00e1-lo, as pontas de seus dedos deslizaram pelas minhas costas e suas m\u00e3os apertaram minhas n\u00e1degas, mordi o l\u00e1bio dele e sorri arranhando seu peitoral com minhas unhas. Levantei apenas para puxar a calcinha de lado, assim como tirar a cal\u00e7a dele da frente, e a pr\u00f3xima coisa que me atingiu foi um prazer extasiante quando escorreguei em seu pau, que se enterrou em mim, pulsante. Soltei um gemido sussurrado e encarei o teto respirando fundo, sentindo seu p\u00eanis latejar dentro de mim. Comecei a rebolar devagar, torturando tanto ele quanto a mim mesma, mas uma tortura gostosa demais para ser interrompida.<br>\u2003\u2003\u2014 C\u00e9us, %Pietra%\u2026 \u2014 Ele apertou minhas coxas que estavam rentes na lateral de seu quadril.<br>\u2003\u2003Subi e desci uma vez, e ouvir o gemido rouco dele me tirava a sanidade, era tentador demais, eu queria ouvi-lo mais vezes. Subi e desci novamente e dessa vez olhei pra ele e sua express\u00e3o sentindo prazer me deixava ainda mais extasiada. Continuei subindo e descendo, mantendo um ritmo lento, gostoso e inebriante. Senti sua m\u00e3o em minha barriga, logo apertando meu seio e ent\u00e3o ele agarrou o meu pesco\u00e7o. Queria v\u00ea-lo, mas o prazer me obrigava a fechar os olhos e soltar gemidos agudos com os movimentos luxuriosos. Sentia meu interior fervendo, os dedos de %Matteo% afundavam em minha carne e eu comecei a aumentar a velocidade, assim como minhas unhas fincaram no peito dele.<br>\u2003\u2003\u2014 %Matteo%, eu vou\u2026 \u2014 apertei os olhos sentindo meu corpo inteiro retesar \u2014 oh, <em>santa madre!<\/em><br>\u2003\u2003\u2014 N\u00e3o para, %Pietra%\u2026 \u2014 Ele tamb\u00e9m come\u00e7ou a mexer o quadril, fazendo com que nossos quadris se chocassem com ainda mais for\u00e7a. Sua m\u00e3o deixou meu pesco\u00e7o e as duas agarraram meu quadril, cada vez que eu descia ele for\u00e7ava ainda mais quando eu sentava, empurrando meu quadril pra baixo. \u2014 Hmm\u2026 \u2014 Ouvi seu grunhido e sua express\u00e3o de prazer extremo tomar conta e aquilo pra mim foi o estopim, gritei jogando a cabe\u00e7a para tr\u00e1s ao atingir o orgasmo novamente.<br>\u2003\u2003Sentia meu corpo quente demais, eu respirava pela boca para conseguir voltar ao normal mais rapidamente, olhei para ele, que estava com os olhos fechados, ent\u00e3o deitei em seu peito em seguida. Nossos cora\u00e7\u00f5es estavam batendo acelerados, sincronizados, ainda tent\u00e1vamos recuperar o f\u00f4lego, senti sua m\u00e3o acariciando minha nuca, tirando os cabelos das minhas costas suadas para poder passar a ponta de seus dedos tamb\u00e9m ali. Sorri me sentindo segura, cuidada e principalmente amada. Depois de semanas eu conseguia me sentir bem pela primeira vez.<br>\u2003\u2003\u2014 Eu amo tanto voc\u00ea, %Tita%, voc\u00ea n\u00e3o sabe o quanto. \u2014 Seus dedos deslizavam para cima e para baixo em minhas costas e eu sorri fazendo carinho em seu peito.<br>\u2003\u2003\u2014 Eu sei, voc\u00ea tomou um tiro por mim, esqueceu? \u2014 falei, brincando.<br>\u2003\u2003\u2014 Tem raz\u00e3o, acho que mostrei o quanto. \u2014 Ele riu e beijou o topo da minha cabe\u00e7a.<br>\u2003\u2003\u2014 Eu tamb\u00e9m te amo muito\u2026 \u2014 Olhei pra ele e sorri, pensando no quanto eu era sortuda por t\u00ea-lo, at\u00e9 mesmo quando o odiava. \u2014 Mas n\u00e3o vou tomar um tiro por voc\u00ea pra provar. \u2014 Soltei uma risada e ele me abra\u00e7ou forte.<br>\u2003\u2003\u2014 Fique comigo para sempre que ser\u00e1 prova o suficiente.<br>\u2003\u2003\u2014 Definitivamente esse era o meu plano.<\/p>\r\n<p align=\"center\">[&#8230;]<\/p>\r\n<p align=\"right\"><strong><em>%Matteo% Perroni<\/em><\/strong><\/p>\r\n<p>\u2003\u2003\u2014 Qual \u00e9 a do sorrisinho na cara? \u2014 Virei para o lado ao ouvir a voz do meu primo.<br>\u2003\u2003\u2014 N\u00e3o sabia dessa sua nova caracter\u00edstica.<br>\u2003\u2003\u2014 Qual? \u2014 Ele franziu o cenho.<br>\u2003\u2003\u2014 Fofoqueiro. \u2014 Ele fez careta e cruzou os bra\u00e7os. \u2014 Vamos ao trabalho? \u2014 Sentei na minha cadeira do escrit\u00f3rio e suspirei.<br>\u2003\u2003\u2014 Nosso informante me passou as fotos do mandante por tr\u00e1s do Estevan\u2026 O problema \u00e9 que\u2026 bom, veja voc\u00ea mesmo. \u2014 Ele colocou o tablet em cima da mesa e ent\u00e3o eu vi a foto de Luca.<br>\u2003\u2003Arregalei os olhos, como aquele desgra\u00e7ado estava controlando tudo por todos os lados e n\u00f3s n\u00e3o sab\u00edamos? Depois de alguns meses procurando alguma pista de quem mandava a droga pra aqueles quase ainda adolescentes, descobrimos que era o Luca, mais essa agora. Ele estava nos rondando h\u00e1 bastante tempo, Estevan estava na cola da %Pietra% quase que desde que ela assumiu a dire\u00e7\u00e3o da <em>Fascino,<\/em> aquilo era ultrajante.<br>\u2003\u2003\u2014 Como ele conseguiu estar t\u00e3o perto da gente e ningu\u00e9m saber de nada, Filippo? \u2014 Bufei e dei um gole no copo baixo de whisky que eu j\u00e1 estava bebendo. \u2014 Carolyn estava dentro da nossa casa, aquela cadela que transava com o cara que confiei minha vida, quase casou comigo! \u2014 Alterei meu tom de voz, irritado.<br>\u2003\u2003\u2014 Ele foi astuto, soube manejar tudo para nos tirar o foco do que realmente importava. \u2014 Filippo sentou na poltrona do outro lado da mesa. \u2014 O importante agora, \u00e9 saber comemorar a vit\u00f3ria.<br>\u2003\u2003\u2014 Estou me sentindo um idiota, isso sim!<br>\u2003\u2003\u2014 Ter algu\u00e9m que seja um pouco mais inteligente n\u00e3o \u00e9 motivo pra nos sentirmos idiotas, afinal, voc\u00ea mesmo matou ele, n\u00e3o?<br>\u2003\u2003\u2014 Sim, mas\u2026<br>\u2003\u2003\u2014 N\u00e3o tem \u201cmas\u201d, primo \u2014 ele me interrompeu e deu um sorriso presun\u00e7oso \u2014, saiba o momento de parar e aceitar, no fim, os Perroni ganharam a guerra.<br>\u2003\u2003Comemorar a vit\u00f3ria parecia algo t\u00e3o errado depois que perdemos a Luna, essa vit\u00f3ria tinha um gosto amargo, que inundava a minha boca com arrependimentos. Eu podia ter agido mais r\u00e1pido, eu deveria ter percebido, insistido para %Pietra% demitir aquele homem. Contudo, agora, n\u00e3o adiantava pensar no que poderia ter sido, Filippo tinha raz\u00e3o, mas ent\u00e3o por que parecia t\u00e3o dif\u00edcil de engolir?<br>\u2003\u2003Quando eu estava com muita raiva eu me imaginava matando o Luca novamente, rever em minha mente dava at\u00e9 uma sensa\u00e7\u00e3o de dever cumprido, por\u00e9m, logo me dava conta de que eu n\u00e3o teria mais a chance de escutar Luna chamando meu nome ou me pedindo pra ajudar nos treinos, e isso tudo me deixava possesso. Eu tinha ficado triste e sofrido nos primeiros dias, depois a raiva vinha vez ou outra me visitar. %Pietra% era a \u00fanica pessoa que me acalmava, que me mantinha s\u00e3o, at\u00e9 porque, eu queria ser o porto seguro dela, assim como ela era o meu.<br>\u2003\u2003Passamos muito tempo separados, brigas, \u00f3dio, remorso, decep\u00e7\u00e3o, n\u00f3s tivemos os piores sentimentos rondando a gente, por\u00e9m agora, tudo era bom, o amor estava sempre presente quando est\u00e1vamos juntos. O carinho com que ela me olhava, a alegria que seus olhos transpareciam e os abra\u00e7os que duravam minutos, tudo isso me deixava transbordando felicidade. Jamais imaginei esse momento em minha vida, nunca achei que era poss\u00edvel sentir um amor t\u00e3o genu\u00edno como o que eu sentia por ela.<br>\u2003\u2003Por mais que toda a trag\u00e9dia que aconteceu na festa tenha nos colocado em um lugar escuro, precis\u00e1vamos nos agarrar ao que t\u00ednhamos de bom. Nossa fam\u00edlia sempre estava em uma montanha russa, quando cheg\u00e1vamos no nosso auge, ca\u00edamos em um buraco sem fundo de desgra\u00e7as. Contudo, eu queria mudar isso, queria mudar, seja l\u00e1 que maldi\u00e7\u00e3o que nos acompanhava, minhas irm\u00e3s precisavam de uma vida est\u00e1vel e feliz. %Pietra% merecia isso tamb\u00e9m, mais do que ningu\u00e9m, ela passou por tanto. Posso dizer que at\u00e9 eu preciso de um pouco de paz, n\u00e3o seria de todo mau.<br>\u2003\u2003\u2014 Filippo, chame %Pietra%, preciso conversar com ela.<br>\u2003\u2003\u2014 Acho que ela est\u00e1 na boate, %Matteo%.<br>\u2003\u2003\u2014 N\u00e3o importa onde ela esteja, quero ela aqui.<br>\u2003\u2003\u2014 <em>Si signore.<\/em><br>\u2003\u2003Vi ele sair do escrit\u00f3rio, peguei meu copo e virei o l\u00edquido antes de ir at\u00e9 o carrinho de bebidas me servir de mais. Mantive meus olhos na paisagem al\u00e9m da janela, o jardim da mans\u00e3o sempre muito bem cuidado, eu gostava da sensa\u00e7\u00e3o de calmaria que a natureza me passava. Era relaxante.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>%Pietra% Perroni [&#8230;] [&#8230;] [&#8230;] %Matteo% Perroni<\/p>\n","protected":false},"author":54,"featured_media":0,"parent":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"historias":[2100],"class_list":["post-9436","capitular","type-capitular","status-publish","format-standard","hentry","historias-vincere"],"acf":[],"_links":{"self":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular\/9436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular"}],"about":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/types\/capitular"}],"author":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/comments?post=9436"}],"wp:attachment":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/media?parent=9436"}],"wp:term":[{"taxonomy":"historias","embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/historias?post=9436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}