{"id":9313,"date":"2025-12-29T11:49:13","date_gmt":"2025-12-29T14:49:13","guid":{"rendered":"https:\/\/espacocriativo.net\/acervo\/historia\/historia-sem-nome\/rascunho-automatico\/"},"modified":"2025-12-29T11:54:39","modified_gmt":"2025-12-29T14:54:39","slug":"capitulo-1","status":"publish","type":"capitular","link":"https:\/\/espacocriativo.net\/acervo\/historia\/pretend\/capitulo-1\/","title":{"rendered":"Cap\u00edtulo 1"},"content":{"rendered":"\r\n<p align=\"center\"><em>\u201cSometimes I wish that we could all forget\u201d<\/em><br><em>(\u00c0s vezes eu desejo que pud\u00e9ssemos esquecer tudo)<\/em><\/p>\r\n<p>\u2003\u2003<span class=\"versalete\">%Lana% estava sentada ao<\/span> balc\u00e3o da balada, enquanto bebia seu drinque e conversava animada com alguns desconhecidos que, assim como ela, acompanhavam animados, ao <em>barman<\/em> executando v\u00e1rias acrobacias no preparo de outros drinques. Uma das garotas ao seu lado concentrou o olhar em um ponto atr\u00e1s dela, indicando para %Lana% com o olhar, que algu\u00e9m viria lhe falar. E pela express\u00e3o da mulher, era um algu\u00e9m muito interessante.<br>\u2003\u2003Concentrou-se em fazer sua melhor express\u00e3o sedutora enquanto ambas as desconhecidas ao seu lado, piscaram para ela saindo do balc\u00e3o a caminho da pista de dan\u00e7a. %Lana% sentiu uma m\u00e3o tocar em seu ombro direito, e sorriu travessa antes de se virar, mas logo sua express\u00e3o de sedutora mudou para descontente:<br>\u2003\u2003\u2014 Voc\u00ea? \u2014 falou surpresa.<br>\u2003\u2003Quais as chances de, seu ex-namorado est\u00fapido, esbarrar contigo em outro estado onde voc\u00ea mora?<br>\u2003\u2003%Lana% n\u00e3o estava s\u00f3 desapontada, ela estava enfurecida!<br>\u2003\u2003\u2014 Eu n\u00e3o acredito que <strong>voc\u00ea <\/strong>est\u00e1 na merda da mesma balada que eu, Rafael! Voc\u00ea n\u00e3o deveria estar sei l\u00e1\u2026 Em <em>Floripa<\/em>?<br>\u2003\u2003\u2014 \u00c9 um prazer rever voc\u00ea tamb\u00e9m, %Lana%.<br>\u2003\u2003Rindo da mulher, Rafael sentou-se em uma das banquetas ao seu lado. %Lana% virou-se para o <em>barman <\/em>e somente com a m\u00e3o, fez um n\u00famero dois indicando o pedido para sua segunda bebida. E assim que o <em>barman <\/em>lhe sorriu em resposta, ela virou os dedos com o n\u00famero dois horizontalmente indicando que seria um drinque <strong>duplo<\/strong>.<br>\u2003\u2003Rafael observava as rea\u00e7\u00f5es da ex, que voltou sua aten\u00e7\u00e3o a ele, com o olhar que ele conhecia muito bem: <em>\u201cEstou esperando a explica\u00e7\u00e3o\u201d<\/em>, era o que significava aquele olhar.<br>\u2003\u2003\u2014 Quer dan\u00e7ar?<br>\u2003\u2003\u2014 Rafael, estou esperando a explica\u00e7\u00e3o.<br>\u2003\u2003Ele sorriu ao ouvi-la. Afinal, ainda a conhecia bem.<br>\u2003\u2003\u2014 Me mudei para c\u00e1.<br>\u2003\u2003\u2014 Quem foi o maldito que te deu a oportunidade de sair de Florian\u00f3polis?<br>\u2003\u2003\u2014 Qual \u00e9, %Lana%\u2026 Vamos esquecer tudo?<br>\u2003\u2003\u2014 Esquecer tudo? Eu j\u00e1 esqueci tudo! E isso n\u00e3o significa que eu v\u00e1 te receber com fogos de artif\u00edcio ao te rever.<br>\u2003\u2003\u2014 Deixa de ser rancorosa! Lembra-se de como \u00e9ramos bons amigos?<br>\u2003\u2003\u2014 Poder\u00edamos ter nos tornado, bons amigos, antes de estragar tudo naquela maldita noite\u2026<br>\u2003\u2003\u2014 Engra\u00e7ado\u2026 Eu me recordo bem de n\u00f3s dois, amic\u00edssimos, antes de imaginar nossas bocas grudadas.<br>\u2003\u2003\u2014 Em que vida? Voc\u00ea nunca foi meu amigo! Nem antes e nem depois, Rafael. J\u00e1 eu, sim, fiz o que pude para ser sua amiga. At\u00e9 ap\u00f3s descobrir o canalha que voc\u00ea \u00e9.<br>\u2003\u2003\u2014 Ei! Vim para c\u00e1 por sua causa. N\u00e3o seja assim t\u00e3o dura, %Lana%. \u2014 O ex-namorado sorria, mexia nos cabelos e a encarava com a mesma express\u00e3o de cachorro que caiu da mudan\u00e7a.<br>\u2003\u2003Ela n\u00e3o se deixaria enganar duas vezes.<br>\u2003\u2003\u2014 Nem vem, nem vem! Pode parar com esta justificativa para trazer o inferno at\u00e9 mim. Eu n\u00e3o tenho nada a ver com isso.<br>\u2003\u2003\u2014 Tem, sim, %Lana%, porque eu n\u00e3o consigo esquecer de voc\u00ea.<br>\u2003\u2003Rafael apertou os l\u00e1bios e pronunciou aquilo ao p\u00e9 do ouvido de %Lana%. Ela o encarou, amea\u00e7adora e divertida:<br>\u2003\u2003\u2014 Ningu\u00e9m consegue. \u2014 respondeu.<br>\u2003\u2003\u2014 %Lana%, vamos agir como adultos! Voltei para me desculpar com voc\u00ea, e tentar recome\u00e7ar do zero. Me d\u00ea esta chance!<br>\u2003\u2003\u2014 Est\u00e1 propondo que apaguemos o passado e finjamos que acabamos de nos conhecer?<br>\u2003\u2003\u2014 Praticamente isso.<br>\u2003\u2003E foi ali que a ideia surgiu na cabe\u00e7a dela. Aceitaria fingir que nada acontecera e veria at\u00e9 onde as inten\u00e7\u00f5es de Rafael iriam.<br>\u2003\u2003\u2014 Est\u00e1 certo, Rafael\u2026 \u2014 %Lana% suspirou virando-se sentada em sua bancada, agora de frente para ele, encorajando assunto: \u2014 Me conte como foi sair de <em>Floripa<\/em>, finalmente\u2026<br>\u2003\u2003O rapaz sorriu satisfeito por conseguir a tr\u00e9gua, e,&nbsp; n\u00e3o demorou muito ap\u00f3s v\u00e1rios drinques para que Rafael demonstrasse a sua reca\u00edda por ela. %Lana% gargalhava por notar qu\u00e3o f\u00e1cil aquilo seria, enquanto escutava Rafael lhe cochichar: <em>\u201cs\u00f3 um beijo, que mal nos far\u00e1?\u201d,<\/em> insistentemente.<br>\u2003\u2003\u2014 N\u00e3o vou te beijar, cara. Voc\u00ea \u00e9 t\u00e3o\u2026 Descarado!<br>\u2003\u2003\u2014 Certo, eu falhei, mas fazer o qu\u00ea se viajei de <em>Floripa<\/em> at\u00e9 aqui pensando no seu beijo?<br>\u2003\u2003\u2014 Se eu te beijar agora, voc\u00ea se arrepender\u00e1 muito amanh\u00e3.<br>\u2003\u2003\u2014 N\u00e3o mais do que se eu n\u00e3o te beijar.<br>\u2003\u2003%Lana% negou com a cabe\u00e7a, em risos que denunciavam a ele que, ela n\u00e3o facilitaria as coisas. Rafael, estava realmente ansioso por aquilo e n\u00e3o aceitaria a ex-namorada fazendo charme. Ela sempre foi t\u00e3o apaixonada por ele! N\u00e3o era poss\u00edvel que n\u00e3o sentisse um pingo de vontade, de nostalgia! Os olhos dela n\u00e3o lhe negavam os desejos, e ele observou a mulher evitando olh\u00e1-lo diretamente. Encarou aquele gesto dela, como um sinal de fraqueza.<br>\u2003\u2003No entanto, %Lana% havia ficado esperta no que dizia respeito ao <em>ex<\/em>, e sabia que demonstrar inseguran\u00e7a em n\u00e3o o olhar o faria cair em seu teatro. E ele caiu. Rafael investiu um beijo que a garota n\u00e3o negou, mas sim, sorriu vingativa. Qu\u00e3o doce era o gosto daquele beijo! E pelo sentimento mais contrastante poss\u00edvel: sadismo. Ela fingiu-se vencida por ele, e mais uma vez, fingiu-se ing\u00eanua quando aceitou ir embora acompanhada do rapaz. Rafael se ofereceu para acompanh\u00e1-la at\u00e9 em casa, insistindo at\u00e9 ela aceitar.<br>\u2003\u2003\u2014 Vamos, eu fa\u00e7o quest\u00e3o de te acompanhar at\u00e9 em casa.<br>\u2003\u2003\u2014 Para gastar duas corridas de t\u00e1xi? Segue o seu caminho, e eu sigo o meu. \u2014 %Lana% negava.<br>\u2003\u2003\u2014 N\u00e3o me importo em gastar quantas corridas precisar, <em>minha linda<\/em>. \u2014 Rafael dizia sorridente e b\u00eabado, satisfeito em estar com ela \u2014 E depois \u00e9 uma maneira de passar mais tempo com voc\u00ea. Amanh\u00e3 voc\u00ea pode acordar me evitando.<br>\u2003\u2003\u2014 N\u00e3o tenha d\u00favidas disso!<br>\u2003\u2003Ele chamou um t\u00e1xi e abriu a porta para %Lana%, que entrou e logo em seguida, Rafael acomodou-se ao seu lado. Por mais que ela estivesse fingindo <em>\u201cn\u00e3o ser preciso\u201d,<\/em> deu o endere\u00e7o dela para o motorista e ao perguntar onde ele estava morando, Rafael disse morar em um bairro que era caminho para a casa dela. Ent\u00e3o, %Lana% prop\u00f4s que eles rachassem a corrida e o ex-namorado aceitou.<br>\u2003\u2003Ao chegar em sua casa, a mo\u00e7a desceu do autom\u00f3vel e ao pagar, Rafael foi mais r\u00e1pido pagando a corrida inteira e dispensando o motorista sem que ela notasse.<br>\u2003\u2003\u2014 Voc\u00ea \u00e9 um filho da m\u00e3e. Vai embora a p\u00e9 por acaso?<br>\u2003\u2003\u2014 Pe\u00e7o por outro t\u00e1xi.<br>\u2003\u2003\u2014 A esta hora? N\u00e3o tem vergonha de um golpe t\u00e3o baixo para ficar aqui?<br>\u2003\u2003\u2014 Est\u00e1 me convidando? Porque eu aceito.<br>\u2003\u2003\u2014 N\u00e3o, n\u00e3o estou! Voc\u00ea pode ficar no sagu\u00e3o enquanto chamo um t\u00e1xi, ou pode esperar no meu apartamento. Apenas isso, j\u00e1 que n\u00e3o quero ser chamada a depor por largar um b\u00eabado na rua a esta hora. Sabe que, s\u00f3 por ser sua <em>ex <\/em>eu seria a principal suspeita, n\u00e3o \u00e9?<br>\u2003\u2003Eles entraram e a mulher cumprimentou o porteiro.<br>\u2003\u2003\u2014 Boa noite, Tadeu, se eu n\u00e3o <em>interfonar<\/em> de volta em dez minutos pode chamar a pol\u00edcia \u2014 sussurrou apontando para Rafael atr\u00e1s de si: \u2014 \u00c9 meu ex-namorado obsessivo.<br>\u2003\u2003\u2014 T\u00e3o engra\u00e7adinha\u2026 \u2014 Rafael falou sorrindo para o porteiro e disse que a obsessiva era ela.<br>\u2003\u2003Eles subiram silenciosos pelo elevador, e quando Rafael investiu em beij\u00e1-la de novo, a garota o empurrou saindo pela porta. Aquele jogo de \u201cpega-pega\u201d seria divertido aos olhos dele.<br>\u2003\u2003Elogiou o apartamento dela e agarrou-a sem muito esfor\u00e7o. %Lana% dissera que seria a \u00faltima noite na vida que ficaria com ele. Rafael sorriu entre beijos distribu\u00eddos por seu pesco\u00e7o e antes que a jogasse no sof\u00e1 da sala, ela o guiou para seu quarto. Interpretou mais algum charme de <em>\u201cmo\u00e7a arrependida pelo que faria\u201d<\/em> e o jogou em sua cama. O rapaz se surpreendeu e n\u00e3o demorou a retirar as roupas.<br>\u2003\u2003O momento entre eles foi ficando cada vez mais quente e no \u00e1pice de sua troca sexual, enquanto o Rafael penetrava-a voluptuoso, os olhos de %Lana% reviravam-se de t\u00e9dio, e ela estava extremamente feliz por perceber que n\u00e3o sentia mais nada por ele, nem mesmo tes\u00e3o. Ap\u00f3s suarem bastante, depois da mulher morder todos os lugares que teve vontade no corpo do <em>ex<\/em>, e ap\u00f3s deix\u00e1-lo surpreso por coisas que nunca havia feito com ele, ela virou-se para o lado para dormir. Rafael tentou abra\u00e7\u00e1-la, mas ela afastou os bra\u00e7os dele de sua cintura.<br>\u2003\u2003\u2014 Me solta, est\u00e1 calor.<br>\u2003\u2003\u2014 Voc\u00ea j\u00e1 foi mais carinhosa. \u2014 Ele sussurrou ao ouvido dela.<br>\u2003\u2003\u2014 N\u00e3o tem romance aqui. Acorda! E por falar em acordar, dorme logo que voc\u00ea vai embora bem cedo.<br>\u2003\u2003\u2014 Que grosseria, %Lana%! Nem vai me convidar para o caf\u00e9? \u2014 sentou-se na cama, surpreso e fazendo a garota o olhar.<br>\u2003\u2003\u2014 Eu n\u00e3o moro sozinha, n\u00e3o quero que meu companheiro esbarre com voc\u00ea saindo do meu quarto.<br>\u2003\u2003\u2014 Voc\u00ea ainda mora com o %Pedro%? \u2014 Rafael indagou suspeitando.<br>\u2003\u2003\u2014 Meu irm\u00e3o? \u2014 %Lana% sorriu maldosa \u2014 N\u00e3o. Divido o apartamento com meu <em>ficante<\/em>.<br>\u2003\u2003\u2014 Seu\u2026 <em>Ficante<\/em>?<br>\u2003\u2003\u2014 Sim, e ele deve estar no quarto ao lado descansando para a prova de amanh\u00e3. Ent\u00e3o fique quieto e durma.<br>\u2003\u2003Rafael estava muito contrariado. Desde quando %Lana% se tornara aquela fingida que ficava com v\u00e1rios caras? Onde estava a garota ing\u00eanua, embora fogosa, que ele havia conhecido? E ainda mais curioso: que tipo de cara aceitaria aquilo?<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>\u201cSometimes I wish that we could all forget\u201d(\u00c0s vezes eu desejo que pud\u00e9ssemos esquecer tudo)<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"historias":[2471],"class_list":["post-9313","capitular","type-capitular","status-publish","format-standard","hentry","historias-pretend"],"acf":[],"_links":{"self":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular\/9313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular"}],"about":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/types\/capitular"}],"author":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/comments?post=9313"}],"wp:attachment":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/media?parent=9313"}],"wp:term":[{"taxonomy":"historias","embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/historias?post=9313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}