{"id":9151,"date":"2025-12-07T16:45:13","date_gmt":"2025-12-07T19:45:13","guid":{"rendered":"https:\/\/espacocriativo.net\/acervo\/historia\/historia-sem-nome\/rascunho-automatico\/"},"modified":"2025-12-07T16:48:08","modified_gmt":"2025-12-07T19:48:08","slug":"unico","status":"publish","type":"capitular","link":"https:\/\/espacocriativo.net\/acervo\/historia\/i-am-you-you-are-me\/unico\/","title":{"rendered":"Cap\u00edtulo \u00fanico"},"content":{"rendered":"\r\n<p>\u2003\u2003<span class=\"versalete\">Em um mesmo bairro<\/span> de Seoul, duas casas em dire\u00e7\u00f5es opostas chamavam a aten\u00e7\u00e3o dos vizinhos pelos seguintes motivos: tinham a mesma cor, o mesmo tamanho, pareciam id\u00eanticas, e at\u00e9 mesmo seus n\u00fameros traziam uma numerologia estranha entre si. Uma numerada por <strong>595<\/strong> e a outra por&#8230; <strong>595<\/strong>. Aquele fato sempre gerava confus\u00e3o aos carteiros, mas %Suzy% nunca se importou em alterar aquilo. A casa do outro lado da rua estava vazia por anos!<br>\u2003\u2003<strong>Dizem que \u00e0s vezes o destino se encarrega de brincar com coisas materiais ou triviais, para chegar ao objetivo de enla\u00e7ar vidas que foram destinadas uma a outra.<\/strong> %Suzy% n\u00e3o era absolutamente crente em supersti\u00e7\u00e3o ou magia, mas talvez aquilo estivesse perto de mudar. Uma noite antes do anivers\u00e1rio de Nini, sua melhor amiga, o cosmos vestiu-se de uma dessas manipula\u00e7\u00f5es do destino. O rel\u00f3gio marcava <strong>21:21<\/strong> horas da noite, e %Suzy% dormia pesadamente. Afinal, estava exausta do dia trabalhado e por isso, n\u00e3o foi dif\u00edcil dormir. E nem mesmo a ventania que adentrou pela janela de seu quarto, causando tumulto em alguns pap\u00e9is, e uma queda da temperatura foi capaz de acord\u00e1-la. O mais estranho naquela ventania era o fato de ventar apenas na casa amarela dela, e trazer consigo um amontoado de p\u00e9talas de flores vermelhas. Flores estas que %Suzy% s\u00f3 notou ao amanhecer ao perceb\u00ea-las ao ch\u00e3o. Estranhou, mas estava atrasada demais para averiguar. Trancou as janelas e saiu, o rel\u00f3gio marcava <strong>12:12<\/strong> horas da manh\u00e3. Bem no meio do dia. Como ela pudera dormir tanto?! Certamente perderia horas descontadas em seu sal\u00e1rio!<br>\u2003\u2003Nem se importou com a presen\u00e7a do caminh\u00e3o de mudan\u00e7as em frente \u00e0 sua casa, ou com os outros vizinhos dizendo ao novato rapaz sobre como ele adoraria o bairro, e felicitando-o pela nova moradia. %Zico% sorriu discreto, nem muito largo, nem muito pouco. Era coisa da sua personalidade, ser disperso e um tanto quanto atento em si. Contudo, na \u00faltima noite, ele havia ficado ainda mais distra\u00eddo, quase que hipnotizado ou autom\u00e1tico.<\/p>\r\n<p>\u2003\u2003\u2014 Sim, Nini! Eu estou chegando ao <em>kombini<\/em> do bairro, e j\u00e1 levo o <em>soju<\/em>!<br>\u2003\u2003Nini estava telefonando h\u00e1 horas para %Suzy%. Por conta de seu atraso, a mulher precisou fazer horas extras e se atrasou tamb\u00e9m para o anivers\u00e1rio. %Zico% lia um livro na sua casa rec\u00e9m-organizada, e como num estalo sentiu vontade de beber. Mas o estranho era que&#8230; Ele n\u00e3o bebia. Independente disso, sem dar aten\u00e7\u00e3o \u00e0 altera\u00e7\u00e3o dos seus sentidos, ele fechou o livro, pegou o celular, a carteira e as chaves de casa e seguiu at\u00e9 o <em>kombini<\/em> mais pr\u00f3ximo do seu bairro.<br>\u2003\u2003Entrou e foi direto ao lugar onde estavam as garrafas e n\u00e3o notou a mulher ao seu lado totalmente vestida como ele. %Suzy%, entretanto, notou, e achou aquilo um tanto quanto&#8230; esquisito. Um cara e uma garota s\u00f3 andavam com roupas iguais daquele jeito quando era um casal, e foi absolutamente esquisito para ela ficar ali do lado dele parecendo&#8230; namorada dele. Correu para pegar o <em>soju<\/em> e pagar, antes que alguns de seus amigos que viriam para o anivers\u00e1rio de Nini chegassem ali por acaso. Certamente, seria constrangedor que interpretassem mal a situa\u00e7\u00e3o.<\/p>\r\n<p align=\"center\">[&#8230;]<\/p>\r\n<p>\u2003\u2003Na semana seguinte, %Suzy% estava no <em>\u201cLevel\u201d.<\/em> Acabou indo trabalhar ali depois de, ap\u00f3s o anivers\u00e1rio de Nini, ela perder a hora de novo e dessa vez s\u00f3 aparecer no trabalho \u00e0s 13:00 horas da tarde. O que resultou? Numa bela demiss\u00e3o. %Suzy% tivera sorte de conseguir um novo emprego t\u00e3o r\u00e1pido e perto de casa. Mal acreditou quando no ponto de \u00f4nibus, debaixo de chuva, uma senhora loira e bem vestida lhe entregou um panfleto com <em>\u201cprocura-se atendente\u201d.<\/em> E ainda mais inacredit\u00e1vel era saber que o novo emprego ficava ali, a poucas quadras de casa.<br>\u2003\u2003O carteiro j\u00e1 vinha descendo a rua quando %Zico% saiu pela varanda. Estava \u00e0 espera de uma encomenda e ao v\u00ea-lo o aguardou, mas o homem foi at\u00e9 a casa da frente e bateu. Foi ent\u00e3o que %Zico% notou as semelhan\u00e7as entre as duas casas, e soube da confus\u00e3o de n\u00fameros. Quando ningu\u00e9m atendeu ao carteiro, ele tomou a liberdade de se aproximar e indagar se n\u00e3o seria para ele aquela encomenda. E era. No fim da tarde, %Zico% j\u00e1 estava comprando uma letra <em>\u201cA\u201d<\/em> e colocando-a pregada aos n\u00fameros do muro da casa, ap\u00f3s ter ido ao correio solicitar a mudan\u00e7a daquela informa\u00e7\u00e3o.<br>\u2003\u2003\u2014 Dongu? \u2014 ele atendeu ao telefone falando com seu melhor amigo. \u2014 Voc\u00ea vem mesmo? <em>Uwa<\/em>&#8230; Eu vou agora comprar aquelas cebolinhas em conserva que voc\u00ea gosta!<br>\u2003\u2003H\u00e1 muito tempo os dois amigos n\u00e3o se viam, e %Zico% estava animado para que Dongu conhecesse sua nova casa e bairro. Vestiu sua jaqueta de couro e olhou-se no espelho. Sentia-se estranhamente&#8230; bem vestido, mas incompleto. Incompleto com o qu\u00ea? Ele n\u00e3o sabia, mas aquela sensa\u00e7\u00e3o vinha sendo cada vez mais comum. Sempre se sentiu assim, mas desde que se mudara, a sensa\u00e7\u00e3o aumentou. Viu que o <em>\u201cLevel\u201d<\/em> ainda estava aberto e entrou para comprar o que havia prometido ao amigo.<br>\u2003\u2003%Suzy%, que estudava concentrada, ao ouvir a sineta, encarou o rapaz. Seria poss\u00edvel? De novo ele? E de novo, com as mesmas roupas? Ela espreitou na dire\u00e7\u00e3o dele enquanto ele ia at\u00e9 a geladeira de sucos, e viu o rapaz se abaixando para amarrar o cadar\u00e7o de seu t\u00eanis. Olhou para seu pr\u00f3prio p\u00e9, e estranhamente, %Suzy% estava com o mesmo p\u00e9 desamarrado. O que, afinal, era aquilo? Como da outra vez, %Zico% n\u00e3o se sentiu nada constrangido e apenas pagou suas compras e saiu. Mas, tamb\u00e9m diferente da outra vez, ele notou a presen\u00e7a da mulher e a coincid\u00eancia das suas vestes. E outra coisinha o deixou intrigado: depois que ela amarrou os cadar\u00e7os tamb\u00e9m, e os dois se notaram, %Zico% sentiu-se completo.<\/p>\r\n<p align=\"center\">[&#8230;]<\/p>\r\n<p>\u2003\u2003\u2014 Nini! As mesmas roupas! Tudo igualzinho! At\u00e9 o anel que a vov\u00f3 me deu! A vov\u00f3 que me deu este anel, Nini! \u2014 %Suzy% falava surpresa para a melhor amiga.<br>\u2003\u2003\u2014 Mas ele \u00e9 bonito?<br>\u2003\u2003\u2014 Sim, ele \u00e9, mas&#8230; O que isso tem a ver?<br>\u2003\u2003\u2014 Oras, e se voc\u00eas forem destinados um ao outro?<br>\u2003\u2003\u2014 Nini! Por favor! N\u00e3o brinca! Eu passei a semana toda esbarrando com esse cara por a\u00ed, ele vestindo as mesmas coisas que eu e&#8230; \u2014 %Suzy% cessou de falar ao parar em sua cal\u00e7ada e encarar a casa vizinha.<br>\u2003\u2003\u2014 <em>Uwa<\/em>! Um vizinho novo? E&#8230; Ele \u00e9 igual a voc\u00ea&#8230; \u2014 Nini exclamou surpresa ao v\u00ea-lo.<br>\u2003\u2003\u2014 \u00c9 ele, Nini! \u2014 %Suzy% disse a puxando para entrar.<br>\u2003\u2003E as coincid\u00eancias permaneciam&#8230; Os dois gostavam de Bob Esponja, tinham mesmos rel\u00f3gios, acess\u00f3rios, estavam cada vez mais atra\u00eddos \u00e0 presen\u00e7a um do outro, e no dia em que %Zico% se cortou acidentalmente, ele encontrou %Suzy% no <em>\u201cLevel\u201d<\/em> colocando um <em>band-aid<\/em>.<br>\u2003\u2003Era estranho para eles sentirem-se t\u00e3o ligados e at\u00e9 aquele dia nunca terem trocado uma palavra sequer. Mas era como se algo estivesse fora do lugar. Ele colocou o curativo, que, pasme, era o mesmo que o dela, e foi para casa. N\u00e3o conseguia parar de pensar nela, e nem ela nele.<\/p>\r\n<p align=\"center\">[&#8230;]<\/p>\r\n<p>\u2003\u2003O vento silvava t\u00edmido naquela noite fria, e Nini descia na casa da amiga escondendo-se da chuva. Havia recebido uma carona de uma senhora loira simp\u00e1tica e quando abriu a porta para descer do carro, foi tomada por uma amn\u00e9sia. Na verdade, perdeu os sentidos e andou automaticamente at\u00e9 a casa de %Zico%. O rapaz atendeu a campainha reconhecendo a mo\u00e7a que dias antes entrou na casa vizinha.<br>\u2003\u2003\u2014 Posso ajudar?<br>\u2003\u2003\u2014 A encomenda! \u2014 Nini gritou. \u2014 Abra-a.<br>\u2003\u2003%Zico% n\u00e3o entendeu nada. Viu a mulher despertar e correr at\u00e9 a casa da frente, mas acabou se lembrando: no dia em que Dongu viera visit\u00e1-lo, havia se esquecido de abrir a caixinha que uma velha amiga de sua av\u00f3 lhe havia mandado. Ele entrou e fez o que deveria ter feito antes e espantou-se quando encontrou uma fotografia antiga. Eram seus av\u00f3s. Ele era parecido com o av\u00f4. E a av\u00f3&#8230; Tinha a face de sua vizinha!<br>\u2003\u2003Um pouco perturbado por aquilo, %Zico% atravessou a rua na chuva fraca a chamando.<br>\u2003\u2003\u2014 O que foi? \u2014 %Suzy% perguntou confusa em sua varanda.<br>\u2003\u2003\u2014 Voc\u00ea&#8230; poderia dar uma olhada&#8230; <em>Er<\/em>&#8230; eu posso entrar?<br>\u2003\u2003Nini surgiu ao seu lado e falou para a amiga abrir o port\u00e3o, ou o vizinho pegaria um resfriado.<br>\u2003\u2003\u2014 Obrigado.<br>\u2003\u2003\u2014 O que voc\u00ea deseja? \u2014 ela perguntou em d\u00favida.<br>\u2003\u2003%Zico% encarou a foto em sua m\u00e3o e olhou para ela, esperan\u00e7oso.<br>\u2003\u2003\u2014 Pode olhar esta fotografia, por favor?<br>\u2003\u2003%Suzy% a pegou e, assustada, indagou \u00e0quele estranho garoto que andava id\u00eantico a ela:<br>\u2003\u2003\u2014 Por que voc\u00ea tem uma fotografia dos meus av\u00f3s?<br>\u2003\u2003De repente, a chuva parou, o vento diminuiu e a roseira da casa da vizinha foi tomada por uma \u00fanica rajada de ventania que despetalou as rosas, cobrindo aos dois por elas.<br>\u2003\u2003\u2014 Voc\u00ea tem um irm\u00e3o?<br>\u2003\u2003\u2014 Eu n\u00e3o sei&#8230; eu me perdi dos meus pais quando crian\u00e7a.<br>\u2003\u2003\u2014 Como sabe se s\u00e3o seus av\u00f3s?<br>\u2003\u2003\u2014 Fui encontrada com uma mochila, e na mochila eu tinha esta fotografia&#8230; \u2014 %Suzy% correu at\u00e9 sua casa e pegou o porta-retratos com a foto id\u00eantica, e mostrou a %Zico%.<br>\u2003\u2003\u2014 Bem&#8230; ent\u00e3o, acho que precisaremos conversar, vizinha&#8230; Mas eu estou em voc\u00ea e voc\u00ea est\u00e1 em mim.<br>\u2003\u2003Nini encarou aos dois, confusa. %Zico% havia tido pistas de sua irm\u00e3 g\u00eamea desaparecida h\u00e1 algum tempo, e foi para aquela vizinhan\u00e7a em busca dela. E realmente, a havia encontrado. O destino realmente d\u00e1 uma m\u00e3ozinha quando necess\u00e1rio. %Zico% e %Suzy% nunca mais se vestiram iguais, e tamb\u00e9m n\u00e3o mais se separaram. Agora, eles estavam completos como h\u00e1 anos n\u00e3o se sentiam. Ah! E a %Suzy%? Ela ainda n\u00e3o acredita em supersti\u00e7\u00f5es ou magia.<\/p>\r\n<p align=\"center\"><strong>Fim.<\/strong><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>[&#8230;] [&#8230;] [&#8230;] Fim.<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"historias":[2419],"class_list":["post-9151","capitular","type-capitular","status-publish","format-standard","hentry","historias-i-am-you-you-are-me"],"acf":[],"_links":{"self":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular\/9151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular"}],"about":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/types\/capitular"}],"author":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/comments?post=9151"}],"wp:attachment":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/media?parent=9151"}],"wp:term":[{"taxonomy":"historias","embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/historias?post=9151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}