{"id":9008,"date":"2011-07-09T16:07:00","date_gmt":"2011-07-09T19:07:00","guid":{"rendered":"https:\/\/espacocriativo.net\/acervo\/historia\/historia-sem-nome\/rascunho-automatico\/"},"modified":"2025-11-24T16:08:32","modified_gmt":"2025-11-24T19:08:32","slug":"chapter-02","status":"publish","type":"capitular","link":"https:\/\/espacocriativo.net\/acervo\/historia\/sweet-december\/chapter-02\/","title":{"rendered":"CHAPTER 02"},"content":{"rendered":"\n<p>&emsp;&emsp;Ap\u00f3s terem uma r\u00e1pida apresenta\u00e7\u00e3o um tanto constrangedora, os tr\u00eas rapazes se direcionaram a suas marcas. Bradie sentou-se atr\u00e1s de sua bateria, Shaun pegou sua guitarra ao mesmo tempo em que Andy colocava seu baixo em posi\u00e7\u00e3o. As convidadas especiais para o clipe se reuniram perto do cen\u00e1rio em que eles estavam, pouco atr\u00e1s das c\u00e2meras, em algumas cadeiras altas.<br \/>\n&emsp;&emsp;- Certo, vamos passar o come\u00e7o da m\u00fasica, tudo bem? &#8211; Pergunta o diretor.<br \/>\n&emsp;&emsp;Ao sinal dele, o som come\u00e7a a tocar e os garotos entram em a\u00e7\u00e3o, em frente as diversas c\u00e2meras que os filmavam de diversos \u00e2ngulos. Shaun e Andy batiam palmas conforme o ritmo do in\u00edcio.<br \/>\n&emsp;&emsp;- <em>I&#8217;m comin&#8217; home, I&#8217;m comin&#8217;&#8230; I&#8217;m comin&#8217; home, I&#8217;m comin&#8217;<\/em> &#8211; ambos preparam-se rapidamente e logo come\u00e7am a tocar a m\u00fasica em seus instrumentos, acompanhando a que tocava ao fundo.<br \/>\n&emsp;&emsp;Shaun e Andy se moviam durante o instrumental, por\u00e9m logo Diviney para, olhando fixamente para a c\u00e2mera \u00e0 sua frente.<br \/>\n&emsp;&emsp;- <em>So wrap you hands around me, darlin&#8217;. Just so you know, I&#8217;m comin&#8217; down around you, darlin&#8217;. We&#8217;ve never looked this beautiful and though I&#8217;ll be your sweet December.<\/em><br \/>\n&emsp;&emsp;Havia diversas telas mostrando o que cada c\u00e2mera, em seu lugar, pegava. Havia quatro c\u00e2meras: uma focalizava-se de frente, mexendo-se de um lado para o outro conforme a situa\u00e7\u00e3o para pegar a banda inteira; as outras, cada uma delas, estava sobre cada um dos stackers, filmando-os enquanto tocavam.<br \/>\n&emsp;&emsp;- <em>Oh, oh, oh&#8230; Oh, oh, oh<\/em> &#8211; uma das telas mostrou Andy olhando para baixo, cantando a m\u00fasica.<br \/>\n&emsp;&emsp;- <em>I don&#8217;t need you when I&#8217;ve got my pride<\/em> &#8211; cantou Shaun, olhando para cima e fechando os olhos.<br \/>\n&emsp;&emsp;As c\u00e2meras pegavam cada cena, cada detalhe. O que era para ser a grava\u00e7\u00e3o de apenas o in\u00edcio da m\u00fasica tocada por eles, tornou-se a grava\u00e7\u00e3o de tudo, considerando que eles estavam calmos e tocando como se n\u00e3o houvesse ningu\u00e9m ali assistindo. Caroline cantarolava a m\u00fasica, junto de Any e Lelen; Jumpnow estava ajudando na sess\u00e3o das telas; Helen e Natashia permaneciam assistindo com aten\u00e7\u00e3o enquanto eles tocavam.<br \/>\n&emsp;&emsp;A m\u00fasica foi gravada inteira, a miss\u00e3o dos funcion\u00e1rios durante a edi\u00e7\u00e3o seria selecionar onde entrariam as cenas da hist\u00f3ria do clipe. Os tr\u00eas desceram do cen\u00e1rio, animados, e chegaram perto das garotas.<br \/>\n&emsp;&emsp;- Para quem estava apenas gravando, voc\u00eas levam isso bem a s\u00e9rio &#8211; Any apontou, sorridente.<br \/>\n&emsp;&emsp;- S\u00f3 nessas horas para eles serem s\u00e9rios &#8211; Jumpnow aparece atr\u00e1s deles, passando reto e se postando ao lado da namorada.<br \/>\n&emsp;&emsp;- Que mentira, somos s\u00e9rios em muitas horas &#8211; Andy defende-se.<br \/>\n&emsp;&emsp;- Claro que sim &#8211; C\u00e1a concorda. &#8211; Acompanho v\u00eddeos de voc\u00eas, vejo bem como s\u00e3o s\u00e9rios. Divers\u00e3o garantida, na realidade &#8211; continua, fazendo as amigas rirem e concordarem, enquanto eles rolavam os olhos.<br \/>\n&emsp;&emsp;- Falando nisso, n\u00e3o dev\u00edamos estar gravando? &#8211; Bradie pergunta ao irm\u00e3o, que era respons\u00e1vel pelos v\u00eddeos na internet.<br \/>\n&emsp;&emsp;- Ah, <em>who cares<\/em>&#8230; As pessoas que nos assistem est\u00e3o bem aqui &#8211; aponta para as garotas. &#8211; Deixem elas verem a divers\u00e3o garantida pessoalmente!<br \/>\n&emsp;&emsp;Helen solta uma risada alta, fazendo as garotas virarem para ela e simplesmente rolarem os olhos bem lentamente, como quem diria &#8220;tinha que ser ela para rir dessa droga&#8221;. Andy sorri para ela, feliz por algu\u00e9m ter rido de sua tentativa in\u00fatil de arrancar risada de todos. Ao menos uma.<br \/>\n&emsp;&emsp;- Quem de voc\u00eas \u00e9 a Natashia? &#8211; Bradie ent\u00e3o pergunta.<br \/>\n&emsp;&emsp;Eles haviam sido apresentados \u00e0 elas, mas ainda n\u00e3o sabiam os nomes de cada uma, nem mesmo de quem seria a principal. Gra\u00e7as ao fato de terem se atrasado um pouco para subir ao cen\u00e1rio e gravar a cena da banda.<br \/>\n&emsp;&emsp;Ao lado de Helen, a garota &#8211; que tinha seus cabelos sobre os ombros &#8211; ergue levemente a m\u00e3o, recebendo um dos belos sorrisos do baterista. Hels, no mesmo instante, levantou-se e seguiu ao lado das outras amigas ao ver que Bradie aproximava-se para ficar ao lado de Natashia.<br \/>\n&emsp;&emsp;- Ali \u00e9 que eu n\u00e3o fico &#8211; disse quando parou entre Any e Caroline. &#8211; Imaginem, ela me mataria se eu estragasse esse momento &#8211; continua, vendo as amigas assentirem.<br \/>\n&emsp;&emsp;Natashia segurou-se muito para n\u00e3o virar para a amiga e mandar-lhe a um lugar n\u00e3o muito agrad\u00e1vel.<br \/>\n&emsp;&emsp;- Ela pode te ouvir, Helen &#8211; Jumpnow ri. &#8211; Meu Deus, voc\u00eas n\u00e3o sabem falar baixo? Por que n\u00e3o aprendem com a Bunny?<br \/>\n&emsp;&emsp;- <em>Bunny<\/em> &#8211; as outras riem, bufando, recebendo um olhar \u00e0 la Natashia dado por Hellen. &#8211; Brincadeirinha, Lelen, erm&#8230;<br \/>\n&emsp;&emsp;Assim, Andy e Shaun seguem at\u00e9 elas e Jumpnow, puxando uma conversa animada, ao mesmo tempo em que Natashia dizia:<br \/>\n&emsp;&emsp;- Ignore-as, adoram me zoar agora s\u00f3 porque eu ganho na hora de zo\u00e1-las longe daqui.<br \/>\n&emsp;&emsp;Bradie ri, sentando-se na cadeira antes ocupada por Helen, e apoiando o cotovelo no bra\u00e7o de madeira da mesma, colocando o queixo sobre a m\u00e3o.<br \/>\n&emsp;&emsp;- Ent\u00e3o, \u00e9 verdade que voc\u00ea \u00e9 obsessa pelo Natal como Jumpnow descreveu no script? &#8211; Pergunta, curioso. Ela sorri de lado, olhando para ele.<br \/>\n&emsp;&emsp;- Ahn, costumam dizer que sou. \u00c9 minha data favorita do ano ent\u00e3o&#8230; Acho que pode se dizer que sim.<br \/>\n&emsp;&emsp;Ele d\u00e1 uma risada abafada, desviando o olhar e fixando-o no cen\u00e1rio agora vazio.<br \/>\n&emsp;&emsp;- Gosto bastante do Natal tamb\u00e9m. Sorte \u00e9 do Andy que comemora duas vezes &#8211; murmura.<br \/>\n&emsp;&emsp;- Invejo at\u00e9 a alma dele por isso &#8211; Natashia concorda. &#8211; Mas s\u00f3 <em>por isso<\/em>.<br \/>\n&emsp;&emsp;O baterista ri alto, assentindo.<br \/>\n&emsp;&emsp;- Com certeza, n\u00e3o tem muito o que invejar aquele ali.<br \/>\n&emsp;&emsp;Um movimento estranho aparece atr\u00e1s deles e logo puderam ouvir:<br \/>\n&emsp;&emsp;- <strong>Aquele ali<\/strong> est\u00e1 te ouvindo! &#8211; a voz de Andy, soando bem atr\u00e1s deles.<br \/>\n&emsp;&emsp;- Mas o que diabos voc\u00ea est\u00e1 fazendo aqui!? &#8211; Bradie pergunta, virando-se indignado.<br \/>\n&emsp;&emsp;- Nada, s\u00f3 vim checar.<br \/>\n&emsp;&emsp;- Checar o qu\u00ea? &#8211; Natashia pergunta. Helen, ent\u00e3o, sai de tr\u00e1s de sua cadeira, bem ao lado de Clemmensen.<br \/>\n&emsp;&emsp;- Checar se a conversa estava boa &#8211; ela concorda, sorrindo.<br \/>\n&emsp;&emsp;Natashia e Bradie se entreolham, provavelmente pensando a mesma coisa: em como aqueles dois eram absurdamente irritantes. Talvez isso se devesse ao fato de que Helen &#8211; assim como Nat tinha uma queda por Bradie &#8211; tinha um tombo por Andy. Aquilo explicava, definitivamente, muita coisa.<\/p>","protected":false},"excerpt":{"rendered":"<p>&emsp;&emsp;Ap\u00f3s terem uma r\u00e1pida apresenta\u00e7\u00e3o um tanto constrangedora, os tr\u00eas rapazes se direcionaram a suas marcas. Bradie sentou-se atr\u00e1s de sua bateria, Shaun pegou sua guitarra ao mesmo tempo em que Andy colocava seu baixo em posi\u00e7\u00e3o. As convidadas especiais para o clipe se reuniram perto do cen\u00e1rio em que eles estavam, pouco atr\u00e1s das [&hellip;]<\/p>\n","protected":false},"author":140,"featured_media":0,"parent":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":true,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"historias":[2357],"class_list":["post-9008","capitular","type-capitular","status-publish","format-standard","hentry","historias-sweet-december"],"acf":[],"_links":{"self":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular\/9008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular"}],"about":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/types\/capitular"}],"author":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/users\/140"}],"replies":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/comments?post=9008"}],"wp:attachment":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/media?parent=9008"}],"wp:term":[{"taxonomy":"historias","embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/historias?post=9008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}