{"id":7920,"date":"2012-11-11T15:58:00","date_gmt":"2012-11-11T18:58:00","guid":{"rendered":"https:\/\/espacocriativo.net\/acervo\/historia\/historia-sem-nome\/rascunho-automatico\/"},"modified":"2025-11-11T15:59:03","modified_gmt":"2025-11-11T18:59:03","slug":"capitulo-13","status":"publish","type":"capitular","link":"https:\/\/espacocriativo.net\/acervo\/historia\/life-as-one-direction\/capitulo-13\/","title":{"rendered":"Cap\u00edtulo 13"},"content":{"rendered":"\n<p>&emsp;&emsp;<strong>%Nathalie%\u2019s POV<\/strong><br \/>\n&emsp;&emsp;Despedimo-nos de alguns amigos dos meninos e de alguns amigos nossos. Sa\u00edmos pelos fundos para nenhum fot\u00f3grafo nos perseguir e fomos com a van, para n\u00e3o chamar aten\u00e7\u00e3o. Nem preciso falar que chegamos quebrados no hotel, mas mesmo assim ficamos na sala conversando. Sentamos na poltrona eu e o Liam, num sof\u00e1 a %Paula%, o Harry, o Louis e a %Cah%; no ch\u00e3o o casal buraco negro e ao lado o Zayn e a %Vick%.<br \/>\n&emsp;&emsp;- GALERA, EU J\u00c1 FALEI QUE CONSEGUI O TELEFONE DA DEMI? E TO TROCANDO SMS COM ELA AGORA AI JESUS! &#8211; %Paula% n\u00e3o parou de falar na Demi um minuto e j\u00e1 tava ficando chato.<br \/>\n&emsp;&emsp;- Nossa %Paula%, d\u00e1 pra mudar de assunto? Puta merda! &#8211; %Cah% zoou com ela e n\u00f3s rimos\u2026 Quer dizer, todo mundo menos a %Ana% e a %Vick%. Elas ainda estavam chateadas com o que ocorreu na festa, era compreens\u00edvel. Os meninos do The Wanted eram gatos, mas ser agarrada por eles e ser obrigada a fazer uma coisa que a gente n\u00e3o quer \u00e9 tenso. E pra deixar tudo mais complicado, elas n\u00e3o tinham voltado com Zayn e Niall, por falta de oportunidade, j\u00e1 que eles n\u00e3o tinham ficado sozinhos ainda.<br \/>\n&emsp;&emsp;- EI BURACO NEGRO F\u00caMEA &#8211; Depois do Niall, a \u00fanica pessoa que conseguia animar a %Ana% era o Louis. &#8211; Vamos com o Boo Bear na cozinha comer um pouco, vem! &#8211; Eles se levantaram e foram comer, logo j\u00e1 estavam um pouco molhados e rindo porque Louis quis brincar com a \u00e1gua da torneira. %Vick% tinha dormido no ombro do Zayn.<br \/>\n&emsp;&emsp;- Zayn, a leve pro quarto, p\u00f5e um pijama nela, aproveita e concerta as coisas! &#8211; Harry sugeriu.<br \/>\n&emsp;&emsp;- NOSSA, O HAROLDO PENSANDO? VAI CHOVER HOJE! &#8211; Na falta de Louis, %Cah% sempre fazia uma piadinha. Zayn pegou %Vick% no colo e subiu com ela para o quarto. J\u00e1 falei no quanto eles eram fofos juntos? Ela toda delicadinha e ele todo protetor\u2026 <em>\u201dTomara que d\u00ea tudo certo l\u00e1, am\u00e9m!\u201d<\/em>, pensei. %Aninha% e Louis voltaram para a sala.<br \/>\n&emsp;&emsp;- Amor, vamos dormir tamb\u00e9m? To cansada\u2026 &#8211; %Paula% nem deixou Harry responder e j\u00e1 o puxou &#8211; Boa noite galera! &#8211; Ela completou de cima da escada e logo os dois sumiram.<br \/>\n&emsp;&emsp;- Eai Boo Bear, vamos tamb\u00e9m? &#8211; %Cah% perguntou e Lou assentiu.<br \/>\n&emsp;&emsp;Eles se despediram de n\u00f3s e subiram tamb\u00e9m. Niall come\u00e7ou a arrumar a sala, porque ele e Zayn dormiriam no sof\u00e1 (se bem que desconfio que isso aconte\u00e7a, enfim). O ajudamos e parecia que tudo estava bem confort\u00e1vel.<br \/>\n&emsp;&emsp;- Agora eu vou descansar seus lindos &#8211; %Aninha% bocejou &#8211; Boa noite coisas lindas! &#8211; Ela subiu quase se arrastando de tanto sono.<br \/>\n&emsp;&emsp;- Vai l\u00e1 mong\u00e3o, \u00e9 a sua chance &#8211; Liam deu dois tapas nas costas de Niall.<br \/>\n&emsp;&emsp;- Eu to bem assim? &#8211; Ele respondeu se olhando no espelho.<br \/>\n&emsp;&emsp;- Niall, ela te ama, mesmo se voc\u00ea estiver horrendo, ela vai te aceitar, agora vai l\u00e1 &#8211; Foi a minha vez de empurrar o duende.<br \/>\n&emsp;&emsp;Ele subiu atr\u00e1s da %Ana% e fiquei com Liam na sala. Tomara que esses dois se resolvam logo, n\u00e3o aguento mais esse clima pesado, espero que Zayn e %Vick% se resolvam tamb\u00e9m&#8230; %Ana% e Niall; %Vick% e Zayn se amam! Ser\u00e1 que s\u00f3 n\u00f3s vemos isso? Porque s\u00f3 de olhar para eles d\u00e1 pra perceber n\u00e9? Se bem que&#8230; Pera a\u00ed! Porque to pensando nisso mesmo?<br \/>\n&emsp;&emsp;- Amor? &#8211; Liam me chamava e eu n\u00e3o percebia.<br \/>\n&emsp;&emsp;- Ahn? Ah, oi amor! &#8211; Ele riu.<br \/>\n&emsp;&emsp;- Tava pensando no que?<br \/>\n&emsp;&emsp;- Tava pensando em como esses casais se amam tanto e n\u00e3o se resolvem nunca! J\u00e1 ta na hora n\u00e9?<br \/>\n&emsp;&emsp;- Tamb\u00e9m acho, n\u00e3o aguentava mais ficar longe de voc\u00ea, ficar sem te abra\u00e7ar, sem te beijar, sem dizer que te amo\u2026 &#8211; Esse Liam \u00e9 um lindo mesmo, n\u00e3o sei como consegui ficar tanto tempo longe dele.<br \/>\n&emsp;&emsp;- Anw, eu tamb\u00e9m estava morrendo de saudades, mas n\u00e3o queria demonstrar &#8211; Fiz bico.<br \/>\n&emsp;&emsp;- Ai meu Deus, n\u00e3o sei por que n\u00e3o queria demonstrar!<br \/>\n&emsp;&emsp;- Ah eu tava brava com voc\u00ea n\u00e9 Sr. Liam? Tamb\u00e9m n\u00e3o \u00e9 pra menos e&#8230; &#8211; Liam fez \u2018shhhh\u2019 e colocou o dedo indicador em meus l\u00e1bios.<br \/>\n&emsp;&emsp;- N\u00e3o interessa, a \u00fanica coisa que interessa agora \u00e9 que estamos juntos de novo e ponto final! &#8211; Liam come\u00e7ou a me beijar, ficamos trocando carinhos abra\u00e7ados no sof\u00e1.<\/p>\n\n<p>&emsp;&emsp;<strong>Niall\u2019s POV<\/strong><br \/>\n&emsp;&emsp;Era agora ou nunca. N\u00e3o aguentava mais ficar longe de %Aninha%, longe do amor da minha vida, da minha potato. Liam e %Nathy% me empurraram escada \u00e0 cima; n\u00e3o tive nem tempo de me arrumar. Bati na porta do quarto dela e uma %Ana% com um coque frouxo e um camiset\u00e3o enorme abriu a porta.<br \/>\n&emsp;&emsp;- Oi! &#8211; Falei t\u00edmido e sorri. Devia estar muito vermelho, porque ela riu bastante. &#8211; Podemos conversar?<br \/>\n&emsp;&emsp;- Claro! Entra. &#8211; Porque estou com tanto medo assim? Parece at\u00e9 que tenho 12 anos e acabo de conhecer minha primeira namorada. Tentei respirar fundo e organizar as ideias &#8211; Niall, antes de voc\u00ea falar alguma coisa eu quero te agradecer por me ajudar na boate, por nos ajudar na boate! N\u00e3o sei o que seria de n\u00f3s se voc\u00ea e o Zayn n\u00e3o tivessem aparecido &#8211; Ela come\u00e7ou a chorar, aquilo realmente havia sido um choque. Os meninos provavelmente as levariam a outro lugar e bem&#8230; O resto voc\u00ea deve imaginar. Fiquei com muita raiva quando vi aquela cena, MUITA raiva.<br \/>\n&emsp;&emsp;- Calma %Aninha%, vem c\u00e1! &#8211; Sentei na cama e ela se sentou em meu colo, me abra\u00e7ando. Que saudade dela. &#8211; Ta tudo bem agora, ah se eu pego aquele canalha do Tom eu mato! &#8211; Ela riu fraco.<br \/>\n&emsp;&emsp;- Voc\u00ea n\u00e3o queria falar alguma coisa? &#8211; Perguntou.<br \/>\n&emsp;&emsp;- Ah sim, quero sim! &#8211; A tirei do meu colo com delicadeza e a coloquei sentada na cama. Me ajoelhei a sua frente &#8211; %Ana%, desculpa por tudo que eu a fiz passar, tudo mesmo! Eu sei que eu fui muito idiota, fui um est\u00fapido! Nem procurei saber o que havia acontecido, disse coisas horr\u00edveis para voc\u00ea&#8230; Me sinto muito mal por isso, me sinto p\u00e9ssimo por ter falado aquelas coisas horr\u00edveis para voc\u00ea, %Ana% me desculpe? Eu n\u00e3o sei viver sem voc\u00ea, eu&#8230; Eu te amo %Aninha%! &#8211; Ela chorava e sorria, que saudade daquele sorriso!<br \/>\n&emsp;&emsp;- \u00c9 claro que eu te desculpo Niall! Eu te amo tanto duende! &#8211; Ela se atirou em meus bra\u00e7os e eu sorri aliviado. A peguei no colo e a girei, rimos bastante. A puxei pela cintura e a beijei. &#8211; Tamb\u00e9m n\u00e3o aguentava mais ficar longe do meu potato! \u2013 Rimos. Essa \u00e9 a %Ana% que eu conhe\u00e7o.<br \/>\n&emsp;&emsp;- %Aninha%, voc\u00ea aceita namorar comigo? Ser minha princesa oficialmente? &#8211; Ela sorriu de orelha a orelha e pulou em cima de mim.<br \/>\n&emsp;&emsp;- \u00c9 claro que eu aceito Niall! &#8211; Gritou distribuindo beijinhos em meu rosto. Ficamos mais um tempo abra\u00e7ados, curtindo o momento at\u00e9 que ficou tarde e decidi ir dormir.<br \/>\n&emsp;&emsp;- %Aninha%, j\u00e1 ta tarde n\u00e9? Acho melhor eu ir dormir, boa noite. &#8211; Ela concordou e demos mais um beijo, quando fui sair do quarto, senti uma m\u00e3o quente encostar na minha e me puxar.<br \/>\n&emsp;&emsp;- Niall, dorme comigo? Ainda estou meio assustada, n\u00e3o quero dormir sozinha\u2026 &#8211; Como n\u00e3o aceitar a um pedido desses? Ela fazia biquinho. Concordei e disse apenas que pegaria meu pijama na sala. Claro que quando eu voltasse levaria umas guloseimas para aproveitarmos.<br \/>\n&emsp;&emsp;Desci as escadas e fiquei vermelho de vergonha: Liam estava sentado no sof\u00e1 e %Nathy% em seu colo. Os dois se beijavam intensamente, ele tinha as m\u00e3os sobre as coxas de %Nathalie%, que passava as m\u00e3os em seu cabelo. Decidi passar sem ser percebido mas n\u00e3o deu muito certo. Tropecei no chinelo de Louis. Porque ele sempre deixa as coisas largadas?<br \/>\n&emsp;&emsp;- Ai caralho! &#8211; Xinguei e levei as m\u00e3os a minha perna direita, que do\u00eda um pouco. %Nathy% e Liam se levantaram num pulo, se arrumaram e tentaram disfar\u00e7ar sem sucesso algum.<br \/>\n&emsp;&emsp;- Niall, t\u00e1 tudo bem? &#8211; Liam perguntou passando as m\u00e3os nos l\u00e1bios inchados e vermelhos. Eu ri.<br \/>\n&emsp;&emsp;- Ta tudo bem sim, desculpa atrapalhar o momento de voc\u00eas, s\u00f3 vim pegar meu pijama e umas guloseimas&#8230;<br \/>\n&emsp;&emsp;- Quer dizer que voc\u00ea e a buraco negro f\u00eamea voltaram? Anw que lindos! &#8211; %Nathy% me abra\u00e7ou &#8211; Ainda bem que voc\u00eas voltaram, n\u00e3o aguentava mais! \u2013 Rimos. Liam tamb\u00e9m me abra\u00e7ou e disse algumas palavras fortalecedoras que ele sempre diz. Coloquei meu pijama, fui \u00e0 cozinha, peguei alguns doces, salgados e suco, e subi ao quarto de %Aninha%. Liam e %Nathy% fizeram sinais positivos para mim.<br \/>\n&emsp;&emsp;- Podem voltar a se amar! &#8211; Comentei e ri.<br \/>\n&emsp;&emsp;- Para Niall, tenho vergonha! &#8211; %Nathy% disse e Liam a abra\u00e7ou.<br \/>\n&emsp;&emsp;- Boa noite pra voc\u00eas! &#8211; Comentei e eles desejaram boa noite. Subi ao quarto e %Aninha% me esperava ligando o v\u00eddeo game.<br \/>\n&emsp;&emsp;- Ta com sono potato? Podemos jogar!<br \/>\n&emsp;&emsp;- Claro que n\u00e3o, adoraria jogar com a minha princesa&#8230; Desculpa amor, mas vou ganhar! &#8211; <em>\u201cVai ganhar nada seu potato podre\u201d<\/em> Rimos e logo est\u00e1vamos jogando v\u00eddeo game. \u00c0s vezes r\u00edamos alto, tent\u00e1vamos nos controlar para n\u00e3o acordar todo mundo, apesar de que duvido que estejam dormindo. Depois de algumas horas jogando v\u00eddeo game e comendo porcarias, fomos dormir. Deitamos abra\u00e7ados e&#8230; Que saudade da minha princesa! Ap\u00f3s alguns minutos dormi.<\/p>\n\n<p>&emsp;&emsp;<strong>Harry\u2019s POV<\/strong><br \/>\n&emsp;&emsp;Chegamos exaustos no hotel, agradeci por ele ser s\u00f3 a alguns quarteir\u00f5es da festa. Jogamos conversa fora at\u00e9 que %Vick% dormiu, o tapad\u00e3o do Zayn ficou l\u00e1, s\u00f3 babando em cima da menina. Menino <em>burro<\/em>, menino <em>lerdo<\/em>.<br \/>\n&emsp;&emsp;- Zayn, a leve pro quarto, p\u00f5e um pijama nela, aproveita e concerta as coisas! &#8211; Falei calmo, mas queria pegar aquele topete do Zayn a arrastar os dois at\u00e9 o quarto. Ele estava t\u00e3o apaixonado que foi todo cuidadoso com ela no colo, calculando o passo de degrau em degrau, esses dois se acertam, to sentindo.<br \/>\n&emsp;&emsp;- NOSSA, O HAROLDO PENSANDO? VAI CHOVER HOJE! \u2013 %Cah% exalando humor. <br \/>\n&emsp;&emsp;- Amor, vamos dormir tamb\u00e9m? To cansada\u2026 &#8211; %Paula% me puxou pelo bra\u00e7o e eu quase a beijei para agradecer &#8211; Boa noite galera! &#8211; Ela terminou a frase e subimos.<br \/>\n&emsp;&emsp;Eu gosto de estar com a galera, mas tamb\u00e9m gosto de ficar sozinho com a minha %Paula%, e isso n\u00e3o estava acontecendo com frequ\u00eancia, j\u00e1 que sempre a %Vick% ou a %Ana% queriam conversar\u2026 Por isso era bom todo mundo voltar a ser feliz e contente. Entramos no quarto, colocamos nossos pijamas (no meu caso s\u00f3 uma cal\u00e7a de moletom) e deitamos.<br \/>\n&emsp;&emsp;- Harry? &#8211; %Paula% se virou para me encarar.<br \/>\n&emsp;&emsp;- Que foi amor?<br \/>\n&emsp;&emsp;- To sem sono, quero assistir um filme &#8211; Ela fez bico. O que eu n\u00e3o fa\u00e7o por ela? Levantei, procurei um DVD nas coisas dela, escolhi Jogos Vorazes. Parece que ela tinha gostado da ideia.<br \/>\n&emsp;&emsp;- Harry? &#8211; %Paula% me chamava outra vez.<br \/>\n&emsp;&emsp;- Oi?<br \/>\n&emsp;&emsp;- Agora eu quero conversar\u2026 &#8211; Nem um pouco bipolar.<br \/>\n&emsp;&emsp;- Sobre o que?<br \/>\n&emsp;&emsp;- Posso desabafar? &#8211; Ela perguntou e eu assenti. %Paulinha% se sentou na minha frente e come\u00e7ou a falar &#8211; OLHA, EU TO PUTA COM O QUE ACONTECEU HOJE, SEI QUE \u00c9 MEIO SEM NO\u00c7\u00c3O, MAS CARA\u2026 ESSES MENINOS DO THE WANTED S\u00c3O UNS IDIOTAS N\u00c9? QUE \u00d3DIO! &#8211; Ela respirou &#8211; Me sinto bem melhor agora.<br \/>\n&emsp;&emsp;- Nossa &#8211; Eu realmente n\u00e3o sabia o que dizer, s\u00f3 ria &#8211; Amor, posso te falar uma coisa?<br \/>\n&emsp;&emsp;- Pode! &#8211; Ela permitiu e eu me aproximei dela, a deitei e fiquei em cima dela. Podia at\u00e9 sentir a respira\u00e7\u00e3o ofegante e ver detalhadamente o fundo dos seus olhos<br \/>\n&emsp;&emsp;- \u00c0s vezes voc\u00ea fala demais\u2026 &#8211; A beijei intensamente.<br \/>\n&emsp;&emsp;- Bobo! &#8211; Ela disse em meio aos beijos.<br \/>\n&emsp;&emsp;- BOBO N\u00c3O! &#8211; Me fingi de bravo e comecei a fazer c\u00f3cegas nela, ela ria muito alto e gritava por clem\u00eancia.<br \/>\n&emsp;&emsp;- ME RENDO, CHEGA &#8211; Ela estava vermelha e quase chorava de tanto rir. Desliguei o DVD, me deitei e ela deitou ao meu lado, apoiando a cabe\u00e7a em meu peito. <br \/>\n&emsp;&emsp;- Harry?<br \/>\n&emsp;&emsp;- Fala amor!<br \/>\n&emsp;&emsp;- Agora eu quero dormir! &#8211; Ela comentou e eu ri. Ficamos de conchinha at\u00e9 pegarmos no sono, o que n\u00e3o foi muito dif\u00edcil, j\u00e1 que eu estava com a melhor companhia do mundo.<\/p>\n\n<p>&emsp;&emsp;<strong>Vit\u00f3ria\u2019s POV<\/strong><br \/>\n&emsp;&emsp;Chegamos no hotel e me sentei ao lado do Zayn. J\u00e1 disse que quando eu choro fico com sono? Ent\u00e3o\u2026 O povo tava num papo muito bom e muito legal, mas meus olhos j\u00e1 n\u00e3o se aguentavam abertos. Aos poucos fui ficando mais sonolenta at\u00e9 que encostei minha cabe\u00e7a no ombro do Zayn e dormi. Acordei assustada. Estava na minha cama, de pijama e enrolada nas cobertas. Levantei num pulo, verifiquei no celular e eram 02h00 da manh\u00e3! Fiquei sem entender nada, olhei para baixo e vi que Zayn dormia num colch\u00e3o no ch\u00e3o, do lado da minha cama.<br \/>\n&emsp;&emsp;- Zayn, Zaaaaaayn! Acorda! &#8211; Resolvi acord\u00e1-lo para esclarecer o que tinha acontecido: COMO EU TROQUEI DE ROUPA? N\u00e3o quero nem pensar. Ele despertou lentamente, esfregou os olhos e me encarou. Senti meu cora\u00e7\u00e3o bater r\u00e1pido e lento ao mesmo tempo.<br \/>\n&emsp;&emsp;- \u00c9r, bom dia? Que horas s\u00e3o? Parece que eu acabei de dormir! &#8211; Ele riu.<br \/>\n&emsp;&emsp;- S\u00e3o 2h00 da manh\u00e3! &#8211; Ele me olhou com uma cara: E QUE PORRA EU TO FAZENDO ACORDADO? Resolvi continuar &#8211; \u00c9 que olha, eu dormi na sala, acordei no meu quarto de pijama e deitada na cama. Olho para o lado e quem esta no colch\u00e3o no ch\u00e3o? Zayn Malik\u2026<br \/>\n&emsp;&emsp;- Ah \u00e9! &#8211; Ele riu novamente &#8211; Eu que te troquei e te enrolei nas cobertas, \u00e9 que voc\u00ea dormiu no meu ombro l\u00e1 na sala e fiquei com d\u00f3 de te acordar, pequena\u2026 &#8211; EU POSSO CHORAR? Odeio quando ele me chama de pequena, porque eu sempre fico manteiga derretida &#8211; E eu s\u00f3 fiquei aqui porque prometi pra mim mesmo que s\u00f3 sairia desse quarto depois que conversasse contigo!<br \/>\n&emsp;&emsp;- Bom &#8211; Me sentei na cama e fiz com que ele sentasse ao meu lado &#8211; Pode falar, estou aqui!<br \/>\n&emsp;&emsp;- Vit\u00f3ria &#8211; Ele segurou minhas m\u00e3os &#8211; Eu quero te pedir desculpas! Sei que j\u00e1 fiz isso milhares de vezes, mas dessa vez quero que voc\u00ea me perdoe de verdade pelo que eu fiz com voc\u00ea\u2026 Sei tamb\u00e9m que faz um tempo j\u00e1, s\u00f3 que eu n\u00e3o consigo mais viver sem voc\u00ea &#8211; Pausa dram\u00e1tica &#8211; N\u00e3o d\u00e1 mais! Toda vez que eu te olho quero te abra\u00e7ar, te proteger e\u2026 Voc\u00ea ficando longe de mim desse jeito, s\u00f3 esta me matando aos poucos! To com saudade de brigar com voc\u00ea por causa do espelho, to com saudade de rir com voc\u00ea, to com saudade de te chamar de minha \u2013 Uma l\u00e1grima escorreu pela minha bochecha, ele a limpou com o polegar e me abra\u00e7ou &#8211; %Vick%, voc\u00ea\u2026 Voc\u00ea quer namorar comigo? &#8211; Nesse momento eu senti fogos de artif\u00edcio no est\u00f4mago, eu queria ir para a sala, subir na mesa e gritar pra todo mundo ouvir: EU AMO O ZAYN!<br \/>\n&emsp;&emsp;- Zayn eu\u2026 &#8211; N\u00e3o me aguentei e me joguei nos bra\u00e7os dele &#8211; Eu aceito &#8211; Sussurrei em seu ouvido. Ficamos um tempo nos encarando at\u00e9 que finalmente nos beijamos. Foi um beijo de saudade, cede\u2026 Um beijo de posse! Fazia tanto tempo que eu queria isso, at\u00e9 me senti aliviada.<br \/>\n&emsp;&emsp;- Voc\u00ea n\u00e3o tem no\u00e7\u00e3o do quanto que eu sofri nessas \u00faltimas semanas! &#8211; Ele passou a m\u00e3o no cabelo &#8211; Mas foi bom! Foi pra eu aprender que n\u00e3o vivo sem voc\u00ea, pequena \u2013 Eu n\u00e3o conseguia responder. Ainda n\u00e3o estava acreditando no que tinha acabado de acontecer. Organizei as ideias e respondi:<br \/>\n&emsp;&emsp;- Ei, chega de pensar nisso! Agora vamos aproveitar cada minuto juntos, promete?<br \/>\n&emsp;&emsp;- Prometo &#8211; Ele selou nossos l\u00e1bios outra vez.<br \/>\n&emsp;&emsp;Claro que eu o fiz deitar comigo, n\u00e3o ia deixar meu namorado dormir no ch\u00e3o, enfim\u2026 Nos deitamos bem coladinhos.<br \/>\n&emsp;&emsp;- T\u00e1 acordado? &#8211; Ele se virou para mim e assentiu &#8211; Eu sou t\u00e3o tapada que me esqueci de te agradecer! Obrigada por me salvar hoje daqueles brutos na festa\u2026 Se n\u00e3o fosse voc\u00ea, acho que\u2026<br \/>\n&emsp;&emsp;- Shhh &#8211; Ele fez com que eu ficasse em sil\u00eancio &#8211; Tamb\u00e9m vamos esquecer isso, ta legal? &#8211; Assenti &#8211; Agora vamos dormir porque voc\u00ea precisa descansar!<br \/>\n&emsp;&emsp;- Ok! Boa noite Malik!<br \/>\n&emsp;&emsp;- Boa noite pequena!<br \/>\n&emsp;&emsp;Ele beijou minha testa e ficamos de conchinha. Estava com saudades dele, at\u00e9 o cheiro dele me acalmava. Eu admito que foi tudo frescura, nem paramos de usar o Yin Yang\u2026 Nem a %Ana% e o Niall pararam de usar o pandeiro e o trevo\u2026 Mas como ele mesmo disse, esse tempo foi bom para cada um tirar suas conclus\u00f5es, e as minhas foram: N\u00e3o vivo sem o Zayn e nunca mais farei isso outra vez! Limpei minha mente desses pensamentos e dormi, j\u00e1 que estava bem cansada.<\/p>\n\n<p>&emsp;&emsp;<strong>%Clarissa%\u2019s POV<\/strong><br \/>\n&emsp;&emsp;\u00c9 hoje que esse pessoal se resolve. Tomara que sim! N\u00e3o aguento mais esse clim\u00e3o, ainda mais depois do que aconteceu na festa\u2026 Como aqueles caras do The Wanted conseguem ser t\u00e3o cretinos? Estavam mais pra l\u00e1 do que pra c\u00e1 de b\u00eabados, mas normais tamb\u00e9m n\u00e3o devem ser diferentes&#8230; Fomos para o meu quarto e Louis ficou no twitter enquanto eu tomava banho. Sa\u00ed com um camiset\u00e3o e ele me fitou intensamente.<br \/>\n&emsp;&emsp;- Quer tomar banho Lou? Te empresto uma camiseta minha&#8230; &#8211; Ri.<br \/>\n&emsp;&emsp;- Ai que engra\u00e7adinha, vai ficar super sexy em mim! &#8211; Rimos. &#8211; Mas aceito tomar um banho sim! &#8211; Peguei uma toalha para ele e entrei no twitter de divulga\u00e7\u00e3o do document\u00e1rio. <br \/>\n&emsp;&emsp;As lindas das directioners ainda mandavam mensagens de apoio para n\u00f3s, principalmente as brasileiras n\u00e9? Respondi algumas meninas e at\u00e9 alguns meninos, eles pediam para que eu postasse uma foto minha com o Lou, mas achei melhor n\u00e3o, tinha que falar com ele primeiro&#8230; Entrei um pouco no meu facebook, conversei com a minha m\u00e3e e minha fam\u00edlia, at\u00e9 que o chuveiro desligou e eu desliguei o computador tamb\u00e9m. Logo a porta do banheiro se abriu e eu levantei a cabe\u00e7a para observar, fiquei est\u00e1tica. Louis saiu apenas com sua boxer branca.<br \/>\n&emsp;&emsp;- Amor, vou deixar minhas roupas aqui ok? To cheirosinho: n\u00e3o quero dormir fedido com voc\u00ea &#8211; Ele sorriu. Ah aquele sorriso, aquele corpo, meu Deus! Isso \u00e9 demais pra mim.<br \/>\n&emsp;&emsp;- Ah deixa num canto qualquer ai! Amanh\u00e3 a gente v\u00ea isso! &#8211; Apaguei a luz e acendi o abajur me segurando pra n\u00e3o voar naquela coisa maravilhosa. Fui pegar o edredom no arm\u00e1rio e ele me abra\u00e7ou por tr\u00e1s.<br \/>\n&emsp;&emsp;- Sabia que estou morrendo de saudades de voc\u00ea amor? &#8211; Louis sussurrou em meu ouvido e distribuiu beijinhos pelo meu pesco\u00e7o.<br \/>\n&emsp;&emsp;- Loooooouis! &#8211; Adverti. Ele continuou a distribuir beijinhos at\u00e9 que me virou de frente para ele e me prensou na porta do guarda roupa. A dist\u00e2ncia entre nossos corpos era m\u00ednima, aqueles olhos azuis me encaravam profundamente. &#8211; Desisto! &#8211; Disse e o puxei pelo pesco\u00e7o.<br \/>\n&emsp;&emsp;Come\u00e7amos um beijo intenso, as m\u00e3os de Louis passavam por todo o meu corpo, at\u00e9 que ele me pegou no colo e eu enlacei minhas pernas em sua cintura. Paramos de nos beijar ofegantes, apenas por dois segundos, logo voltamos. Eu j\u00e1 estava sem f\u00f4lego, quando percebi est\u00e1vamos deitados na cama, Lou por cima de mim. Os carinhos foram ficando cada vez mais quentes, at\u00e9 que rolou. E foi lindo, m\u00e1gico&#8230; Louis era perfeito, carinhoso e eu amo ele mais que tudo nessa vida.<\/p>","protected":false},"excerpt":{"rendered":"<p>&emsp;&emsp;%Nathalie%\u2019s POV &emsp;&emsp;Despedimo-nos de alguns amigos dos meninos e de alguns amigos nossos. Sa\u00edmos pelos fundos para nenhum fot\u00f3grafo nos perseguir e fomos com a van, para n\u00e3o chamar aten\u00e7\u00e3o. Nem preciso falar que chegamos quebrados no hotel, mas mesmo assim ficamos na sala conversando. Sentamos na poltrona eu e o Liam, num sof\u00e1 a [&hellip;]<\/p>\n","protected":false},"author":107,"featured_media":0,"parent":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":true,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"historias":[2280],"class_list":["post-7920","capitular","type-capitular","status-publish","format-standard","hentry","historias-life-as-one-direction"],"acf":[],"_links":{"self":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular\/7920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular"}],"about":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/types\/capitular"}],"author":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/users\/107"}],"replies":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/comments?post=7920"}],"wp:attachment":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/media?parent=7920"}],"wp:term":[{"taxonomy":"historias","embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/historias?post=7920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}