{"id":7667,"date":"2024-06-11T14:18:00","date_gmt":"2024-06-11T17:18:00","guid":{"rendered":"https:\/\/espacocriativo.net\/acervo\/historia\/historia-sem-nome\/rascunho-automatico\/"},"modified":"2025-11-09T14:19:36","modified_gmt":"2025-11-09T17:19:36","slug":"capitulo-2","status":"publish","type":"capitular","link":"https:\/\/espacocriativo.net\/acervo\/historia\/dahlia-negra\/capitulo-2\/","title":{"rendered":"CAP\u00cdTULO DOIS"},"content":{"rendered":"\n<p>&emsp;&emsp;<span class=\"versalete\">A aus\u00eancia de movimento<\/span> era at\u00edpica naquela regi\u00e3o de New York. Havia passado das oito da noite, deixando a ilumina\u00e7\u00e3o a cargo dos diversos postes, al\u00e9m das luzes provenientes das resid\u00eancias e estabelecimentos comerciais.<br>\n&emsp;&emsp;Era de se esperar que a agita\u00e7\u00e3o ainda estivesse presente e carros passassem de um lado a outro, no entanto, tudo estava estranhamente silencioso, como se houvesse alguma esp\u00e9cie de toque de recolher estabelecida por ali.<br>\n&emsp;&emsp;Se realmente se tratava daquilo ou n\u00e3o, o senhor Goodman n\u00e3o queria saber. Nada o impediria de ir at\u00e9 o mercado de sempre para comprar os alimentos que sua esposa havia solicitado.<br>\n&emsp;&emsp;Na verdade, a senhora Goodman n\u00e3o havia pedido nada, mas sua perna machucada por uma queda recente requeria um pouco mais de cuidados. Ent\u00e3o, mesmo sob protestos, o marido conseguiu fazer com que ela ficasse quietinha em casa, aguardando-o retornar com tudo o que precisava para fazer o jantar.<br>\n&emsp;&emsp;A respira\u00e7\u00e3o do velho senhor estava um tanto falha devido ao esfor\u00e7o da caminhada. N\u00e3o era um trajeto muito longo, mas seus pulm\u00f5es n\u00e3o funcionavam da mesma forma de quando era jovem e qualquer tentativa de apressar seus passos logo fazia seu cora\u00e7\u00e3o disparar como se fosse sair pela boca a qualquer momento.<br>\n&emsp;&emsp;Carregando o pacote de papel nos bra\u00e7os, Goodman caminhava com uma certa tranquilidade que n\u00e3o condizia muito com a atmosfera da regi\u00e3o naqueles \u00faltimos tempos. N\u00e3o com um poss\u00edvel assassino \u00e0 solta. Mas pelo que o homem havia visto nos notici\u00e1rios, o tal Dahlia Negra tinha uma prefer\u00eancia por criminosos, ent\u00e3o aquilo significava que estava livre, certo? E, de qualquer forma, ele estava velho demais para se importar com coisas do tipo. Costumava dizer que quando chegasse sua hora, ele partiria e n\u00e3o havia nada que ningu\u00e9m pudesse fazer.<br>\n&emsp;&emsp;Dando uma risada rouca de seus pr\u00f3prios pensamentos, o senhor Goodman acabou tossindo sonoramente, sentindo seus pulm\u00f5es protestarem novamente e clamarem por oxig\u00eanio. Ele parou sua caminhada sem se dar conta, ou at\u00e9 mesmo sem se importar com a sombra parada na curva de um beco escuro.<br>\n&emsp;&emsp;O dono da sombra, no entanto, se importava com o velho senhor. N\u00e3o por ter alguma rela\u00e7\u00e3o com ele ou empatia, mas simplesmente porque ali estava a sua oportunidade de garantir alguma coisa naquela noite.<br>\n&emsp;&emsp;Se aproximou sorrateiramente, observando Goodman tirar um len\u00e7o do bolso de sua cal\u00e7a para tossir mais uma vez, cobrindo a boca com o peda\u00e7o de pano. E foi quando o homem ergueu sua cabe\u00e7a que sentiu o cano de uma arma encostar na base de suas costas.<br>\n&emsp;&emsp;Por mais que estivesse conformado com o fato de que morreria em breve, a sensa\u00e7\u00e3o de que sua vida agora estava nas m\u00e3os de um estranho fez com que gelo percorresse sua espinha e cada c\u00e9lula de seu corpo entrasse em estado de alerta. A adrenalina gritou para que corresse o mais r\u00e1pido que pudesse, por\u00e9m, seu c\u00e9rebro clamava o contr\u00e1rio. Correr s\u00f3 ia fazer o estranho apertar o gatilho, fazendo com que as compras nunca chegassem at\u00e9 sua amada esposa.<br>\n&emsp;&emsp;\u2014 Se tentar fugir ou gritar, voc\u00ea morre. Entendeu? \u2014 A voz rouca fez o trabalho de aumentar ainda mais o pavor que o velho senhor sentia.<br>\n&emsp;&emsp;Ele assentiu febrilmente. A \u00fanica coisa que pensava era na senhora Goodman.<br>\n&emsp;&emsp;\u2014 \u00d3timo. Ent\u00e3o anda comigo. \u2014 O assaltante empurrou o cano da arma, cutucando as costas do homem e o fazendo caminhar para dentro do beco escuro, onde definitivamente ningu\u00e9m poderia v\u00ea-los. Mesmo as ruas estando desertas, n\u00e3o podia arriscar.<br>\n&emsp;&emsp;Goodman engoliu em seco, seus pulm\u00f5es come\u00e7aram uma luta ainda mais intensa por oxig\u00eanio e seus l\u00e1bios come\u00e7aram a tremer sem controle, pressentindo que o pior estava prestes a acontecer.<br>\n&emsp;&emsp;Por que aquele estranho simplesmente n\u00e3o pegava seu dinheiro e ia embora?<br>\n&emsp;&emsp;\u2014 Pode parar a\u00ed. \u2014 Apontou a parede ao lado de uma grande ca\u00e7amba de lixo. \u2014 Agora passa tudo o que tiver nos bolsos.<br>\n&emsp;&emsp;Tentando controlar a tremedeira em suas m\u00e3os, o homem tateou um dos bolsos com a m\u00e3o livre, entregando a carteira e mostrando em seguida que no outro havia apenas a chave de sua casa.<br>\n&emsp;&emsp;\u2014 Seu rel\u00f3gio tamb\u00e9m.<br>\n&emsp;&emsp;O cora\u00e7\u00e3o do senhor Goodman se apertou quando ele ouviu aquilo. O rel\u00f3gio havia sido um presente da filha, que naquele momento provavelmente estava do outro lado da cidade, encerrando seu expediente na empresa em que trabalhava. Ele n\u00e3o a via j\u00e1 fazia quase um m\u00eas, era verdade, por\u00e9m sabia o quanto a mulher era ocupada e tinha certeza de que a sua esposa tamb\u00e9m. Aquilo nunca havia sido um problema para o casal, por mais saudades que sentissem.<br>\n&emsp;&emsp;Se separar daquele item era como deixar que um peda\u00e7o de sua filha fosse levado e, por um mil\u00e9simo de segundo, o homem hesitou. O momento n\u00e3o passou despercebido pelo assaltante, que, dominado pela pr\u00f3pria adrenalina, agiu com ainda mais agressividade.<br>\n&emsp;&emsp;\u2014 T\u00e1 de brincadeira, velhote? Passa logo essa merda! \u2014 Ent\u00e3o o socou com tanta for\u00e7a em um dos ombros que o pacote de compras caiu das m\u00e3os do senhor Goodman.<br>\n&emsp;&emsp;Um grunhido de dor ecoou pelo ambiente e l\u00e1grimas escaparam dos olhos do homem. Naquele momento, Goodman teve a certeza de que, mesmo que entregasse seu rel\u00f3gio \u00e0quele estranho, n\u00e3o seria o suficiente. Sem nada a perder, ele tiraria sua vida.<br>\n&emsp;&emsp;Pensou em implorar, mas de repente n\u00e3o encontrava for\u00e7as para fazer com que as palavras sa\u00edssem de sua boca. O desespero era tanto que naquele momento a \u00fanica coisa que lhe restava era pedir mentalmente por uma salva\u00e7\u00e3o, mesmo sabendo que esta nunca chegaria.<br>\n&emsp;&emsp;Estendendo o pulso, tremendo como se estivesse congelando de frio, seus dedos erraram algumas vezes em abrir o fecho do rel\u00f3gio, o que causou ainda mais impaci\u00eancia ao assaltante. A arma foi pressionada com mais for\u00e7a em suas costas e mais amea\u00e7as foram proferidas, por\u00e9m o pavor naquele momento era tanto que o senhor Goodman mal conseguiu entend\u00ea-las. S\u00f3 queria que aquilo acabasse de uma vez. S\u00f3 queria voltar para casa e se aninhar com a esposa, nunca mais solt\u00e1-la.<br>\n&emsp;&emsp;Ent\u00e3o, de repente, n\u00e3o havia mais nada machucando suas costas. N\u00e3o havia mais ningu\u00e9m cuspindo enquanto gritava em seu ouvido. A \u00fanica coisa que o senhor Goodman sentiu foi uma lufada de ar, como se o pr\u00f3prio vento tivesse arrancado o assaltante dali.<br>\n&emsp;&emsp;Atordoado, o homem olhou \u00e0 sua volta, percebendo que o estranho agora estava atirado no ch\u00e3o, a apenas alguns metros dele e olhava em sua dire\u00e7\u00e3o com f\u00faria.<br>\n&emsp;&emsp;Mais uma onda de p\u00e2nico tomou conta de si, at\u00e9 o momento em que a arma voltou a ser erguida e o assaltante a apontou para algo que parecia estar logo atr\u00e1s de Goodman.<br>\n&emsp;&emsp;\u2014 Seja l\u00e1 quem voc\u00ea for, eu n\u00e3o tenho medo. Te furo inteiro antes mesmo de se mexer! \u2014 Estava claro que sua primeira frase n\u00e3o era verdadeira. Sua voz estava tr\u00eamula, assim como sua m\u00e3o, enquanto se atrapalhava para posicionar o dedo no gatilho.<br>\n&emsp;&emsp;Uma risada baixa ecoou.<br>\n&emsp;&emsp;\u2014 Quero ver voc\u00ea tentar. Manda a ver! \u2014 A voz era um tanto distorcida e o senhor Goodman n\u00e3o conseguiu reconhec\u00ea-la, muito menos distinguir se pertencia a um homem ou a uma mulher.<br>\n&emsp;&emsp;Ele se virou para olhar quem o salvava, por\u00e9m, t\u00e3o r\u00e1pido quanto havia atingido o assaltante anteriormente, o vulto encapuzado se lan\u00e7ou na dire\u00e7\u00e3o dele, ficando bem diante da arma, como se esperasse pelos tiros que foram prometidos.<br>\n&emsp;&emsp;\u2014 E ent\u00e3o? N\u00e3o vai me furar? \u2014 Mais uma risada sarc\u00e1stica p\u00f4de ser ouvida e o vigilante tombou a cabe\u00e7a de lado, parecendo se divertir com o quanto o assaltante de repente parecia atrapalhado. \u2014 Voc\u00eas criminosos s\u00e3o mesmo todos iguais.<br>\n&emsp;&emsp;Ent\u00e3o lhe deu um chute que fez a arma voar longe ao mesmo tempo que um grito de dor dominou o ambiente.<br>\n&emsp;&emsp;Os olhos do senhor Goodman se arregalaram diante daquilo e ele p\u00f4de jurar que tinha visto a m\u00e3o do homem se dobrar em um \u00e2ngulo estranho.<br>\n&emsp;&emsp;As hist\u00f3rias sobre a figura encapuzada realmente eram verdadeiras. Aquele era o Dahlia Negra e aquele gesto deixou muito claro que n\u00e3o teria um pingo de miseric\u00f3rdia com aquele homem.<br>\n&emsp;&emsp;Ainda encolhido onde estava, paralisado pelo medo, o senhor Goodman assistiu quando Dahlia Negra avan\u00e7ou ainda mais para cima do criminoso, desviando uma tentativa tosca de um soco e atingindo-o com um chute em uma das pernas. O homem tombou, caindo de joelhos, mas mal teve tempo para se dar conta disso, porque, no instante seguinte, foi atingido com socos impiedosos em seu rosto.<br>\n&emsp;&emsp;\u2014 Gosta de assaltar idosos e bater neles? \u2014 o vigilante sibilava, completamente dominado pela f\u00faria, n\u00e3o deixando que o homem respondesse, lhe dando joelhadas no est\u00f4mago e acertando seu queixo com um gancho de direita que com toda certeza devia ter quebrado sua mand\u00edbula.<br>\n&emsp;&emsp;Goodman devia desejar que o criminoso pagasse pelo que havia feito com ele, mas n\u00e3o se sentia daquela forma. Cada golpe que assistia o homem receber e cada som de dor e engasgo que chegava aos seus ouvidos fazia uma agonia sem fim tomar conta de si.<br>\n&emsp;&emsp;\u2014 Pare! \u2014 De repente, ouviu a pr\u00f3pria voz ecoar, falha devido \u00e0 falta de oxig\u00eanio que nunca ia embora.<br>\n&emsp;&emsp;O vulto, que naquele momento segurava o assaltante pela gola da camiseta, se virou para encarar o velho senhor. Pela forma como o corpo do homem balan\u00e7ava mole, estava praticamente desmaiado \u00e0quela altura.<br>\n&emsp;&emsp;\u2014 Por favor, ele vai pagar pelo que fez. V\u00e3o jog\u00e1-lo numa cela. Voc\u00ea n\u00e3o precisa fazer isso \u2014 Goodman prosseguiu, num fio de esperan\u00e7a de que suas palavras estariam surtindo algum efeito.<br>\n&emsp;&emsp;Dahlia Negra olhou rapidamente para o homem em suas m\u00e3os e mais uma vez para o senhor Goodman.<br>\n&emsp;&emsp;\u2014 Tenha miseric\u00f3rdia. \u2014 Mal sabia ele que aquela havia sido uma p\u00e9ssima escolha de palavras.<br>\n&emsp;&emsp;\u2014 A miseric\u00f3rdia \u00e9 dada apenas para aqueles que merecem. Ele ser\u00e1 preso hoje, amanh\u00e3 volta para as ruas e volta a atacar pessoas. Ele n\u00e3o merece miseric\u00f3rdia \u2014 declarou, irredut\u00edvel.<br>\n&emsp;&emsp;\u2014 E quem \u00e9 voc\u00ea para julgar quem merece miseric\u00f3rdia ou n\u00e3o? \u2014 Goodman questionou, em um surto de coragem.<br>\n&emsp;&emsp;\u2014 Eu sou a <em>justi\u00e7a<\/em>. <br>\n&emsp;&emsp;De repente, as sirenes da pol\u00edcia puderam ser ouvidas. Ainda estavam h\u00e1 alguns quarteir\u00f5es de dist\u00e2ncia, ent\u00e3o Dahlia Negra teria tempo o suficiente para terminar seu trabalho.<br>\n&emsp;&emsp;\u2014 Se eu fosse o senhor, n\u00e3o olhava. \u2014 Sabia que n\u00e3o teria tempo para esperar o velho senhor sair dali, ent\u00e3o apenas se voltou para o criminoso, que soltou um gemido baixo, denunciando que estava quase recobrando a consci\u00eancia.<br>\n&emsp;&emsp;Puxando a adaga de sua cintura, o vigilante precisou de apenas um movimento r\u00e1pido para cortar a garganta do homem, jogando-o no ch\u00e3o e o assistindo se debater enquanto encarava a \u00faltima coisa que veria em sua vida. Um olho azul e o outro negro.<br>\n&emsp;&emsp;Horrorizado, o senhor Goodman assistiu o vulto encapuzado tirar uma pequena planta e coloc\u00e1-la sobre o assaltante, agora morto.<br>\n&emsp;&emsp;\u2014 <em>Ei, voc\u00ea!<\/em> \u2014 De repente, uma terceira voz preencheu o ambiente e Dahlia Negra se virou na dire\u00e7\u00e3o dela, j\u00e1 sabendo muito bem a quem pertencia.<\/p>\n\n<p align=\"center\">\ud83d\udd77<\/p>\n\n<p>&emsp;&emsp;Peter Parker havia disparado janela afora ao ouvir no r\u00e1dio da pol\u00edcia que havia uma ocorr\u00eancia onde o Dahlia Negra parecia estar envolvido.<br>\n&emsp;&emsp;N\u00e3o lembrava de ter disparado suas teias e cruzado os grandes pr\u00e9dios t\u00e3o r\u00e1pido desde o momento de sua volta \u00e0quele universo. A ansiedade em confrontar aquele assassino de criminosos tomava conta de si.<br>\n&emsp;&emsp;Na verdade, ele n\u00e3o sabia como cham\u00e1-lo. Se de assassino ou justiceiro. Precisava descobrir qual era seu prop\u00f3sito e aquela era a sua chance.<br>\n&emsp;&emsp;Usando seu sentido aranha, conseguiu localizar com mais facilidade onde tudo estava acontecendo, mas, ao chegar l\u00e1, viu que era tarde demais para salvar uma vida.<br>\n&emsp;&emsp;Dahlia Negra deixava sua assinatura sobre o corpo do criminoso, enquanto um senhor se encolhia horrorizado. Sua voz ecoou pelo beco, chamando a aten\u00e7\u00e3o da figura, que se voltou para ele e tombou a cabe\u00e7a de lado como se o desafiasse.<br>\n&emsp;&emsp;\u2014 Eu s\u00f3 quero\u2026 bater um papo. \u2014 O Homem Aranha interrompeu sua fala, quando Dahlia Negra disparou pela noite em uma velocidade t\u00e3o impressionante quanto sua habilidade para escalar muros.<br>\n&emsp;&emsp;Peter tentou lan\u00e7ar uma teia, mas n\u00e3o conseguiu peg\u00e1-lo, ent\u00e3o seguiu na dire\u00e7\u00e3o por onde o justiceiro havia ido. Seguiu procurando qualquer vest\u00edgio dele, por\u00e9m, frustrado, n\u00e3o encontrou nenhum sinal do Dahlia Negra.<br>\n&emsp;&emsp;<em>Ele havia sumido feito fuma\u00e7a<\/em>.<\/p>\n\n<p>&emsp;&emsp;Honestamente, dizer que Peter Parker estava frustrado era muito pouco. Sem conseguir evitar um grunhido alto de frustra\u00e7\u00e3o, o Homem Aranha retornou ao local do crime para se certificar de que o senhor Goodman estava bem e descobriu que, al\u00e9m do choque com a cena presenciada, o homem estava com seu ombro deslocado.<br>\n&emsp;&emsp;Aos sussurros, ele contou que havia sido o criminoso, mas que nem por isso a morte e a viol\u00eancia eram a solu\u00e7\u00e3o. Parker ficou ali, lhe fazendo companhia at\u00e9 a pol\u00edcia enfim chegar e s\u00f3 foi embora ap\u00f3s se certificar de que tudo estava mesmo bem.<br>\n&emsp;&emsp;\u2014 Obrigado, meu filho. Voc\u00ea tem um bom cora\u00e7\u00e3o. \u2014 A voz do senhor Goodman permaneceu ecoando nos ouvidos de Peter enquanto ele se deslocava entre os pr\u00e9dios.<br>\n&emsp;&emsp;Mesmo n\u00e3o tendo nenhuma semelhan\u00e7a f\u00edsica, aquele homem o lembrou de seu tio Ben e v\u00ea-lo machucado daquela forma trouxe de volta aquela dor com a qual havia aprendido a conviver, mas nunca ia embora de fato.<br>\n&emsp;&emsp;Um suspiro resignado escapou de seus l\u00e1bios. Tomando mais um impulso, Parker seguiu atravessando os pr\u00e9dios, procurando por algo que ele j\u00e1 sabia que n\u00e3o ia mais encontrar. N\u00e3o havia conseguido quando a fuga do Dahlia Negra havia sido recente, n\u00e3o era naquele momento que qualquer milagre aconteceria.<br>\n&emsp;&emsp;Naquela noite, Peter interveio em mais dois crimes que aconteciam na regi\u00e3o. Um havia sido uma tentativa de furto de um carro e no outro ele parou um estranho prestes a assaltar uma conveni\u00eancia.<br>\n&emsp;&emsp;Retornando ao seu apartamento, Parker se jogou em sua cama de uniforme e tudo, encarando o teto e tentando assimilar as coisas. Tudo havia acontecido muito r\u00e1pido e ele recebeu informa\u00e7\u00f5es demais desde o momento em que foi parar em outro universo.<br>\n&emsp;&emsp;Parecia que tudo havia virado de ponta cabe\u00e7a e por mais que tentasse consertar as coisas, n\u00e3o conseguia.<br>\n&emsp;&emsp;Bufou alto, fechando os olhos e pressionando as t\u00eamporas com suas duas m\u00e3os. A imagem do Dahlia Negra se virando para encar\u00e1-lo voltou aos seus pensamentos e Peter observou que o justiceiro nem mesmo havia tentado enfrent\u00e1-lo, o que s\u00f3 deixava ainda mais claro que seus alvos eram apenas os criminosos.<br>\n&emsp;&emsp;\u2014 Mas por que mat\u00e1-los? \u2014 murmurou, aturdido. \u2014 Assassinato s\u00f3 o torna igual a eles.<br>\n&emsp;&emsp;Antes que pudesse chegar a uma resposta, no entanto, o som da televis\u00e3o, que Parker havia deixado ligada, chamou sua aten\u00e7\u00e3o.<br>\n&emsp;&emsp;\u2014 <em>E segue a busca pelo assassino vigilante, conhecido como Dahlia Negra. Embora a pol\u00edcia local n\u00e3o tenha nenhuma novidade sobre o caso, o delegado Crosby refor\u00e7ou que as investiga\u00e7\u00f5es est\u00e3o a todo vapor. Muito pouco se sabe, mas todo o cuidado \u00e9 pouco e um toque de recolher est\u00e1 sendo estudado.<\/em><br>\n&emsp;&emsp;Sentando-se na cama para prestar aten\u00e7\u00e3o no que era dito, uma careta tomou as fei\u00e7\u00f5es de Peter.<br>\n&emsp;&emsp;Ele precisava descobrir a identidade daquele vigilante e, mais do que isso, queria entender o seu prop\u00f3sito. Algo dentro de si gritava por aquilo.<br>\n&emsp;&emsp;Decidiu ent\u00e3o que no dia seguinte come\u00e7aria a analisar os lugares por onde Dahlia Negra havia deixado seu rastro.<\/p>\n\n<p align=\"center\">\ud83d\udd77<\/p>\n\n<p>&emsp;&emsp;Quando seu despertador tocou naquela manh\u00e3, um resmungo de protesto ecoou dos l\u00e1bios de Peter. Num gesto r\u00e1pido, ele se levantou e silenciou o aparelho sem nem mesmo olh\u00e1-lo, para logo em seguida desabar novamente na cama, cobrindo seu rosto com o travesseiro.<br>\n&emsp;&emsp;Pressionando os olhos com for\u00e7a, Parker desejou febrilmente voltar a dormir. Havia passado quase a madrugada toda acordado, sem conseguir parar de pensar nos \u00faltimos acontecimentos e quando finalmente sua mente relaxou estava quase amanhecendo.<br>\n&emsp;&emsp;No momento em que o barulho estridente ecoou pelo c\u00f4modo, parecia que ele havia acabado de dormir.<br>\n&emsp;&emsp;N\u00e3o soube quanto tempo permaneceu naquela posi\u00e7\u00e3o, encolhido na cama e com o travesseiro ainda tampando seu rosto, mas de repente foi como se pudesse ouvir a voz de Tia May dizendo que ele precisava levantar ou iria se atrasar.<br>\n&emsp;&emsp;Bufou, descobrindo seu rosto e encarando o teto. Para ser sincero, Peter sentia falta de quando tudo parecia se resolver se ele simplesmente fosse para a aula.<br>\n&emsp;&emsp;Havia prometido a si mesmo que tentaria viver ao menos uma parte de sua vida de forma \u201cnormal\u201d, mesmo duvidando de que aquilo realmente era poss\u00edvel, e ir para a universidade era um passo importante. N\u00e3o era?<br>\n&emsp;&emsp;Levantou da cama, por fim, pegando a primeira combina\u00e7\u00e3o de roupas que encontrou e abriu um sorriso amarelo quando viu seu reflexo desgrenhado no espelho.<br>\n&emsp;&emsp;O apartamento de Parker era realmente pequeno. O que queria dizer que seu quarto era tamb\u00e9m a sala de estar, a cozinha e a lavanderia. O \u00fanico c\u00f4modo separado era o banheiro e para ele n\u00e3o era t\u00e3o ruim. Era aquele lugar que podia pagar, ent\u00e3o <em>n\u00e3o podia<\/em> ser t\u00e3o ruim.<br>\n&emsp;&emsp;Peter abriu a geladeira, vendo que ali tinha s\u00f3 um gal\u00e3o de leite e uma bandeja com rosbife. Ele precisava comprar comida urgente, n\u00e3o podia ficar comendo todos os dias na casa da Tia May, por mais que provavelmente ela fosse adorar aquela ideia.<br>\n&emsp;&emsp;Riu com o pensamento, pegando a caixa de cereal do arm\u00e1rio, sendo aquele tamb\u00e9m o \u00fanico alimento que havia ali e colocando um pouco na tigela para depois acrescentar o leite.<br>\n&emsp;&emsp;No entanto, seu riso sumiu quando colocou uma colherada na boca. O cereal estava mole.<br>\n&emsp;&emsp;\u2014 Nojento! \u2014 resmungou, sacudindo o corpo ao sentir um arrepio e largou a tigela na pia, correndo para o banheiro e terminando de se ajeitar para finalmente sair de casa.<br>\n&emsp;&emsp;Repassando mentalmente as coisas que precisava fazer naquele dia, Peter carregou a c\u00e2mera consigo. Precisava arrumar algum dinheiro logo e o trabalho como fot\u00f3grafo freelancer sempre salvava sua vida.<br>\n&emsp;&emsp;N\u00e3o duvidava nada se o editor chefe do Clarim Di\u00e1rio resolvesse que agora queria fotos do Dahlia Negra, al\u00e9m do Homem Aranha. Todos estavam obcecados pelo justiceiro e, aparentemente, ele mesmo tamb\u00e9m estava.<br>\n&emsp;&emsp;Quando saiu para a movimentada New York, Parker de repente percebeu que precisava correr ou chegaria atrasado \u00e0 universidade.<br>\n&emsp;&emsp;Andando apressado at\u00e9 o primeiro beco vazio que encontrou, sua \u00fanica alternativa era pegar carona com o Homem Aranha.<br>\n&emsp;&emsp;E apesar do breve mau humor matinal, Peter Parker n\u00e3o deixou de cruzar as ruas e pr\u00e9dios da cidade com a anima\u00e7\u00e3o o fazendo gritar a plenos pulm\u00f5es e cumprimentar cada pessoa que parava para olh\u00e1-lo.<br>\n&emsp;&emsp;Ter conhecido os outros dois Peter Parkers tinha trazido aquilo de volta a ele. A anima\u00e7\u00e3o de ser o amigo da vizinhan\u00e7a, a vontade de ajudar cada cidad\u00e3o, mesmo em coisas simples como atravessar a rua ou salvar gatos pendurados em \u00e1rvores.<br>\n&emsp;&emsp;Lembran\u00e7as ruins tentavam cruzar seus pensamentos, por\u00e9m Peter escolheu n\u00e3o focar nelas naquele momento. Aquele dia seria \u00f3timo apenas para variar um pouco.<br>\n&emsp;&emsp;E, ao aterrissar no telhado da universidade, ele estava certo de que conseguiria.<\/p>\n\n<p align=\"center\">\ud83d\udd77<\/p>\n\n<p>&emsp;&emsp;Trabalhar como professor assistente era muito mais f\u00e1cil do que Parker imaginava. Exigia bem menos esfor\u00e7o se ele fosse considerar, bem, suas <em>outras atividades<\/em>. Peter tinha bastante experi\u00eancia e a ideia de ajudar os estudantes estava lhe agradando bem mais do que esperava.<br>\n&emsp;&emsp;No fim das contas, ele gostava de ser surpreendido. Se fosse para um lado bom, \u00e9 claro.<br>\n&emsp;&emsp;O tempo pareceu passar relativamente r\u00e1pido, ou talvez Peter apenas estivesse realmente entretido no novo emprego.<br>\n&emsp;&emsp;Ele foi bastante elogiado pelo professor Hofstader e s\u00f3 n\u00e3o recusou seu intervalo porque realmente precisava comer alguma coisa.<br>\n&emsp;&emsp;Parker voltava do refeit\u00f3rio com a ideia de passar o tempo que lhe restava no telhado, ou quem sabe na biblioteca? Como um era caminho do outro, resolveria na hora.<br>\n&emsp;&emsp;Encontrou um ou outro rosto conhecido no corredor. O lance de ser professor assistente fazia as pessoas o notarem e ele n\u00e3o sabia ainda como se sentia em rela\u00e7\u00e3o \u00e0quilo.<br>\n&emsp;&emsp;Por algum motivo, no entanto, uma das portas dos laborat\u00f3rios chamou sua aten\u00e7\u00e3o. Mais especificamente o pequeno vidro no meio dela, que dava um vislumbre de quem estivesse ali dentro e em uma bancada pr\u00f3xima.<br>\n&emsp;&emsp;E foi olhando naquela dire\u00e7\u00e3o que Peter identificou mais um rosto conhecido. Esse, no entanto, talvez n\u00e3o ficasse t\u00e3o feliz em v\u00ea-lo.<br>\n&emsp;&emsp;Era %Reyna% %Bennington%.<br>\n&emsp;&emsp;Parker n\u00e3o esperava mesmo que ela fosse ficar contente em ver o cara que tinha lhe dado um fora no outro dia. Pelo menos ele n\u00e3o ficaria se a situa\u00e7\u00e3o fosse invertida.<br>\n&emsp;&emsp;Passou reto pelo laborat\u00f3rio, agradecendo mentalmente porque %Reyna% aparentemente n\u00e3o tinha lhe visto, por\u00e9m acabou parando uns tr\u00eas passos depois.<br>\n&emsp;&emsp;Uma careta se formou em suas fei\u00e7\u00f5es. Ele devia ao menos se desculpar com ela, certo? %Rey% parecia ser uma pessoa legal, Peter s\u00f3 n\u00e3o podia arriscar a vida de outra pessoa e\u2026<br>\n&emsp;&emsp;E tinha Gwen.<br>\n&emsp;&emsp;Como podia sequer pensar em pensar em outra garota?<br>\n&emsp;&emsp;Sacudiu a cabe\u00e7a, confuso com os pr\u00f3prios pensamentos, ent\u00e3o respirou fundo.<br>\n&emsp;&emsp;Ele ia se desculpar. Era o certo a se fazer.<br>\n&emsp;&emsp;Parker s\u00f3 se deu conta de que corria o risco de passar uma vergonha colossal depois de empurrar a porta do laborat\u00f3rio e entrar. Mas, por sorte, o lugar n\u00e3o estava cheio de alunos e muito menos de outros t\u00e9cnicos. Havia apenas %Reyna% ali.<br>\n&emsp;&emsp;\u2014 Peter Parker? \u2014 A mulher havia erguido a cabe\u00e7a para encar\u00e1-lo, erguendo uma sobrancelha em confus\u00e3o. De todas as pessoas que poderiam entrar ali, jamais esperaria por ele.<br>\n&emsp;&emsp;Peter co\u00e7ou a nuca, nervoso, ent\u00e3o deu dois passos na dire\u00e7\u00e3o da bancada onde %Bennington% estava.<br>\n&emsp;&emsp;\u2014 Esse sou eu \u2014 respondeu a primeira coisa que veio \u00e0 sua cabe\u00e7a e se sentiu idiota por aquilo segundos depois.<br>\n&emsp;&emsp;\u2014 N\u00e3o quero ser mal educada, mas\u2026 O que faz aqui? \u2014 Ela o avaliou rapidamente, tentando parecer o mais centrada poss\u00edvel. Parker a deixava nervosa e ele certamente j\u00e1 a achava maluca o suficiente por conta do convite no outro dia.<br>\n&emsp;&emsp;\u2014 Hm, eu estava passando e te vi aqui. Achei que seria uma boa hora para conversar sobre uma coisa. \u2014 Peter torceu a boca, como se j\u00e1 esperasse uma resposta negativa por parte dela, por\u00e9m %Reyna% achou aquilo um tanto ador\u00e1vel e conteve um sorriso.<br>\n&emsp;&emsp;\u2014 Tudo bem. Mas \u00e9 melhor voc\u00ea vestir um jaleco antes. Ainda n\u00e3o cheguei aos meus experimentos em humanos. \u2014 Piscou para ele, indicando que poderia pegar um dos jalecos pendurados atr\u00e1s da porta, se precisasse.<br>\n&emsp;&emsp;O coment\u00e1rio fez Parker sentir uma s\u00fabita curiosidade, mas n\u00e3o podia se distrair e s\u00f3 sairia daquele lugar depois de ter resolvido as coisas com ela.<br>\n&emsp;&emsp;N\u00e3o gostava muito da ideia de usar o jaleco de outras pessoas, mas o dele estava no laborat\u00f3rio do professor Hofstader, ent\u00e3o, \u00e0 contragosto, vestiu o primeiro que parecia servir nele e logo voltou para perto de %Reyna%, puxando uma banqueta e se sentando ao lado dela.<br>\n&emsp;&emsp;%Bennington% examinava amostras no microsc\u00f3pio e parou por alguns segundos para fazer algumas anota\u00e7\u00f5es num caderno posto ao lado. Ao terminar, largou a caneta na bancada e voltou seu olhar para Peter.<br>\n&emsp;&emsp;Os olhos dela eram t\u00e3o negros que pareciam refletir as luzes do laborat\u00f3rio e por alguns segundos ele se viu completamente perdido os encarando.<br>\n&emsp;&emsp;\u2014 E ent\u00e3o? \u2014 A voz de %Reyna% o fez despertar de seus pensamentos.<br>\n&emsp;&emsp;\u2014 O qu\u00ea? \u2014 N\u00e3o quis soar totalmente atordoado, mas foi imposs\u00edvel disfar\u00e7ar, afinal, ele estava a encarando fixamente sabe-se l\u00e1 por quanto tempo.<br>\n&emsp;&emsp;\u2014 O que quer conversar, Peter Parker? \u2014 Um pequeno sorriso se formou nos l\u00e1bios de %Rey%, enquanto, mais uma vez, ela o achava ador\u00e1vel.<br>\n&emsp;&emsp;\u2014 Acho que, para come\u00e7ar, voc\u00ea n\u00e3o precisa ficar me chamando pelo nome completo, sabe? Peter j\u00e1 est\u00e1 \u00f3timo. \u2014 Tentou soar o mais descontra\u00eddo poss\u00edvel. Alguma coisa nela o deixava nervoso e ele se sentia como um adolescente de novo.<br>\n&emsp;&emsp;\u2014 Tudo bem, <em>Peter<\/em>. O que quer conversar? \u2014 %Bennington% tinha bastante coisa para fazer no laborat\u00f3rio naquele dia, mas n\u00e3o se importou. Parker podia levar o tempo que quisesse ali.<br>\n&emsp;&emsp;Ela s\u00f3 precisava lembrar que havia levado um fora \u00e9pico dele. N\u00e3o podia se permitir ser completamente pat\u00e9tica de novo.<br>\n&emsp;&emsp;\u2014 Ent\u00e3o\u2026 Eu vim me desculpar. \u2014 %Reyna% o olhou surpresa e estava pronta para dizer algo, por\u00e9m Peter prosseguiu antes que o nervosismo levasse a melhor. \u2014 Acho que n\u00e3o foi nada legal o que aconteceu no outro dia. Quer dizer, voc\u00ea estava sendo legal e eu n\u00e3o fui. Eu sinto muito, %Reyna%.<br>\n&emsp;&emsp;%Bennington% simplesmente n\u00e3o conseguia acreditar que Parker havia ido at\u00e9 ali s\u00f3 para fazer aquilo. Ele n\u00e3o tinha obriga\u00e7\u00e3o alguma de se desculpar ou justificar qualquer coisa, afinal, eles nem se conheciam. No entanto, ali estava ele.<br>\n&emsp;&emsp;E ela n\u00e3o conseguiu segurar o sorriso delicado que surgiu em seu rosto, algo que n\u00e3o passou despercebido por Peter. Ele n\u00e3o sabia qual rea\u00e7\u00e3o esperar dela, mas n\u00e3o imaginava que %Reyna% fosse sorrir daquele jeito t\u00e3o\u2026 doce.<br>\n&emsp;&emsp;\u2014 Peter, voc\u00ea n\u00e3o precisa me pedir desculpas. Eu que fui totalmente maluca de chegar chamando voc\u00ea pra sair. Afinal de contas, n\u00f3s nem nos conhecemos. \u2014 A voz dela oscilou na \u00faltima frase, deixando em evid\u00eancia que se sentia envergonhada, e Parker negou com a cabe\u00e7a.<br>\n&emsp;&emsp;\u2014 Acho que n\u00e3o tem problema nenhum nisso. As pessoas n\u00e3o saem para se conhecerem?<br>\n&emsp;&emsp;\u2014 Ainda assim\u2026<br>\n&emsp;&emsp;\u2014 Que tal se a gente come\u00e7ar de novo? \u2014 De repente, ele estendeu a m\u00e3o para ela. \u2014 Prazer, eu sou o Peter Parker.<br>\n&emsp;&emsp;%Reyna% riu daquilo e tirou uma das luvas de l\u00e1tex para segurar a m\u00e3o dele de volta.<br>\n&emsp;&emsp;\u2014 %Reyna% %Bennington%. Mas voc\u00ea pode me chamar de %Rey%. \u2014 Parker sorriu para ela, que retribuiu.<br>\n&emsp;&emsp;Um sil\u00eancio tomou conta do ambiente e os dois ficaram se encarando por alguns segundos. Ele imaginando que seria expulso do laborat\u00f3rio a qualquer segundo. Ela esperando pelo momento em que o rapaz levantaria e sairia correndo. Tinha consci\u00eancia de que n\u00e3o era l\u00e1 t\u00e3o soci\u00e1vel, a prova daquilo era estar ali sozinha naquele momento.<br>\n&emsp;&emsp;\u2014 Me desculpe por ter sa\u00eddo daquele jeito, ali\u00e1s.<br>\n&emsp;&emsp;\u2014 Ent\u00e3o, sobre o que \u00e9 a sua pesquisa?<br>\n&emsp;&emsp;Os dois haviam falado ao mesmo tempo e aquilo arrancou mais algumas risadas t\u00edmidas de ambos.<br>\n&emsp;&emsp;\u2014 Eu teria feito a mesma coisa \u2014 Peter falou primeiro, porque certamente sua resposta seria mais breve. \u2014 Mas nem lembro mais do que voc\u00ea t\u00e1 falando, de qualquer forma. \u2014 Acrescentou, franzindo o cenho como se estivesse realmente tentando lembrar.<br>\n&emsp;&emsp;Aquilo fez %Reyna% rir mais uma vez. Parker realmente era ador\u00e1vel demais para a sanidade dela.<br>\n&emsp;&emsp;\u2014 Bom, a minha tese \u00e9 voltada para o melhoramento gen\u00e9tico de plantas. Mais especificamente a hibridiza\u00e7\u00e3o entre esp\u00e9cies. \u2014 Sabia que Peter entendia do que ela estava falando, porque ele n\u00e3o pareceu nem um pouco confuso com as palavras que usava. \u2014 Comecei com cruzamentos planta com planta, depois plantas com fungos e agora plantas com bact\u00e9rias e cianobact\u00e9rias. A ideia \u00e9 ir evoluindo at\u00e9\u2026<br>\n&emsp;&emsp;\u2014 At\u00e9 fazer um h\u00edbrido de planta e ser humano? \u2014 Parker arqueou uma sobrancelha, surpreso e ao mesmo tempo tendo uma esp\u00e9cie de d\u00e9j\u00e0 vu. A conversa era muito parecida com os trabalhos de seu pai e do Doutor Connors.<br>\n&emsp;&emsp;\u2014 Exatamente. Mas a ideia n\u00e3o \u00e9 beneficiar o ser humano com isso, Peter. \u00c9 tentar reverter um pouco do dano que n\u00f3s j\u00e1 fizemos ao meio ambiente. Sei que parece algo completamente maluco, mas\u2026<br>\n&emsp;&emsp;\u2014 Sim, realmente \u00e9 meio louco. \u2014 Ele foi sincero, fazendo uma careta se formar no rosto de %Bennington%.<br>\n&emsp;&emsp;\u2014 Pode ficar tranquilo. N\u00e3o quero transformar a popula\u00e7\u00e3o do mundo inteiro em \u00e1rvores \u2014 %Rey% brincou, com uma risada envergonhada. \u2014 O estudo ainda vai levar anos para chegar ao est\u00e1gio humano. Mas algu\u00e9m precisa come\u00e7ar, n\u00e3o \u00e9? E imagina o qu\u00e3o incr\u00edvel seria um indiv\u00edduo fitocin\u00e9tico. \u2014 Os olhos dela brilharam.<br>\n&emsp;&emsp;Parker assentiu, embora ainda tentasse assimilar tudo aquilo.<br>\n&emsp;&emsp;No entanto, n\u00e3o podia negar que a ambi\u00e7\u00e3o de %Reyna% era admir\u00e1vel.<br>\n&emsp;&emsp;\u2014 Ent\u00e3o, al\u00e9m de inteligente e divertida, voc\u00ea \u00e9 bastante ambiciosa. \u2014 Sem que conseguisse se controlar, de repente os elogios haviam escapado de sua boca.<br>\n&emsp;&emsp;Sentindo algo engra\u00e7ado no est\u00f4mago, %Bennington% desviou seu olhar para as pr\u00f3prias m\u00e3os, depois tornou a encarar Parker, precisando de um certo esfor\u00e7o para recuperar a pr\u00f3pria voz. Ele realmente a deixava nervosa.<br>\n&emsp;&emsp;\u2014 Obrigada, Peter. Voc\u00ea tamb\u00e9m \u00e9 inteligente e divertido. S\u00f3 n\u00e3o sei da ambi\u00e7\u00e3o ainda. \u2014 Abriu um pequeno sorriso, que ele retribuiu de imediato.<br>\n&emsp;&emsp;Parker n\u00e3o esperava que ela fosse elogi\u00e1-lo de volta, mas havia gostado de ouvir.<br>\n&emsp;&emsp;Mais uma vez, o sil\u00eancio tomou conta do ambiente e mesmo que a ideia de recome\u00e7ar tivesse partido dele, de repente ali estava novamente a necessidade de se desculpar.<br>\n&emsp;&emsp;\u2014 Eu realmente sinto muito por aquele fora, %Rey%. \u00c9 bem clich\u00ea o que eu vou dizer, mas n\u00e3o \u00e9 voc\u00ea\u2026 sou eu. \u2014 E riu do quanto aquilo soava idiota.<br>\n&emsp;&emsp;\u2014 N\u00e3o se preocupe, Peter. Eu entendo. De verdade. \u2014 Sorriu mais uma vez daquele jeito que Parker havia achado doce. \u2014 Mas n\u00f3s falamos em recome\u00e7o, certo?<br>\n&emsp;&emsp;\u2014 Certo. \u2014 Ele assentiu, acompanhando com curiosidade quando %Reyna% desviou sua aten\u00e7\u00e3o dele para pegar a caneta na bancada e anotar alguma coisa em uma folha em branco de seu caderno.<br>\n&emsp;&emsp;Quando ela arrancou o papel e estendeu em sua dire\u00e7\u00e3o, ficou claro do que se tratava.<br>\n&emsp;&emsp;\u2014 \u00c9 o meu n\u00famero. \u2014 %Bennington% n\u00e3o precisava dizer, mas mesmo assim o fez. \u2014 Se voc\u00ea quiser uma amiga ou apenas algu\u00e9m para conversar, me manda uma mensagem, ou me liga. Voc\u00ea \u00e9 legal demais para ficar andando por a\u00ed sozinho, Peter.<br>\n&emsp;&emsp;Parker sorriu com aquilo e aceitou o papel.<br>\n&emsp;&emsp;\u2014 Como sabe que eu ando sozinho, %Bennington%? \u2014 Ergueu uma sobrancelha.<br>\n&emsp;&emsp;\u2014 Foi um palpite e voc\u00ea acabou de confirmar. \u2014 Seus l\u00e1bios se curvaram em um sorriso esperto.<br>\n&emsp;&emsp;Peter sentia que poderia continuar ali por horas conversando com ela, mesmo que em alguns momentos ambos ficassem sem saber o que dizer. No entanto, %Reyna% estava trabalhando e ele tamb\u00e9m.<br>\n&emsp;&emsp;<em>Ele tamb\u00e9m<\/em>.<br>\n&emsp;&emsp;De repente, Parker olhou para o rel\u00f3gio em seu pulso, percebendo que faltavam dois minutos para o fim de seu intervalo.<br>\n&emsp;&emsp;Voltou a encarar %Bennington% e ela poderia rir novamente apenas com aquela express\u00e3o atordoada dele. De novo, ador\u00e1vel demais para o bem dela.<br>\n&emsp;&emsp;\u2014 Deixa eu adivinhar. Voc\u00ea precisa ir \u2014 %Reyna% se pronunciou antes que ele o fizesse.<br>\n&emsp;&emsp;\u2014 O restante do meu intervalo voou. Vou te deixar voltar ao seu trabalho tamb\u00e9m. \u2014 Riu sem jeito e de repente ela sentiu uma certa anima\u00e7\u00e3o em saber que Parker havia se perdido no tempo ali com ela.<br>\n&emsp;&emsp;\u2014 Bom saber que gostou da nossa conversa. \u2014 Tombou levemente a cabe\u00e7a de lado e Peter sorriu.<br>\n&emsp;&emsp;\u2014 N\u00e3o imagino como eu n\u00e3o gostaria. \u2014 Foi sincero. \u2014 A gente se v\u00ea, %Rey%. Nada de transformar as pessoas em \u00e1rvores.<br>\n&emsp;&emsp;Talvez aquela brincadeira fosse idiota demais, mas havia sido mais forte do que ele.<br>\n&emsp;&emsp;\u2014 Pode deixar. A gente se v\u00ea, Peter.<br>\n&emsp;&emsp;%Reyna% o assistiu seguir at\u00e9 a porta e dar uma \u00faltima olhada para ela, sorrindo antes de sair do laborat\u00f3rio.<br>\n&emsp;&emsp;Pelo restante do dia, a sensa\u00e7\u00e3o de anima\u00e7\u00e3o continuou ali e vez ou outra %Rey% se pegava sorrindo para absolutamente nada.<br>\n&emsp;&emsp;Ter dado seu n\u00famero a ele provavelmente havia sido um erro fatal.<\/p>\n\n<p align=\"center\">\ud83d\udd77<\/p>\n\n<p>&emsp;&emsp;Ficar atento ao movimento policial naquela noite n\u00e3o foi o suficiente para Peter. Ele tinha experi\u00eancia o bastante para duvidar que qualquer viatura conseguiria chegar a tempo caso Dahlia Negra atacasse mais uma vez.<br>\n&emsp;&emsp;N\u00e3o \u00e9 que n\u00e3o confiava na pol\u00edcia ou os achava incapazes de proteger a popula\u00e7\u00e3o, mas Parker havia de fato dado de cara com o vigilante e comprovado que sua agilidade n\u00e3o era comum.<br>\n&emsp;&emsp;E n\u00e3o saber exatamente com o que estava lidando s\u00f3 aumentava ainda mais sua vontade de encontr\u00e1-lo.<br>\n&emsp;&emsp;O Homem Aranha estaria preparado, n\u00e3o permitiria que escapasse at\u00e9 obter as respostas que procurava.<br>\n&emsp;&emsp;Analisando todos os ataques anteriores, Peter sabia que a regi\u00e3o do Brooklyn era a de principal atua\u00e7\u00e3o do Dahlia Negra e foi se atendo \u00e0quela informa\u00e7\u00e3o que ele se escondeu na escurid\u00e3o do pr\u00e9dio mais alto, observando com aten\u00e7\u00e3o qualquer movimenta\u00e7\u00e3o suspeita.<br>\n&emsp;&emsp;As ruas estavam praticamente desertas, exatamente como nos dias anteriores. Vez ou outra, alguma pessoa ou cachorro de rua passava, por\u00e9m nada de surpreendente aconteceu. Estavam todos em alerta. Cinco ataques haviam acontecido e mesmo que os alvos fossem criminosos, ningu\u00e9m queria arriscar.<br>\n&emsp;&emsp;Sentado no parapeito, Parker deixou um suspiro escapar. Na \u00faltima vez em que ficou daquela forma, cuidado de algo, na verdade havia sido de <em>algu\u00e9m<\/em>.<br>\n&emsp;&emsp;Teve tanta esperan\u00e7a de que suas a\u00e7\u00f5es no outro universo fossem mudar o que tinha acontecido. Por que estava tudo igual?<br>\n&emsp;&emsp;N\u00e3o havia um dia sequer que ele n\u00e3o sentisse falta dela. Da sua Gwen. E j\u00e1 tinha se conformado com o fato de que aquilo nunca mudaria porque Peter nunca esqueceria dela.<br>\n&emsp;&emsp;Por algum motivo, seus pensamentos foram guiados para %Reyna% %Bennington%. Seria justo ele conhecer uma outra mulher? Seria justo com %Reyna% traz\u00ea-la para toda a sua realidade bagun\u00e7ada e cheia de perigos?<br>\n&emsp;&emsp;Por outro lado, Parker estava cansado de ficar sozinho. Estava cansado de lutar contra vil\u00f5es e monstros durante o dia e com seus pr\u00f3prios dem\u00f4nios durante a noite.<br>\n&emsp;&emsp;Talvez n\u00e3o fosse t\u00e3o ruim ao menos ter algu\u00e9m com quem conversar.<br>\n&emsp;&emsp;Deixando um sorriso fraco se formar em seus l\u00e1bios, ele puxou seu celular e procurou o n\u00famero de %Reyna% na lista de contatos. Havia o salvado no instante em que saiu do laborat\u00f3rio, em um impulso por ter realmente gostado da breve conversa que tiveram.<br>\n&emsp;&emsp;O que diria pra ela?<br>\n&emsp;&emsp;Um \u201coi\u201d j\u00e1 era um come\u00e7o?<br>\n&emsp;&emsp;Droga, ele havia perdido completamente o jeito com aquelas coisas.<br>\n&emsp;&emsp;Se \u00e9 que j\u00e1 teve jeito algum dia.<br>\n&emsp;&emsp;Riu de si mesmo e parou para pensar em algo mais elaborado. Por fim, at\u00e9 achou razo\u00e1vel a mensagem que digitou, enviando antes que perdesse a coragem ou refletisse demais sobre o que escreveu.<br>\n\n<p align=\"center\"><em>%Reyna% %Bennington%<br>\nvisto por \u00faltimo hoje \u00e0s 23:35<\/em><\/p>\n\n<p align=\"center\"><em>Conferindo se esse \u00e9 o seu n\u00famero mesmo ou se voc\u00ea resolveu se vingar me dando qualquer outro.<br>\nx Peter Parker.<\/em><\/p>\n\n<p>&emsp;&emsp;%Reyna% havia dito que o achou divertido, mesmo que fosse apenas uma resposta ao elogio dele, ent\u00e3o talvez fosse gostar da mensagem, certo?<br>\n&emsp;&emsp;Parker batucou os dedos na parte traseira do aparelho, ficando um tanto ansioso para saber o que %Bennington% responderia. Ent\u00e3o na segunda vez que acendeu o visor, conferindo se havia alguma notifica\u00e7\u00e3o de mensagem, seus olhos se fixaram no hor\u00e1rio, que marcava exatamente duas e trinta e sete da manh\u00e3.<br>\n&emsp;&emsp;Bateu na pr\u00f3pria testa, se sentindo um completo idiota. Tinha mesmo mandado mensagem para ela de madrugada? Com certeza %Reyna% estaria dormindo.<br>\n&emsp;&emsp;Ainda assim, ele n\u00e3o deixou de conferir o celular de vez em quando, dividindo sua aten\u00e7\u00e3o com a movimenta\u00e7\u00e3o da cidade.<br>\n&emsp;&emsp;Eram quase quatro horas da manh\u00e3 quando Peter decidiu voltar para casa e descansar um pouco. No dia seguinte, ele voltaria a analisar os ataques anteriores do Dahlia Negra para retomar o plano de tentar prever suas pr\u00f3ximas v\u00edtimas.<br>\n&emsp;&emsp;Aquela foi uma das raras noites em que Parker se jogou em sua cama e adormeceu instantaneamente.<\/p>\n\n<p>&emsp;&emsp;<em>\u2014 Peter! \u2014 Mais uma vez, ele estava de volta \u00e0quele momento terr\u00edvel.<\/em><br>\n&emsp;&emsp;<em>As risadas de Harry Osborn pareciam vir de todos os lugares, mas o mundo simplesmente parou quando Parker olhou para baixo e viu que Gwen despencava.<\/em><br>\n&emsp;&emsp;<em>Mas ele conseguiria peg\u00e1-la. Sua teia havia sido desenvolvida para aquilo. Gwen estaria a salvo em poucos segundos.<\/em><br>\n&emsp;&emsp;<em>No entanto, tudo passou em c\u00e2mera lenta diante de seus olhos. Peter estendeu o pulso, lan\u00e7ando a teia em dire\u00e7\u00e3o ao amor de sua vida, se jogando tamb\u00e9m em dire\u00e7\u00e3o a ela para que pudesse agarr\u00e1-la antes que atingisse o solo.<\/em><br>\n&emsp;&emsp;<em>Os olhos de Gwen estavam fixos nos dele, apavorados, suplicantes, marejados. Ele jamais esqueceria daquela imagem.<\/em><br>\n&emsp;&emsp;<em>Por que o mundo havia desacelerado? Parker precisava ser mais r\u00e1pido, ele <strong>seria<\/strong> mais r\u00e1pido.<\/em><br>\n&emsp;&emsp;<em>E por um segundo achou de verdade que havia conseguido. Por um segundo, o al\u00edvio tinha tomado conta de seu peito e Peter poderia dizer a ela que tudo estava bem. Que Gwen estava a salvo.<\/em><br>\n&emsp;&emsp;<em>Mas o corpo dela estava mole como uma boneca, suspenso pela teia.<\/em><br>\n&emsp;&emsp;<em>Parker se agarrou a ela, tentando acord\u00e1-la, tentando acordar tamb\u00e9m a si mesmo daquele pesadelo, mas n\u00e3o conseguia, assim como n\u00e3o conseguiu salv\u00e1-la.<\/em><br>\n&emsp;&emsp;<em>Sua Gwen havia partido e n\u00e3o havia nada que pudesse fazer para t\u00ea-la de volta.<\/em><br>\n&emsp;&emsp;<em>Peter se debateu, implorando de novo para acordar, mas, de repente, tudo come\u00e7ou de novo.<\/em><br>\n&emsp;&emsp;<em>De repente, ele estava mais uma vez no alto, ouvindo a voz de Gwen gritar por ele, as risadas. E mais uma vez o mundo estava desacelerando enquanto o Homem Aranha lan\u00e7ava sua teia e se jogava em dire\u00e7\u00e3o \u00e0 sua amada.<\/em><br>\n&emsp;&emsp;<em>Aquilo era tortura demais.<\/em><br>\n&emsp;&emsp;<em>E como se n\u00e3o bastasse aquele pesadelo se repetindo em um loop, de repente a imagem de Gwen oscilava, assim como todo o cen\u00e1rio ao seu redor.<\/em><br>\n&emsp;&emsp;<em>De repente, n\u00e3o era Gwen Stacy e sim Michelle Jones despencando enquanto o Peter mais jovem n\u00e3o conseguia alcan\u00e7\u00e1-la, mas, de alguma forma, <strong>ele<\/strong> sabia que conseguiria.<\/em><br>\n&emsp;&emsp;<em>Seus sentimentos estavam completamente confusos entre o pesar e o al\u00edvio de alcan\u00e7ar Michelle a tempo.<\/em><br>\n&emsp;&emsp;<em>Os olhos de Parker estavam marejados de l\u00e1grimas, ele afirmava que estava bem e era como se sentisse que algu\u00e9m o acalentava.<\/em><br>\n&emsp;&emsp;<em>Ent\u00e3o o cen\u00e1rio mudou.<\/em><br>\n&emsp;&emsp;<em>Mais uma vez, o Homem Aranha chegava a um ambiente escuro, onde apenas a luz do luar impedia o breu completo.<\/em><br>\n&emsp;&emsp;<em>\u2014 Ei, voc\u00ea! \u2014 gritava, vendo a figura encapuzada segurando algu\u00e9m pelo colarinho.<\/em><br>\n&emsp;&emsp;<em>Dahlia Negra se virou para ele, a cabe\u00e7a tombando rapidamente em curiosidade, para logo em seguida o vigilante largar o corpo sem vida no ch\u00e3o, seguido pela flor que era sua assinatura.<\/em><br>\n&emsp;&emsp;<em>Sabendo que fugiria, Peter se adiantou em sua dire\u00e7\u00e3o, mas algo o impediu de persegui-lo.<\/em><br>\n&emsp;&emsp;<em>Na verdade, n\u00e3o era algo, era <strong>algu\u00e9m<\/strong>.<\/em><br>\n&emsp;&emsp;<em>O corpo jogado no ch\u00e3o era do Doutor Connors.<\/em><\/p>\n\n<p>&emsp;&emsp;Suando como nunca, Parker despertou. Aquele pesadelo foi t\u00e3o v\u00edvido que de repente o Homem Aranha olhou \u00e0 sua volta, como se fosse encontrar o Dahlia Negra em seu quarto e o Doutor Connors morto ao lado de sua cama.<br>\n&emsp;&emsp;Por que havia sonhado com aquilo? Seria um aviso?<br>\n&emsp;&emsp;Seria ele a pr\u00f3xima v\u00edtima do vigilante?<br>\n&emsp;&emsp;Suas m\u00e3os tremiam. Foram emo\u00e7\u00f5es demais, pesadelos demais, e seu cora\u00e7\u00e3o continuava apertado por ter revivido pela mil\u00e9sima vez a morte de Gwen.<br>\n&emsp;&emsp;Peter se sentou na cama, passando a m\u00e3o pelos cabelos, sentindo-os pingando e tentou colocar seus pensamentos em ordem, analisar as coisas que haviam acontecido nos pesadelos.<br>\n&emsp;&emsp;Ent\u00e3o lhe ocorreu uma coisa e de repente ele se sentiu idiota por n\u00e3o ter pensado naquilo antes.<br>\n&emsp;&emsp;O que havia acontecido com o Doutor Connors e com Max ao retornarem curados para o seu universo?<br>\n&emsp;&emsp;Como estaria Harry Osborn?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&emsp;&emsp;A aus\u00eancia de movimento era at\u00edpica naquela regi\u00e3o de New York. Havia passado das oito da noite, deixando a ilumina\u00e7\u00e3o a cargo dos diversos postes, al\u00e9m das luzes provenientes das resid\u00eancias e estabelecimentos comerciais. &emsp;&emsp;Era de se esperar que a agita\u00e7\u00e3o ainda estivesse presente e carros passassem de um lado a outro, no entanto, tudo [&hellip;]<\/p>\n","protected":false},"author":95,"featured_media":0,"parent":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":true,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"historias":[2250],"class_list":["post-7667","capitular","type-capitular","status-publish","format-standard","hentry","historias-dahlia-negra"],"acf":[],"_links":{"self":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular\/7667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular"}],"about":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/types\/capitular"}],"author":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/users\/95"}],"replies":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/comments?post=7667"}],"wp:attachment":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/media?parent=7667"}],"wp:term":[{"taxonomy":"historias","embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/historias?post=7667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}