{"id":5876,"date":"2025-10-20T14:24:36","date_gmt":"2025-10-20T17:24:36","guid":{"rendered":"https:\/\/espacocriativo.net\/acervo\/historia\/historia-sem-nome\/rascunho-automatico\/"},"modified":"2025-10-20T14:35:25","modified_gmt":"2025-10-20T17:35:25","slug":"unico","status":"publish","type":"capitular","link":"https:\/\/espacocriativo.net\/acervo\/historia\/image\/unico\/","title":{"rendered":"Cap\u00edtulo \u00fanico"},"content":{"rendered":"\r\n<p><span class=\"versalete\">\u2003\u2003\u2014 E se a gente<\/span> fizesse um m\u00e9nage? N\u00f3s quatro, o que acham?<br \/>\u2003\u2003A pergunta \u00e9 feita e os quatro amigos se encaram.<br \/>\u2003\u2003Antes de prosseguir, acho que \u00e9 necess\u00e1rio voltar um pouco no tempo, n\u00e3o acham? Ok, vamos l\u00e1&#8230;<\/p>\r\n<p>\u2003\u2003<em>Horas antes&#8230;<\/em><br \/>\u2003\u2003Quatro amigos.<br \/>\u2003\u2003%Kohshi% tem 33 anos, \u00e9 surfista profissional. %Keigo% tem a mesma idade dele e \u00e9 policial, delegado, para ser mais preciso. %Take% \u00e9 o mais novo entre os homens, tem 32 anos e \u00e9 analista de TI. A \u00fanica mulher do grupo \u00e9 a %Ali%, a mais nova, 31 anos e trabalha como chefe de cozinha em um renomado restaurante.<br \/>\u2003\u2003Eles s\u00e3o amigos desde o ensino m\u00e9dio. Os quatro j\u00e1 tiveram in\u00fameros relacionamentos durante a vida, atualmente todos est\u00e3o solteiros, mas os tr\u00eas homens t\u00eam amores secretos. %Ali% j\u00e1 teve, mas desencantou h\u00e1 tempos de seu antigo amor.<br \/>\u2003\u2003Eles sempre saem juntos para colocarem o papo em dia, j\u00e1 que, por terem profiss\u00f5es e agendas bem diferentes, quase n\u00e3o t\u00eam tempo de se ver. A mo\u00e7a chega ao bar onde marcou de se encontrar com os rapazes, que j\u00e1 est\u00e3o sentados \u00e0 mesa, bebendo.<br \/>\u2003\u2003\u2014 Come\u00e7aram sem mim, seus cachaceiros! \u2014 diz ela, assim que se aproxima da mesa dos amigos, recebendo o olhar feliz deles.<br \/>\u2003\u2003\u2014 Demorou, %Ali% \u2014 comenta %Take%, puxando a cadeira vazia ao lado dele.<br \/>\u2003\u2003\u2014 Fiquei presa no restaurante \u2014 explica a mulher, sentando-se.<br \/>\u2003\u2003\u2014 Pedi um <em>drink<\/em> para voc\u00ea \u2014 anuncia %Keigo%, sorrindo para ela.<br \/>\u2003\u2003\u2014 Obrigada, %Keigo%! Voc\u00ea \u00e9 sempre um amorzinho \u2014 diz %Ali% e coloca a bolsa pendurada na cabeceira da cadeira.<br \/>\u2003\u2003\u2014 Ai, que melosos \u2014 zomba %Kohshi%, rindo e %Take% o acompanha.<br \/>\u2003\u2003\u2014 Ranzinza \u2014 %Ali% d\u00e1 de ombros e completa: \u2014 Do que tanto riam antes de eu chegar? \u2014 questiona.<br \/>\u2003\u2003\u2014 Est\u00e1vamos falando do golpe que %Kohshi% levou da prancha hoje \u2014 diz %Take% com o ar divertido.<br \/>\u2003\u2003\u2014 N\u00e3o foi bem assim&#8230; \u2014 defende-se %Kohshi% dando um gole em sua bebida.<br \/>\u2003\u2003\u2014 Foi sim, tem at\u00e9 v\u00eddeo, %Ali% \u2014 desmente %Keigo% tamb\u00e9m rindo.<br \/>\u2003\u2003\u2014 Ah, deixa eu ver! \u2014 ela diz, animada.<br \/>\u2003\u2003\u2014 Melhor n\u00e3o, %Ali%, assim eu vou perder minhas chances \u2014 comenta ele.<br \/>\u2003\u2003\u2014 Que chances? \u2014 indaga %Take%, confuso.<br \/>\u2003\u2003\u2014 De pegar a mais nova eleita melhor chefe de cozinha da cidade! \u2014 %Kohshi% diz com o ar orgulhoso e ergue seu copo. \u2014 Voc\u00ea \u00e9 maravilhosa, meu amor, parab\u00e9ns!<br \/>\u2003\u2003\u2014 Parab\u00e9ns, %Ali%!!! \u2014 %Take% e %Keigo% tamb\u00e9m erguem seus copos num brinde, %Ali% fica vermelha de vergonha, mas sorri agradecida.<br \/>\u2003\u2003\u2014 Obrigada, gente \u2014 ela diz. \u2014 Foi uma surpresa, na verdade&#8230;<br \/>\u2003\u2003\u2014 Surpresa para quem? \u2014 diz %Keigo%, retoricamente.<br \/>\u2003\u2003\u2014 \u00c9, %Ali%, voc\u00ea \u00e9 incr\u00edvel na cozinha. N\u00e3o se subjugue! \u2014 concorda %Kohshi%.<br \/>\u2003\u2003\u2014 Ali\u00e1s&#8230; voc\u00ea est\u00e1 nos devendo um jantar \u2014 lembra %Take% e recebe o olhar entediado da amiga.<br \/>\u2003\u2003\u2014 L\u00e1 vem voc\u00ea me cobrar de novo, %Take%! \u2014 reclama ela.<br \/>\u2003\u2003\u2014 Ele tem raz\u00e3o, %Ali%. J\u00e1 faz mais de cinco meses que nos prometeu esse jantar \u2014 defende %Keigo%.<br \/>\u2003\u2003\u2014 E voc\u00ea s\u00f3 nos enrola, mocinha \u2014 %Kohshi% completa a reclama\u00e7\u00e3o e %Ali% revira o olhar.<br \/>\u2003\u2003\u2014 Voc\u00eas s\u00e3o uns exploradores! J\u00e1 n\u00e3o basta irem toda semana no restaurante e comer de gra\u00e7a, ainda querem jantar?<br \/>\u2003\u2003\u2014 Mas queremos que voc\u00ea jante conosco \u2014 diz %Kohshi%.<br \/>\u2003\u2003\u2014 Todos n\u00f3s \u2014 %Keigo% aponta para si mesmo e para os amigos.<br \/>\u2003\u2003\u2014 Sim, %Ali%, voc\u00ea \u00e9 nossa chefe preferida \u2014 %Take% faz uma express\u00e3o fofa e %Ali% n\u00e3o aguenta.<br \/>\u2003\u2003\u2014 Idiotas \u2014 ela ri, balan\u00e7ando a cabe\u00e7a negativamente. \u2014 Est\u00e1 bem, vamos marcar um dia.<br \/>\u2003\u2003\u2014 Vai marcar mesmo, n\u00e9? Da \u00faltima vez voc\u00ea, nos enrolou.<br \/>\u2003\u2003\u2014 Vou sim, %Keigo%&#8230;<br \/>\u2003\u2003\u2014 Ok \u2014 ele concorda e bebe mais um pouco de sua bebida.<br \/>\u2003\u2003Nessa hora, o gar\u00e7om chega com o <em>drink <\/em>de %Ali% e os quatro brindam novamente a conquista da mais nova. Algumas horas se passam e o \u00e1lcool j\u00e1 faz efeito em todos. Os tr\u00eas homens trocam olhares significativos durante toda a conversa, antes de sa\u00edrem para o estacionamento, %Keigo% lan\u00e7a um olhar penetrante em %Take%. %Kohshi% faz o mesmo.<br \/>\u2003\u2003\u2014 Voc\u00eas est\u00e3o estranhos \u2014 comenta %Ali%, arqueando a sobrancelha, desconfiada e virando-se para encar\u00e1-los. \u2014 Digam logo o que voc\u00eas querem \u2014 determina ela.<br \/>\u2003\u2003\u2014 Odeio voc\u00ea e sua capacidade de ler a gente, que droga, %Ali%! \u2014 reclama %Take%, nervoso.<br \/>\u2003\u2003\u2014 Pois \u00e9&#8230; \u2014 dizem %Kohshi% e %Keigo%, fora de ordem.<br \/>\u2003\u2003\u2014 Bom&#8230;<br \/>\u2003\u2003\u2014 Fala, %Take%!<br \/>\u2003\u2003O rapaz \u00e9 o escolhido para dar a not\u00edcia. Na verdade, para fazer a proposta para %Ali%.<br \/>\u2003\u2003\u2014 Antes de perguntar o que realmente irei perguntar, posso te fazer outra pergunta? \u2014 ele diz, encarando a amiga.<br \/>\u2003\u2003\u2014 Fala de uma vez, pelo amor de Deus \u2014 briga ela.<br \/>\u2003\u2003\u2014 Ok, l\u00e1 vai: voc\u00ea gosta de m\u00e9nage, %Ali%? \u2014 a mo\u00e7a arregala o olhar e quase se engasga com o <em>drink<\/em>.<br \/>\u2003\u2003\u2014 Que?<br \/>\u2003\u2003\u2014 Voc\u00ea est\u00e1 bem? \u2014 indaga %Kohshi%, preocupado.<br \/>\u2003\u2003\u2014 Estou, mas que porra de pergunta \u00e9 essa, %Take%?! \u2014 ela diz e completa: \u2014 E voc\u00eas tamb\u00e9m querem saber disso? Meu Deus&#8230;<br \/>\u2003\u2003\u2014 S\u00f3 responde a pergunta, %Ali% \u2014 instiga %Keigo%.<br \/>\u2003\u2003\u2014 Nunca fiz, voc\u00eas sabem&#8230;<br \/>\u2003\u2003\u2014 N\u00e3o, n\u00e3o sabemos \u2014 apressa-se %Kohshi%.<br \/>\u2003\u2003\u2014 E como saber\u00edamos com quem voc\u00ea anda transando? \u2014 completa %Keigo%. %Take% e %Kohshi% apenas concordam com a cabe\u00e7a de maneira \u00f3bvia.<br \/>\u2003\u2003\u2014 Ok, voc\u00ea nunca fez, mas faria? \u2014 insiste %Take% e recebe o olhar de %Ali%.<br \/>\u2003\u2003\u2014 Eu n\u00e3o sei&#8230; depende \u2014 hesita ela.<br \/>\u2003\u2003\u2014 De qu\u00ea? \u2014 pergunta %Kohshi%, curioso. Agora, os tr\u00eas encaram a amiga de maneira instigante, o que a deixa acuada.<br \/>\u2003\u2003\u2014 Ai, me deixem voc\u00eas tr\u00eas! \u2014 brada ela. \u2014 Por que querem saber?<br \/>\u2003\u2003\u2014 Bom, \u00e9 uma vontade nossa em fazer, tamb\u00e9m nunca fizemos e, sei l\u00e1&#8230; \u2014 inicia %Keigo%.<br \/>\u2003\u2003\u2014 Seria legal se fosse com algu\u00e9m conhecido, n\u00e9? \u2014 diz %Kohshi%, completando a fala do amigo.<br \/>\u2003\u2003<em>\u2014 E se a gente fizesse um m\u00e9nage? N\u00f3s quatro, o que acham?<\/em><br \/>\u2003\u2003%Take% finalmente faz a proposta.<br \/>\u2003\u2003Os quatro amigos se encaram. %Ali%, sem falar nada, apenas pega sua bolsa e sai andando at\u00e9 a sa\u00edda do bar. Os outros pagam a conta e seguem a amiga at\u00e9 o carro de %Kohshi%. Todos embarcam no ve\u00edculo e seguem at\u00e9 o apartamento da mais nova, eles ficam calados todo o caminho. %Kohshi% dirige, %Keigo% o acompanha no banco do carona, %Take% e %Ali% no banco detr\u00e1s.<br \/>\u2003\u2003Quando chegam em frente ao pr\u00e9dio de %Ali%, antes de descer do carro, a mo\u00e7a fala, finalmente.<br \/>\u2003\u2003\u2014 Sobre aquilo&#8230; \u2014 inicia ela. \u2014 Eu topo.<br \/>\u2003\u2003A mo\u00e7a abre a porta do carro e sai, fechando-a em seguida. Os tr\u00eas amigos ficam mais um pouco ali e respiram aliviados. Finalmente eles poder\u00e3o realizar a fantasia sexual deles. Mas, para um dos tr\u00eas, ser\u00e1 mais que uma fantasia realizada.<\/p>\r\n<p align=\"center\">[\ud83d\udd25]<\/p>\r\n<p>\u2003\u2003%Ali% se pergunta se realmente estava em seu estado normal quando aceitou fazer m\u00e9nage com seus amigos. Agora, ela arruma seu apartamento para receb\u00ea-los em algumas horas. Alguns dias se passam desde \u00e0 sa\u00edda ao bar em que fizeram a proposta do ato. Desde ent\u00e3o, eles conversam sobre os detalhes da brincadeira. Acima de tudo, eles querem que seja algo respeitoso, pois n\u00e3o querem que a amizade acabe depois ou que fique estranho se verem ou se abra\u00e7arem ap\u00f3s essa noite. Os pensamentos de cada um s\u00e3o bem diversos durante esses dias. %Kohshi% \u00e9 o que mais quer ter rela\u00e7\u00f5es \u00edntimas com %Ali%, a curiosidade dele vem de muito antes. %Keigo% est\u00e1 ansioso, por ser um rapaz rom\u00e2ntico, ele quer que seja al\u00e9m de prazeroso, que tenha algo de meigo e carinhoso tamb\u00e9m. %Take% nunca desejou sexualmente %Ali%, mas, n\u00e3o deixa de achar a amiga uma grande e linda mulher. J\u00e1 a mulher desse m\u00e9nage est\u00e1 nervosa, por\u00e9m controlada em suas emo\u00e7\u00f5es. Ela n\u00e3o tem nenhum interesse amoroso por nenhum dos tr\u00eas, ela os v\u00ea como amigos, realmente. Mas, confessa que possa ser dif\u00edcil encar\u00e1-los mais tarde quando todos estiverem nus no mesmo ambiente.<br \/>\u2003\u2003A inseguran\u00e7a da jovem nesse sentido \u00e9 facilmente resolvida com o fato dela ceder seu apartamento para o ato acontecer. %Ali% acha que se sentir\u00e1 mais confort\u00e1vel estando, literalmente, em casa do que em um motel ou na casa de algum dos rapazes.<br \/>\u2003\u2003O hor\u00e1rio combinado chega, s\u00e3o exatamente 8PM e apenas o %Kohshi% havia chegado. Eles est\u00e3o conversando enquanto aguardam os demais. De repente, a campainha toca.<br \/>\u2003\u2003\u2014 Deve ser o %Take% \u2014 comenta %Kohshi% e v\u00ea %Ali% levantar do sof\u00e1 para atender a porta.<br \/>\u2003\u2003\u2014 Boa noite \u2014 diz %Take% assim que se torna vis\u00edvel na porta e adentra ao apartamento. \u2014 %Keigo% pediu para avisar que vai se atrasar \u2014 avisa ele enquanto retira os sapatos.<br \/>\u2003\u2003\u2014 Justo ele vai se atrasar! \u2014 diz %Ali% em tom irritado. \u2014 Pois ele vai ver s\u00f3 uma coisa quando ele chegar \u2014 completa a mo\u00e7a, fechando a porta e caminhando sala a dentro.<br \/>\u2003\u2003\u2014 Ih, t\u00e1 brava \u2014 brinca %Take%, risonho.<br \/>\u2003\u2003\u2014 Ele deve ter tido alguma emerg\u00eancia na delegacia \u2014 sup\u00f5e %Kohshi% comendo mais um salgado feito por %Ali%.<br \/>\u2003\u2003\u2014 Um dia importante como esse, ele n\u00e3o deveria atrasar \u2014 ela diz e senta-se de volta no sof\u00e1. \u2014 E ele era o mais animado.<br \/>\u2003\u2003\u2014 Sim \u2014 concorda %Kohshi%.<br \/>\u2003\u2003\u2014 Dia importante \u00e9? \u2014 indaga %Take% com o olhar suspenso e risonho. \u2014 Hm&#8230;<br \/>\u2003\u2003\u2014 Cala a boca, %Take% \u2014 ela diz e os rapazes riem.<br \/>\u2003\u2003E a campainha toca novamente.<br \/>\u2003\u2003\u2014 Deve ser o %Keigo% \u2014 sup\u00f5e %Kohshi% novamente.<br \/>\u2003\u2003\u2014 Se n\u00e3o for ele, eu juro que vou at\u00e9 a delegacia dar nele \u2014 amea\u00e7a %Ali%.<br \/>\u2003\u2003\u2014 Se voc\u00ea <em>der<\/em> para ele, capaz dele gostar \u2014 diz %Take%, rindo. %Kohshi% o acompanha.<br \/>\u2003\u2003\u2014 %Take%! Eu quis dizer dar <em>na cara dele<\/em>, meu Deus, que pervertido \u2014 briga a mo\u00e7a, mas acaba rindo.<br \/>\u2003\u2003\u2014 Estou entrando no clima, beb\u00ea \u2014 ela pisca para ela, que balan\u00e7a a cabe\u00e7a negativamente, abrindo a porta em seguida.<br \/>\u2003\u2003\u2014 Me desculpe o atraso \u2014 %Keigo% j\u00e1 diz assim que v\u00ea a fei\u00e7\u00e3o brava de %Ali%. \u2014 N\u00e3o precisa \u201cdar na minha cara\u201d, eu j\u00e1 cheguei.<br \/>\u2003\u2003\u2014 HA HA HA, que engra\u00e7ado voc\u00ea, <em>delegado<\/em> \u2014 brinca ela. \u2014 Ouvindo atr\u00e1s da porta? Isso \u00e9 crime, sabia?<br \/>\u2003\u2003\u2014 Teoricamente, n\u00e3o \u00e9 crime \u2014 explica. \u2014 Se eu tivesse <em>gravando<\/em> para mostrar a algu\u00e9m sem autoriza\u00e7\u00e3o, a\u00ed sim seria crime. Ou, quem sabe, usasse o que escutei contra voc\u00eas \u2014 ele conclui o pensamento e entra pela sala. %Ali% revira o olhar.<br \/>\u2003\u2003\u2014 Falou o senhor perfeitinho \u2014 zomba %Kohshi%.<br \/>\u2003\u2003\u2014 <em>Nerd<\/em> \u2014 %Take% continua a zombaria.<br \/>\u2003\u2003\u2014 %Keigo%, esque\u00e7a, pelo menos por hoje, que voc\u00ea \u00e9 policial, est\u00e1 bem? \u2014 pede %Ali% e o homem ri.<br \/>\u2003\u2003\u2014 Pedindo com educa\u00e7\u00e3o eu posso pensar no seu caso \u2014 ele deixa seu distintivo e sua arma na mesinha que h\u00e1 pr\u00f3xima \u00e0 porta.<br \/>\u2003\u2003\u2014 Est\u00e1 descarregada? \u2014 indaga %Ali%.<br \/>\u2003\u2003\u2014 Para que quer saber?<br \/>\u2003\u2003\u2014 Sei l\u00e1, tenho medo dessas coisas \u2014 ela aponta para a arma e %Keigo% ri.<br \/>\u2003\u2003\u2014 Est\u00e1 com a trava acionada, mas est\u00e1 carregada sim \u2014 explica e p\u00f5e sua carteira junto com o distintivo.<br \/>\u2003\u2003\u2014 Est\u00e1 pensando em usar a arma do %Keigo% para o nosso <em>jogo<\/em> mais tarde? \u2014 questiona %Kohshi% com os olhos arregalados.<br \/>\u2003\u2003\u2014 Se for usar alguma coisa de mim, que seu o meu pau \u2014 diz %Keigo%, sentando-se no sof\u00e1.<br \/>\u2003\u2003\u2014 Ahhhhh eu n\u00e3o acredito!! \u2014 espanta-se %Take%, rindo bastante.<br \/>\u2003\u2003\u2014 Porra, %Keigo%, virei seu f\u00e3 agora! \u2014 exalta %Kohshi%.<br \/>\u2003\u2003\u2014 Que baixaria, %Keigo%! \u2014 diz %Ali% com o rosto vermelho de vergonha. \u2014 Vou me lembrar disso mais tarde \u2014 ela diz.<br \/>\u2003\u2003\u2014 Aaaaaa \u2014 %Kohshi% e %Take% gritam, ainda rindo.<br \/>\u2003\u2003\u2014 Essa foda vai ser muito boa \u2014 diz %Keigo% encarando a amiga.<br \/>\u2003\u2003\u2014 S\u00f3 pensa em sacanagem \u2014 comenta %Ali%, sentando-se ao lado de %Take% no sof\u00e1.<br \/>\u2003\u2003\u2014 Acho que a gente j\u00e1 pode come\u00e7ar, j\u00e1 que todos chegaram \u2014 prop\u00f5e %Take%, animado.<br \/>\u2003\u2003\u2014 %Keigo% tem que tomar banho, n\u00e3o? \u2014 indaga %Kohshi%.<br \/>\u2003\u2003\u2014 Eu tomei banho \u2014 diz o rapaz.<br \/>\u2003\u2003\u2014 Aonde?<br \/>\u2003\u2003\u2014 Na delegacia \u2014 explica.<br \/>\u2003\u2003\u2014 Ah, nem sabia que tinha chuveiro l\u00e1 \u2014 diz %Kohshi%.<br \/>\u2003\u2003\u2014 Tem \u2014 diz %Keigo%. \u2014 Bom, como come\u00e7amos?<br \/>\u2003\u2003\u2014 Sei l\u00e1&#8230; tirando a roupa? \u2014 diz %Take%, retoricamente e retira a pr\u00f3pria camisa.<br \/>\u2003\u2003\u2014 N\u00e3o \u00e9 assim, %Take%! \u2014 briga %Ali% e olha para %Keigo% repreendendo-o pois ele tamb\u00e9m est\u00e1 desabotoando a pr\u00f3pria camisa.<br \/>\u2003\u2003\u2014 Eu nunca fiz isso, ok? N\u00e3o sei qual o procedimento \u2014 defende-se %Take%, colocando a camisa de volta e rindo. %Kohshi% apenas ri da cara dos amigos.<br \/>\u2003\u2003\u2014 Isso n\u00e3o \u00e9 um daqueles programas de computador que voc\u00ea mexe, %Take%, por favor \u2014 %Ali% revira o olhar.<br \/>\u2003\u2003\u2014 Achei que fosse s\u00f3 chegarmos e transarmos \u2014 diz %Keigo% com o ar s\u00e9rio.<br \/>\u2003\u2003\u2014 Meu Deus, %Keigo%, voc\u00ea tamb\u00e9m? Tem que ter o m\u00ednimo de clima primeiro \u2014 ela volta a revirar o olhar.<br \/>\u2003\u2003\u2014 Tipo?<br \/>\u2003\u2003\u2014 Vou colocar uma m\u00fasica \u2014 %Ali% diz e se vira para o mais novo. \u2014 %Take%, pega o vinho na geladeira e traz para gente \u2014 ordena ela.<br \/>\u2003\u2003\u2014 Opa, vinho! \u2014 %Take% comemora e vai at\u00e9 a cozinha executar a ordem da amiga.<br \/>\u2003\u2003\u2014 E a gente? \u2014 indaga %Kohshi%.<br \/>\u2003\u2003\u2014 Tentem entrar no clima \u2014 ela diz, simplesmente.<br \/>\u2003\u2003A mo\u00e7a pega o celular e conecta a m\u00fasica em seu aparelho de som. %Take% volta da cozinha com a garrafa de vinho e %Kohshi% pega as ta\u00e7as para servir a todos. Os quatro n\u00e3o admitem, mas \u00e9 n\u00edtido o nervosismo em todos. Por\u00e9m, a chegada do vinho vai animar um pouco as coisas.<\/p>\r\n<p align=\"center\">[\ud83d\udd25]<\/p>\r\n<p>\u2003\u2003A luz do quarto de %Ali% est\u00e1 apagada, mas o abajur est\u00e1 ligado bem ao lado da cama de casal da mo\u00e7a. Em cima dela, est\u00e3o os quatro executando fun\u00e7\u00f5es diferentes. Ap\u00f3s alguns goles de vinho e alguns minutos dan\u00e7ando a m\u00fasica que tocava, eles come\u00e7aram a entrar no clima verdadeiramente. Agora, %Keigo% e %Ali% est\u00e3o deitados na cama, de lado e opostos em rela\u00e7\u00e3o ao outro. %Keigo% faz sexo oral nela e vice versa. Enquanto isso, %Take% suga os seios da mulher com muito vigor. J\u00e1 %Kohshi% est\u00e1 ajoelhado atr\u00e1s da cabe\u00e7a de %Ali%, afagando seus curtos cabelos enquanto se masturba. O prazer coletivo est\u00e1 transparecendo em cada um deles. %Ali% tenta saber qual das car\u00edcias que recebe \u00e9 mais prazerosa. %Kohshi% n\u00e3o est\u00e1 ativo na transa, por enquanto, mas est\u00e1 se divertindo muito e sentindo um grande prazer em ver os amigos se chupando de maneira t\u00e3o gostosa. %Keigo% saboreia com fervor a intimidade de %Ali% enquanto se controla para n\u00e3o a morder, pois est\u00e1 sentindo seu membro explodir ao ser chupado pela mo\u00e7a. E %Take% est\u00e1 tocando e sugando fielmente cada seio de %Ali%, seios esses que n\u00e3o s\u00e3o fartos, mas que s\u00e3o macios e do agrado dos l\u00e1bios de %Take%.<br \/>\u2003\u2003Os gemidos s\u00e3o inevit\u00e1veis. Nesse momento, %Keigo% e %Ali% interrompem o sexo oral m\u00fatuo e %Take% tamb\u00e9m interrompe sua sugada nos seios dela. A mo\u00e7a puxa ansiosamente %Kohshi% para cima dela, o beijando na boca em seguida. As m\u00e3os dela percorrem as costas do amigo, arranhando-o, o que o deixa empolgado e o faz introduzir seu membro na intimidade dela de maneira r\u00e1pida. %Ali% solta um grito de prazer. Soltando-se do abra\u00e7o dela, %Kohshi% deixa seu corpo mais ereto e come\u00e7a a estocar com for\u00e7a. Sentindo um leve inc\u00f4modo, %Keigo% se deita ao lado dela e come\u00e7a a chupar os seios de %Ali%, %Take% faz o mesmo logo em seguida. A mo\u00e7a afaga os cabelos dos dois, puxando-os com for\u00e7a, mas sem machucar. Os gritos de prazer, enquanto \u00e9 fodida por %Kohshi%, s\u00e3o cada vez mais longos. Gemidos que deixam os tr\u00eas homens loucos de tes\u00e3o.<\/p>\r\n<p>\u2003\u2003<em>Minutos depois&#8230;<\/em> <br \/>\u2003\u2003%Take% abra\u00e7a %Ali% por tr\u00e1s beijando seu pesco\u00e7o, deixando lambidas no local. O membro dele est\u00e1 dentro de %Ali%, os movimentos feitos por %Take% s\u00e3o fortes e precisos, cada estocada acompanhada por um gemido alto da mulher. %Ali% empina mais sua bunda para receber estocadas mais fortes e profundas, isso aumenta seu prazer. %Take% ainda a beija enquanto ela mant\u00e9m sua respira\u00e7\u00e3o pela boca. %Kohshi% resolve participar tamb\u00e9m e come\u00e7a a sugar os seios de %Ali%, deitado na frente dela. J\u00e1 %Keigo% senta-se nas pr\u00f3prias pernas e beija os l\u00e1bios da mo\u00e7a.<br \/>\u2003\u2003Nesse momento, algo acende dentro de %Ali%.<\/p>\r\n<p align=\"center\">[\ud83d\udd25]<\/p>\r\n<p>\u2003\u2003<strong>6AM.<\/strong><br \/>\u2003\u2003%Keigo% est\u00e1 tomando banho, ele pega no plant\u00e3o dentro de alguns minutos, precisa se apressar. De banho finalizado, o rapaz se enxuga com uma toalha que encontra no arm\u00e1rio do banheiro e veste sua roupa. %Keigo% \u00e9 delegado da delegacia da cidade que toma conta da maior parte do local. H\u00e1 apenas quatro delegacias na regi\u00e3o, por se tratar de um lugar mediano, ele \u00e9 tratado como autoridade m\u00e1xima na \u00e1rea. Ele veste sua camisa social, cal\u00e7a e sapatos, antes de caminhar at\u00e9 \u00e0 sala, o rapaz volta ao quarto para se despedir de %Ali%. Ela dorme tranquilamente na ponta da cama, ao lado dela est\u00e3o %Kohshi% e %Take% espalhados, praticamente empurrando a mo\u00e7a para fora. %Keigo% d\u00e1 a volta na cama e deposita um beijo na testa da mo\u00e7a que se mexe levemente, aninhando-se no travesseiro.<br \/>\u2003\u2003\u2014 <em>Fofa&#8230;<\/em> \u2014 sussurra ele para si mesmo, sorrindo.<br \/>\u2003\u2003Antes de deixar o quarto, %Keigo% d\u00e1 um tapa nas pernas dos amigos, na tentativa de fazer ambos se encolherem na cama para dar mais espa\u00e7o para %Ali%. %Kohshi% apenas troca seu corpo de posi\u00e7\u00e3o, virando para o outro lado e voltando a dormir. J\u00e1 %Take% desperta totalmente e pergunta para ele que horas s\u00e3o. Quase 7h da manh\u00e3. O rapaz tamb\u00e9m resolve levantar.<br \/>\u2003\u2003%Keigo% deixa o apartamento de %Ali% com um sentimento confuso dentro de si. Ao mesmo tempo que adorou cada segundo transando com a mo\u00e7a, ele sentiu-se incomodado com a presen\u00e7a dos outros. Na verdade, o rapaz quer mesmo transar <em>apenas<\/em> com a %Ali%. Para ele, o m\u00e9nage de ontem foi mais que uma fantasia realizada. Foi a constata\u00e7\u00e3o de seus sentimentos.<\/p>\r\n<p>\u2003\u2003<em>Dias depois&#8230;<\/em> <br \/>\u2003\u2003O delegado %Keigo% caminha a passos firmes e irritados ap\u00f3s sair de sua viatura. Ele recebe uma informa\u00e7\u00e3o que o deixou extremamente irritado. Dias atr\u00e1s, ap\u00f3s sua sa\u00edda do apartamento de %Ali%, ele soube, atrav\u00e9s de %Take%, que %Kohshi% havia ficado mais tempo l\u00e1. Quando %Take% foi ao quarto se despedir da mo\u00e7a, a flagrou aos beijos com %Kohshi% e o rapaz em cima dela, penetrando-a com for\u00e7a. Tal informa\u00e7\u00e3o fez o sangue de %Keigo% ferver de raiva e <em>ci\u00fame<\/em>.<br \/>\u2003\u2003%Kohshi% caminha com sua prancha debaixo do bra\u00e7o, jogando os longos cabelos molhados para tr\u00e1s, retirando parte da \u00e1gua acumulada neles. O olhar do rapaz se ergue e ele v\u00ea o amigo caminhar em sua dire\u00e7\u00e3o, acompanhado de dois policiais.<br \/>\u2003\u2003\u2014 Veio aprender a surfar, delegado? \u2014 questiona ele, brincalh\u00e3o, mas seu sorriso morre ao receber um soco no rosto.<br \/>\u2003\u2003\u2014 Delegado, por favor, estamos em p\u00fablico! \u2014 alerta um dos policiais, apreensivo. %Keigo% se recomp\u00f5e, ajeitando sua camisa no corpo.<br \/>\u2003\u2003\u2014 O que eu fiz? \u2014 indaga %Kohshi%, surpreso.<br \/>\u2003\u2003\u2014 Voc\u00ea sabe perfeitamente, %Kohshi% \u2014 %Keigo% diz, simplesmente, e completa: \u2014 Como se atreveu?<br \/>\u2003\u2003\u2014 N\u00e3o sei do que est\u00e1 falando, %Keigo%&#8230;<br \/>\u2003\u2003\u2014 Ah, n\u00e3o sabe?! \u2014 debocha ele. \u2014 Vou refrescar sua mem\u00f3ria \u2014 %Keigo% segura o amigo pelo bra\u00e7o e o arrasta at\u00e9 a cal\u00e7ada, onde h\u00e1 um estacionamento, empurrando %Kohshi% com o bra\u00e7o contra a viatura. \u2014 O bar onde sempre vamos. Antes de combinarmos com a %Ali%. O nosso combinado foi diferente. Nada de transas individuais. Lembrou? Ou eu terei que refrescar mais a sua mem\u00f3ria lixo, %Kohshi%? \u2014 explica ele, em pausas, e %Kohshi% arregala o olhar.<br \/>\u2003\u2003\u2014 %Ali% te contou? \u2014 indaga %Kohshi%, assustado.<br \/>\u2003\u2003\u2014 %Take% me contou \u2014 diz %Keigo%.<br \/>\u2003\u2003\u2014 Traidor&#8230; \u2014 sussurra o outro e \u00e9 empurrado novamente na viatura.<br \/>\u2003\u2003\u2014 Delegado&#8230; \u2014 alerta o policial novamente.<br \/>\u2003\u2003\u2014 Calado! \u2014 brada %Keigo%, irritado e volta seu olhar para %Kohshi%. \u2014 Desde quando voc\u00ea \u00e9 um traidor que n\u00e3o cumpre com sua palavra?<br \/>\u2003\u2003\u2014 N\u00e3o foi bem assim, %Keigo%&#8230;<br \/>\u2003\u2003\u2014 N\u00e3o me subestime, %Kohshi%, sabemos que voc\u00ea traiu n\u00e3o s\u00f3 a mim como ao %Take% tamb\u00e9m. Esse <em>n\u00e3o era<\/em> o combinado \u2014 enfatiza ele.<br \/>\u2003\u2003\u2014 Mas&#8230; a %Ali% quem come\u00e7ou me beijando&#8230; \u2014 ele tenta se defender, mas leva outro encontr\u00e3o de %Keigo%.<br \/>\u2003\u2003\u2014 N\u00e3o me diga que ela jogou a buceta na sua cara? \u2014 sibila %Keigo% com o rosto muito pr\u00f3ximo ao do amigo.<br \/>\u2003\u2003\u2014 Quase isso&#8230;<br \/>\u2003\u2003\u2014 Eu deveria atirar voc\u00ea&#8230; \u2014 sussurra o delegado, extremamente irritado e %Kohshi% se arrepende de sua \u00faltima frase.<br \/>\u2003\u2003\u2014 Delegado, algu\u00e9m pode&#8230;<br \/>\u2003\u2003\u2014 Se me der outra ordem, eu irei atirar <em>em voc\u00ea<\/em>, entendeu? \u2014 brada o homem e o policial se cala.<br \/>\u2003\u2003\u2014 N\u00e3o sabia que ficaria t\u00e3o chateado, %Keigo%&#8230;<br \/>\u2003\u2003\u2014 Chateado? \u2014 ele ri, debochado. \u2014 Eu n\u00e3o estou chateado. Eu estou <em>furioso<\/em>! \u2014 brada. \u2014 Se voc\u00ea se atrever a <em>pensar<\/em> em repetir seu ato nojento, eu juro que eu ca\u00e7o algo para prender voc\u00ea. Entendeu? \u2014 ele faz a amea\u00e7a e %Kohshi% engole em seco, apenas concordando com a cabe\u00e7a. \u2014 \u00d3timo, que bom que entendeu, <em>%Kohshi%<\/em>.<br \/>\u2003\u2003\u2014 Me&#8230; me perdoa, eu n\u00e3o sabia que gostava da %Ali%&#8230;<br \/>\u2003\u2003\u2014 \u00d3bvio que eu gosto dela. At\u00e9 o %Take% sabe&#8230;<br \/>\u2003\u2003\u2014 Mas ela n\u00e3o, n\u00e9? \u2014 indaga %Kohshi% e %Keigo% o solta.<br \/>\u2003\u2003\u2014 N\u00e3o \u2014 responde o outro, passando as m\u00e3os nos cabelos.<br \/>\u2003\u2003\u2014 Deveria contar \u2014 sugere %Kohshi% e recebe o olhar irritado do amigo. \u2014 Calma! \u2014 ele ergue as m\u00e3os ao ar, controlando o riso.<br \/>\u2003\u2003\u2014 Eu j\u00e1 vou, tenho uma dilig\u00eancia para fazer \u2014 ele diz, sem mais detalhes e %Kohshi% relaxa o corpo.<br \/>\u2003\u2003\u2014 Mais uma vez, me desculpe, %Keigo%.<br \/>\u2003\u2003\u2014 S\u00f3 n\u00e3o repita&#8230; \u2014 alerta %Keigo%, encarando-o com firmeza. \u2014 Est\u00e1 liberado.<br \/>\u2003\u2003%Kohshi% d\u00e1 uma tapinha de leve no ombro do amigo e se afasta, voltando para a areia da praia. Os policiais entram na viatura e %Keigo% tamb\u00e9m, no banco do carona, eles partem para o local da dilig\u00eancia. Durante o caminho, inevitavelmente, %Keigo% pensa no motivo que o deixou t\u00e3o furioso. Al\u00e9m de sentir ci\u00fames do fato de %Kohshi% ter transado com a %Ali% sozinho, o fato de, durante todo o m\u00e9nage, ele n\u00e3o conseguiu <em>penetrar<\/em> a mulher com seu membro, apenas com seus dedos e l\u00edngua. O prazer foi incr\u00edvel, mas ele queria mesmo estar dentro dela de outra forma. Ele ainda quer.<\/p>\r\n<p>\u2003\u2003<em>Horas depois&#8230;<\/em> <br \/>\u2003\u2003%Keigo% d\u00e1 mais um gole em seu caf\u00e9, tentando manter-se acordado. O plant\u00e3o noturno \u00e9 sempre cansativo para ele, mas ele faz com prazer. \u00c9 a profiss\u00e3o que ama exercer, afinal. S\u00e3o quase 23h e os \u00faltimos policiais deixam a delegacia, restando apenas %Keigo% e o Ken, soldado novato que \u00e9 escalado para acompanhar o delegado nesse plant\u00e3o.<br \/>\u2003\u2003A concentra\u00e7\u00e3o de %Keigo% \u00e9 interrompida por um barulho vindo da parte externa da delegacia. Curioso e irritado, ele se levanta e caminha at\u00e9 a sa\u00edda do local, surpreendendo-se com <em>quem<\/em> ele encontra.<br \/>\u2003\u2003\u2014 %Ali%? \u2014 indaga ele, surpreso. A mo\u00e7a est\u00e1 parada na frente do Ken tentando passar por ele.<br \/>\u2003\u2003\u2014 Diz para esse fedelho sair da minha frente, %Keigo%! \u2014 ordena ela apontando para Ken.<br \/>\u2003\u2003\u2014 Se-Senhor delegado, ela est\u00e1 me desacatando, n\u00e3o est\u00e1? \u2014 pergunta o rapaz, assustado.<br \/>\u2003\u2003\u2014 Ken, deixa ela passar \u2014 pede %Keigo%, calmamente.<br \/>\u2003\u2003\u2014 Ma-Mas senhor delegado, ela me deu um tapa&#8230;<br \/>\u2003\u2003\u2014 Ken! \u2014 enfatiza %Keigo%. \u2014 Deixa ela passar \u2014 assustado com o olhar fuzilante de %Ali%, o jovem soldado deixa a mo\u00e7a passar.<br \/>\u2003\u2003\u2014 Obrigada, Kenzinho \u2014 diz ela, debochada, e volta a fei\u00e7\u00e3o de raiva anterior, caminhando at\u00e9 %Keigo%, a m\u00e3o dela se ergue e voa no ar at\u00e9 o rosto dele, mas %Keigo% segura antes de ser atingido.<br \/>\u2003\u2003\u2014 Est\u00e1 batendo em policiais agora, %Ali%? \u2014 pergunta ele, sustentando o olhar da amiga.<br \/>\u2003\u2003\u2014 Voc\u00ea merece, <em>delegado<\/em> \u2014 sibila ela de maneira debochada.<br \/>\u2003\u2003\u2014 Por que diz isso?<br \/>\u2003\u2003\u2014 Como ousou amea\u00e7ar o %Kohshi%?! \u2014 questiona %Ali% com raiva. %Keigo% mant\u00e9m sua express\u00e3o calma na face.<br \/>\u2003\u2003\u2014 Ah, ent\u00e3o \u00e9 isso \u2014 diz ele como se n\u00e3o fosse nada.<br \/>\u2003\u2003\u2014 Como pode estar t\u00e3o calmo? Voc\u00ea foi arbitr\u00e1rio! Usou seu distintivo para amea\u00e7ar o %Kohshi%! \u2014 acusa %Ali%.<br \/>\u2003\u2003\u2014 Delegado! \u2014 espanta-se Ken.<br \/>\u2003\u2003\u2014 Ken, por favor, nos deixe a s\u00f3s \u2014 pede %Keigo% ainda de maneira calma.<br \/>\u2003\u2003\u2014 Mas, senhor, o plant\u00e3o&#8230;<br \/>\u2003\u2003\u2014 Est\u00e1 dispensado. Creio que n\u00e3o ocorrer\u00e1 crimes hoje \u00e0 noite \u2014 ele mant\u00e9m seu olhar em %Ali% que, pelo olhar que lan\u00e7a para ele, o rapaz tem certeza de que quer mat\u00e1-lo na primeira oportunidade.<br \/>\u2003\u2003\u2014 Imprevistos podem acontecer, senhor. Crimes tamb\u00e9m \u2014 diz Ken e s\u00f3 ent\u00e3o %Keigo% o encara.<br \/>\u2003\u2003\u2014 Ken Yoshida! \u2014 brada ele e o rapaz deixa o corpo ereto, em contin\u00eancia. \u2014 Pegue suas coisas e volte para sua casa, <em>agora<\/em>!<br \/>\u2003\u2003\u2014 Sim, senhor! \u2014 obedece e volta para dentro da delegacia. Segundos depois ele volta para fora. \u2014 Pronto, senhor!<br \/>\u2003\u2003\u2014 Pode ir&#8230; E outra coisa&#8230; \u2014 chama %Keigo%. \u2014 N\u00e3o conte a ningu\u00e9m sobre nada do que presenciou hoje, entendido?<br \/>\u2003\u2003\u2014 E se me perguntarem como foi o plant\u00e3o?<br \/>\u2003\u2003\u2014 Diga que foi pac\u00edfico \u2014 finaliza %Keigo%.<br \/>\u2003\u2003Ainda sem entender, Ken vai at\u00e9 o estacionamento e d\u00e1 partida em sua moto, indo embora em seguida.<br \/>\u2003\u2003\u2014 Voc\u00ea \u00e9 um arbitr\u00e1rio realmente, %Keigo%! \u2014 diz %Ali%, horrorizada.<br \/>\u2003\u2003\u2014 Eu queria ficar \u00e0 s\u00f3s com voc\u00ea para conversarmos melhor \u2014 explica. \u2014 Entra \u2014 ele d\u00e1 passagem para que a mo\u00e7a entre na delegacia.<br \/>\u2003\u2003\u2014 <em>Tisc&#8230;<\/em> \u2014 resmunga %Ali%.<br \/>\u2003\u2003A jovem chefe de cozinha adentra a delegacia e %Keigo% a acompanha, fechando a porta principal do local. %Ali% para quase no meio do sal\u00e3o principal onde h\u00e1 algumas mesas dos policiais que trabalham no lugar. Ela se vira para %Keigo% que sente o vento produzido pelos cabelos dela esvoa\u00e7ando com o movimento que ela faz.<br \/>\u2003\u2003\u2014 Por que o showzinho de mach\u00e3o para cima do %Kohshi%, hein, <em>delegado?<\/em> \u2014 ela volta a usar o tom pejorativo ao se referir a ele.<br \/>\u2003\u2003\u2014 Vamos conversar na minha sala \u2014 ele chama e caminha at\u00e9 a porta de seu escrit\u00f3rio.<br \/>\u2003\u2003\u2014 Estou falando com voc\u00ea! N\u00e3o d\u00ea \u00e0s costas para mim&#8230; \u2014 ela o segue e puxa o bra\u00e7o do rapaz, parando-o ainda na porta.<br \/>\u2003\u2003\u2014 Estou te ouvindo, %Ali%, apenas quero que fique mais confort\u00e1vel \u2014 ele diz, calmamente. \u2014 Por favor, entre e sente-se \u2014 %Keigo% entra na sala, dando a volta na mesa e sentando em sua cadeira.<br \/>\u2003\u2003\u2014 N\u00e3o preciso me sentar \u2014 a mo\u00e7a entra na sala e para em frente \u00e0 mesa dele e prossegue sua fala: \u2014 Quero saber o motivo de voc\u00ea ter feito aquele esc\u00e2ndalo todo e ainda ter amea\u00e7ado prender o %Kohshi%?! \u2014 repete o questionamento.<br \/>\u2003\u2003\u2014 Ele quebrou uma promessa importante, apenas fui cobr\u00e1-lo \u2014 explica ele, ainda mantendo a calma de sempre.<br \/>\u2003\u2003\u2014 Que promessa?<br \/>\u2003\u2003\u2014 Voc\u00ea n\u00e3o precisa saber \u2014 diz.<br \/>\u2003\u2003\u2014 Pois eu quero saber, eu <em>exijo<\/em> saber, %Keigo%! \u2014 brada %Ali% e bate na mesa.<br \/>\u2003\u2003\u2014 Exige \u00e9? Vai mesmo usar esse tom comigo? Eu sou seu amigo, %Ali% \u2014 diz %Keigo%.<br \/>\u2003\u2003\u2014 Por ser meu amigo, voc\u00ea sabe que n\u00e3o temos segredos. Por que n\u00e3o pode me contar?<br \/>\u2003\u2003\u2014 Porque envolve voc\u00ea tamb\u00e9m e&#8230;<br \/>\u2003\u2003\u2014 Agora mesmo que eu quero saber. Me conta, %Keigo%!<br \/>\u2003\u2003\u2014 N\u00e3o posso, eu quebraria outra promessa \u2014 responde, tentando controlar o riso.<br \/>\u2003\u2003\u2014 Que se fodam essas promessas, %Keigo%! Mas que inferno!!! \u2014 brada %Ali% e d\u00e1 a volta na mesa, aproximando-se do rapaz. \u2014 Me conte agora! \u2014 ele o puxa com for\u00e7a pela camisa, mas n\u00e3o o suficiente para faz\u00ea-lo se mexer. %Keigo% sorri.<br \/>\u2003\u2003\u2014 Vai me bater ou me beijar? \u2014 indaga ele j\u00e1 n\u00e3o conseguindo mais se controlar e rindo.<br \/>\u2003\u2003\u2014 Imbecil!<br \/>\u2003\u2003Ela se irrita mais e empurra %Keigo% na cadeira, fazendo o objeto ir para tr\u00e1s junto com seu ocupante. A jovem caminha at\u00e9 \u00e0 porta, mas antes diz:<br \/>\u2003\u2003\u2014 Fica longe do %Kohshi%, seu idiota!<br \/>\u2003\u2003%Ali% deixa a sala de %Keigo% e caminha firmemente para fora da delegacia. J\u00e1 passa das 23h e est\u00e1 ventando bastante. Ela se encolhe em sua jaqueta e caminha pelo estacionamento na parte detr\u00e1s do local, onde estacionou sua moto. Antes dela chegar no ve\u00edculo, ela sente o corpo ser puxado para tr\u00e1s e m\u00e3os envolverem sua cintura com firmeza. Logo ela reconhece o cheiro de %Keigo% que come\u00e7a a distribuir beijos em seu pesco\u00e7o.<br \/>\u2003\u2003\u2014 Delegado&#8230; \u2014 sussurra a jovem, vacilante por sentir o toque do rapaz em seu corpo.<br \/>\u2003\u2003\u2014 Sabe por que eu fiz aquilo? Sabe o porqu\u00ea de eu ter ficado t\u00e3o irritado com o %Kohshi%? \u2014 indaga %Keigo%, com a voz baixa muito pr\u00f3xima ao ouvido dela. %Ali% n\u00e3o responde, ent\u00e3o ele apenas prossegue sua fala: \u2014 Porque eu n\u00e3o penetrei voc\u00ea naquele dia. Eu queria ter te penetrado com o meu pau, mas eu n\u00e3o tive oportunidade que os outros tiveram. Isso me deixou enciumado&#8230;<br \/>\u2003\u2003\u2014 Ent\u00e3o foi isso? \u2014 questiona %Ali%, retoricamente.<br \/>\u2003\u2003%Keigo% a vira de frente para si e agarra com ambas as m\u00e3os um pouco abaixo das n\u00e1degas dela, erguendo o corpo de %Ali% para cima, ato que a for\u00e7a se agarrar no pesco\u00e7o dele e envolver suas pernas na cintura do delegado. Ele caminha rapidamente at\u00e9 o ve\u00edculo mais pr\u00f3ximo, encostando o corpo da mulher na porta de tr\u00e1s enquanto beija seus l\u00e1bios. %Keigo% solta as pernas dela, que as apoia no ch\u00e3o, o corpo do delegado muito colado ao dela de maneira firme.<br \/>\u2003\u2003\u2014 Se eu soubesse que voc\u00ea queria isso, eu chamava os meninos tamb\u00e9m \u2014 brinca %Ali%, ofegante.<br \/>\u2003\u2003\u2014 Eu quero <em>s\u00f3<\/em> voc\u00ea, %Ali%.<br \/>\u2003\u2003O olhar intenso de %Keigo% penetra os olhos de %Ali% que engole em seco, finalmente entendendo o que o rapaz quer dizer de verdade. Ela percebe que ele n\u00e3o ficou apenas chateado de n\u00e3o ter transado com ela, %Keigo% ficou chateado porque ela transou com %Take% e com o %Kohshi%, sendo o \u00faltimo por duas vezes. Mas, o que %Ali% est\u00e1 confusa \u00e9 se %Keigo% est\u00e1 com o orgulho ferido ou apenas enciumado porque tem sentimentos por ela.<br \/>\u2003\u2003N\u00e3o d\u00e1 tempo de ela descobrir, pelo menos n\u00e3o agora.<br \/>\u2003\u2003%Keigo% abre a porta da viatura e empurra %Ali% para o banco de tr\u00e1s. Ap\u00f3s deitar-se, ela sente o peso do corpo de %Keigo% sobre ela e as m\u00e3os habilidosas do rapaz percorrendo seu corpo. Ele come\u00e7a a despir-se retirando sua camisa e desabotoando sua cal\u00e7a, voltando sua aten\u00e7\u00e3o em seguida em retirar a roupa de %Ali%.<br \/>\u2003\u2003\u2014 Que motivo mesquinho, delegado&#8230; \u2014 diz ela, referindo-se ainda ao motivo do enfurecimento de %Keigo%. Ele a encara com as m\u00e3os na lateral dos seios dela.<br \/>\u2003\u2003\u2014 N\u00e3o \u00e9 mesquinho se voc\u00ea considerar o fato que eu te amo \u2014 declara-se ele com o olhar fixo nela.<br \/>\u2003\u2003\u2014 Amor? \u2014 indaga ela, confusa.<br \/>\u2003\u2003\u2014 Amor&#8230; \u2014 sussurra o rapaz e d\u00e1 um chup\u00e3o no queixo dela, que joga a cabe\u00e7a para tr\u00e1s sentindo um prazer com o gesto. Em seguida, %Keigo% d\u00e1 um selinho carinhoso nos l\u00e1bios dela. \u2014 Eu amo voc\u00ea, %Ali% \u2014 ele volta a sussurrar e puxa a blusa da mo\u00e7a de uma vez.<br \/>\u2003\u2003Quando a blusa passa pelo seu rosto, %Ali% v\u00ea os olhos penetrantes de %Keigo%, vis\u00edveis gra\u00e7as \u00e0 luz externa que adentra ao carro, encarando-a, engolindo em seco a mo\u00e7a logo sente as m\u00e3os dele descerem at\u00e9 suas coxas, erguendo-as levemente, e os l\u00e1bios dele tocar os seus de maneira incandescente.<\/p>\r\n<p align=\"center\">[\ud83d\udd25]<\/p>\r\n<p>\u2003\u2003Fren\u00e9tica.<br \/>\u2003\u2003Essa \u00e9 uma boa palavra para descrever a transa entre %Keigo% e %Ali% nesse momento. Agora, o rapaz est\u00e1 deitado em sua mesa, as coisas que haviam ali espalhadas pelo ch\u00e3o, %Ali% encaixada em seu membro e as m\u00e3os dele encaixadas em sua bunda.<br \/>\u2003\u2003Com a finalidade de acelerar o prazer de ambos, %Keigo% puxa o tronco de %Ali% para deitar-se sobre ele, impulsionando seu quadril para cima ritmicamente em estocadas fortes. Com isso, a mo\u00e7a come\u00e7a a gemer muito alto.<br \/>\u2003\u2003\u2014 N\u00e3o grite t\u00e3o alto, v\u00e3o achar que est\u00e3o invadindo a delegacia \u2014 pede %Keigo% com a voz vacilante.<br \/>\u2003\u2003\u2014 N\u00e3o controle o meu gemido, %Keigo%&#8230; \u2014 ela diz, tamb\u00e9m ofegante. \u2014 \u00c9 broxante!<br \/>\u2003\u2003\u2014 Perdoe-me, %Ali%&#8230;<br \/>\u2003\u2003\u2014 Vou gemer no seu ouvido, ent\u00e3o&#8230;<br \/>\u2003\u2003\u2014 Sou <em>todo<\/em> seu, %Ali%, fa\u00e7a o que quiser comigo \u2014 ele usa um tom dengoso que, at\u00e9 ent\u00e3o, era desconhecido pela mo\u00e7a. \u2014 Geme aqui, geme \u2014 %Keigo% aponta para o pr\u00f3prio ouvido e volta sua m\u00e3o at\u00e9 a bunda da mo\u00e7a, apertando-a e aumenta o ritmo das estocadas.<br \/>\u2003\u2003\u2014 Me fode, delegado! Me fode&#8230;<br \/>\u2003\u2003O pedido ati\u00e7a o rapaz que sente seu orgasmo chegar, um prazer enorme lhe percorrendo o corpo. Avassalador.<\/p>\r\n<p>\u2003\u2003<em>Horas depois&#8230;<\/em> <br \/>\u2003\u2003%Keigo% e %Ali% est\u00e3o deitados no sof\u00e1 que h\u00e1 encostado na parede pr\u00f3xima \u00e0 porta. O cheiro do cabelo dela penetrando seu olfato o deixa calmo, abaixando a adrenalina do intenso sexo que praticam por algumas horas. Ele afaga os cabelos dela que se aninha em seu peito, a respira\u00e7\u00e3o de ambos mais amena.<br \/>\u2003\u2003\u2014 %Keigo%&#8230;<br \/>\u2003\u2003\u2014 Quer me perguntar algo? \u2014 deduz ele afastando-se um pouco para poder olhar para ela. %Ali% faz o mesmo.<br \/>\u2003\u2003\u2014 Por que eu sinto que n\u00e3o vou conseguir ficar longe de voc\u00ea? \u2014 ele sorri levemente.<br \/>\u2003\u2003\u2014 N\u00e3o sei&#8230;<br \/>\u2003\u2003\u2014 Tem algo em voc\u00ea que \u00e9 <em>viciante<\/em>&#8230; \u2014 ela pausa um pouco o seu racioc\u00ednio e prossegue segundos depois: \u2014 Eu quero mais e mais.<br \/>\u2003\u2003\u2014 Eu sou todo seu, %Ali% \u2014 diz %Keigo%, sorrindo.<br \/>\u2003\u2003\u2014 Colocou entorpecentes no seu pau, delegado?<br \/>\u2003\u2003%Keigo% n\u00e3o segura o riso.<br \/>\u2003\u2003\u2014 N\u00e3o, ele \u00e9 assim de nascen\u00e7a \u2014 gaba-se. \u2014 Quem prova, vicia.<br \/>\u2003\u2003\u2014 Acho que eu n\u00e3o quero me curar desse v\u00edcio \u2014 ela diz tamb\u00e9m sorrindo.<br \/>\u2003\u2003\u2014 Tem certeza? \u2014 o olhar carinhoso do rapaz a faz sentir seu cora\u00e7\u00e3o encher-se de amor.<br \/>\u2003\u2003\u2014 Tenho.<br \/>\u2003\u2003A convic\u00e7\u00e3o na voz e no olhar de %Ali% deixam %Keigo% aliviado e feliz. Carinhoso, ele d\u00e1 um beijo nela tentando transmitir um pouco do sentimento que tem pela mulher.<br \/>\u2003\u2003\u2014 Posso prender voc\u00ea, sabia? \u2014 ele diz, ap\u00f3s o beijo e %Ali% a encara confusa.<br \/>\u2003\u2003\u2014 Por que, delegado?<br \/>\u2003\u2003\u2014 Por dois crimes. O primeiro \u00e9 por ter roubado o meu cora\u00e7\u00e3o \u2014 ela ri abertamente.<br \/>\u2003\u2003\u2014 Que brega, %Keigo%!<br \/>\u2003\u2003\u2014 Mas voc\u00ea gostou, eu sei \u2014 gaba-se ele novamente, tamb\u00e9m rindo.<br \/>\u2003\u2003\u2014 Metido! E qual o segundo crime que eu supostamente cometi?<br \/>\u2003\u2003\u2014 O segundo crime \u00e9 ser uma grande gostosa. Ah, al\u00e9m de tamb\u00e9m ter me viciado em voc\u00ea \u2014 ele diz com o olhar fixo nela e, dessa vez, \u00e9 ela quem o beija rapidamente. \u2014 Ah, preciso fazer algo \u2014 lembra-se ele, levantando do sof\u00e1.<br \/>\u2003\u2003\u2014 Vai me deixar sozinha aqui? \u2014 ela senta-se no sof\u00e1 e se finge de ofendida.<br \/>\u2003\u2003\u2014 Dois segundos&#8230; \u2014 ele diz, sem olhar para ela e finalmente acha seu celular, que est\u00e1 no ch\u00e3o pr\u00f3ximo a sua mesa. \u2014 Faz uma pose para mim \u2014 pede ele, encarando-a.<br \/>\u2003\u2003\u2014 Pose? \u2014 ela cobre os seios e cruza as pernas, ainda sem roupas. \u2014 Assim?<br \/>\u2003\u2003\u2014 Eu admiro muito o seu corpo nu, meu amor, mas eu quero um registro desse momento com voc\u00ea vestida \u2014 explica ele.<br \/>\u2003\u2003\u2014 N\u00e3o vai vender a foto na internet, vai? Eu mando te prender&#8230;<br \/>\u2003\u2003\u2014 Jamais faria isso, voc\u00ea sabe como eu sou.<br \/>\u2003\u2003\u2014 Sei at\u00e9 demais \u2014 eles riem.<br \/>\u2003\u2003\u2014 Isso \u00e9 ruim?<br \/>\u2003\u2003\u2014 N\u00e3o sei ainda, mas adoraria descobrir mais sobre o s\u00e9rio e gostoso delegado %Keigo%. O lado que eu ainda n\u00e3o conhe\u00e7o \u2014 ela sorri, sugestiva.<br \/>\u2003\u2003O rapaz entrega as roupas de %Ali% para que ela se vista. Depois, ela faz algumas poses para ele. O corpo da mo\u00e7a \u00e9 quase todo tatuado, seus bra\u00e7os s\u00e3o os que mais t\u00eam tatuagens, s\u00e3o desenhos diversos, mas cada um com um significado para estarem ali. O olhar apaixonado de %Keigo% faz a mo\u00e7a sentir-se amada, cada clique dado por ele registra a genu\u00edna felicidade da mo\u00e7a em estar ali com ele.<br \/>\u2003\u2003E ela quer tanto ter mais disso.<\/p>\r\n<p>\u2003\u2003<em>Minutos depois&#8230;<\/em> <br \/>\u2003\u2003A \u00e1gua quente percorre o corpo malhado de %Keigo% enquanto ele esfrega cada canto de si mesmo. A distra\u00e7\u00e3o dele n\u00e3o lhe permite perceber a aproxima\u00e7\u00e3o sorrateira de %Ali% que adentra o box, fechando-o em seguida, e abra\u00e7a as costas de %Keigo%. Ele sorri com o gesto e segura os bra\u00e7os dela, envoltos em seu t\u00f3rax, balan\u00e7ando o corpo levemente para os lados. Eles se afastam um pouco do chuveiro, %Keigo% o desliga, e se vira de frente para %Ali% que volta a o abra\u00e7ar. As m\u00e3os dela arranham levemente as costas do rapaz enquanto eles se beijam, mas logo o beijo \u00e9 interrompido por ela que passa suas m\u00e3os no t\u00f3rax dele de maneira sensual, o olhar fixado nos olhos de %Keigo% que n\u00e3o consegue desviar nem por um segundo. Quando alcan\u00e7a o membro do rapaz, %Ali% come\u00e7a a manuse\u00e1-lo e logo o p\u00f5e na boca dando algumas chupadas, o que faz %Keigo% soltar suspiros e levar sua m\u00e3o esquerda diretamente nos cabelos da amiga. Os l\u00e1bios aveludados dela sugando com vigor o seu membro faz o prazer de %Keigo% elevar gradativamente. Por\u00e9m, para sua insatisfa\u00e7\u00e3o moment\u00e2nea, %Ali% para de chup\u00e1-lo e ergue se corpo para encarar %Keigo%, ainda segurando o membro dele, masturbando-o.<br \/>\u2003\u2003\u2014 Ser\u00e1 que voc\u00ea pode me foder agora, <em>ursinho<\/em>? \u2014 pede ela com a voz sexy.<br \/>\u2003\u2003\u2014 <em>Ursinho?<\/em> \u2014 repete ele, encarando a amiga com o olhar suspenso.<br \/>\u2003\u2003\u2014 Por causa das suas bochechonas rosadas \u2014 explica a mulher enquanto ro\u00e7a a intimidade no membro de %Keigo%, que se controla muito para n\u00e3o a empurrar na parede nesse instante. \u2014 Me fode, meu ursinho, me fode!! \u2014 ela volta a pedir.<br \/>\u2003\u2003\u2014 Serei seu ursinho, meu amor \u2014 ele segura o rosto dela e a beija intensamente.<br \/>\u2003\u2003Logo em seguida, %Keigo% faz o que pensou segundos atr\u00e1s: ele introduz seu membro nela, empurrando-a contra a parede de maneira firme, a m\u00e3o ainda segurando o rosto da amiga, tamb\u00e9m pressionando-o na parede, mas sem machuc\u00e1-la. As estocadas fortes e ininterruptas fazem %Ali% gritar de tes\u00e3o. Mas logo elas cessam.<br \/>\u2003\u2003\u2014 Quem mandou parar, delegado? \u2014 protesta %Ali%, ofegante.<br \/>\u2003\u2003\u2014 Me chama daquilo de novo, chama? \u2014 ele pede e lambe o queixo dela. \u2014 Me pede para te foder com for\u00e7a e eu fa\u00e7o \u2014 o rosto de %Ali% para bem pr\u00f3ximo do dele e %Keigo% passa sua l\u00edngua pelas bochechas da mo\u00e7a.<br \/>\u2003\u2003\u2014 Me fode com for\u00e7a, <em>ursinho<\/em> \u2014 implora a mulher sentindo o corpo amolecer, apesar de estar bastante firme nos bra\u00e7os do delegado.<br \/>\u2003\u2003\u2014 \u00c9 assim que eu gosto, meu beb\u00ea \u2014 ele volta a lamber o rosto dela e volta a estocar com for\u00e7a.<br \/>\u2003\u2003\u2014 Ahhh, %Keigo%! \u2014 geme ela, agarrando o peito dele.<br \/>\u2003\u2003\u2014 Quer com mais for\u00e7a, meu amor? \u2014 ati\u00e7a o rapaz e %Ali% o encara.<br \/>\u2003\u2003\u2014 Me fode com for\u00e7a, <em>amor<\/em>&#8230; ahhh!<br \/>\u2003\u2003N\u00e3o se deixando muito levar pelo apelido no fim da frase, %Keigo% mant\u00e9m a for\u00e7a durante o restante do sexo. Por\u00e9m, a mente dele n\u00e3o deixa de pensar naquela palavra. \u00c9 somente uma palavra, afinal? Ou ser\u00e1 que h\u00e1 o <em>sentimento<\/em>?<\/p>\r\n<p align=\"center\">[\ud83d\udd25]<\/p>\r\n<p>\u2003\u2003O aroma inebriante dos cabelos da %Ali% deixa %Keigo% a\u00e9reo. Ele desperta ap\u00f3s terem adormecido depois da noite intensa que tiveram. O escrit\u00f3rio do delegado possui um sof\u00e1-cama bastante confort\u00e1vel que ele usa para dormir um pouco durante os plant\u00f5es que costumam ser tranquilos. Sua sala est\u00e1 trancada e as persianas abaixadas para que ningu\u00e9m veja o interior do c\u00f4modo. O ar condicionado ligado refresca o ambiente.<br \/>\u2003\u2003%Ali% se remexe manhosamente ao lado de %Keigo% que sorri com o abra\u00e7o repentino que ela lhe d\u00e1, aconchegando-se em seguida. Ele ajeita o edredom, cobrindo mais os seus corpos e encosta a cabe\u00e7a na testa dela, dando um beijinho no local. De repente, %Keigo% ouve uma movimenta\u00e7\u00e3o vinda da parte externa. Curioso, ele estica o bra\u00e7o e pega seu celular, conferindo a hora no visor do aparelho.<br \/>\u2003\u2003<strong>8AM<\/strong><br \/>\u2003\u2003A hora passa t\u00e3o rapidamente que ele mal nota que j\u00e1 est\u00e1 no hor\u00e1rio dos policiais chegarem para assumirem o plant\u00e3o matinal. As vozes externas denunciam a curiosidade dos colegas de trabalho de %Keigo% em saber o motivo de sua sala estar toda fechada ainda. Ele ouve que tentam abrir a porta, sem sucesso, e desistem de tentar incomod\u00e1-lo. Se for algo realmente importante, eles o chamar\u00e3o. %Keigo% n\u00e3o deseja mais nada al\u00e9m de aproveitar mais algum tempo com a %Ali% aninhada em seu peito, ele nem sabia que esse seria o melhor momento de sua vida.<br \/>\u2003\u2003A mulher acorda, ap\u00f3s um longo suspiro manhoso e sente o corpo quente de %Keigo% agarrado a ela. Sorri de leve e afaga o peito dele com carinho, recebendo um beijo terno em sua testa.<br \/>\u2003\u2003\u2014 Bom dia \u2014 sussurra ele. \u2014 Se quiser pode dormir mais \u2014 avisa ele dando mais um beijo.<br \/>\u2003\u2003\u2014 Eu preciso ir \u2014 lamenta ela, tamb\u00e9m sussurrando. \u2014 Os outros policiais chegaram, n\u00e9?<br \/>\u2003\u2003\u2014 Sim \u2014 responde %Keigo% e sente o corpo dela se afastar um pouco, mas ainda aninhado. O olhar de %Ali% direcionado para ele agora.<br \/>\u2003\u2003\u2014 %Keigo%&#8230;<br \/>\u2003\u2003\u2014 Oi.<br \/>\u2003\u2003\u2014 Ser\u00e1 que&#8230; bom, ser\u00e1 que&#8230;<br \/>\u2003\u2003%Ali% pausa sua fala enquanto desenha formas aleat\u00f3rias no t\u00f3rax dele. %Keigo% puxa o rosto da amiga com a m\u00e3o livre e a encara com o olhar sereno e um sorriso singelo nos l\u00e1bios. Esse olhar&#8230; ah, esse olhar e esse sorriso que, por alguma raz\u00e3o nova, a faz sentir falta de ar e uma sensa\u00e7\u00e3o gostosa que a faz querer ficar encarando-o pela eternidade.<br \/>\u2003\u2003\u2014 Voc\u00ea quer sair comigo mais tarde? \u2014 pergunta ele, de repente, e %Ali% toma um susto, sem esperar pela pergunta.<br \/>\u2003\u2003\u2014 Sair? Para onde?<br \/>\u2003\u2003\u2014 Ah, n\u00e3o sei. Para onde voc\u00ea quer ir? \u2014 ele acaricia a bochecha dela causando arrepios na mulher.<br \/>\u2003\u2003\u2014 Tamb\u00e9m n\u00e3o sei \u2014 eles riem com a indecis\u00e3o de ambos.<br \/>\u2003\u2003\u2014 Vou a qualquer lugar com voc\u00ea, o importante \u00e9 a sua companhia \u2014 a frase dita por %Keigo% faz %Ali% sorrir involuntariamente.<br \/>\u2003\u2003\u2014 O delegado sabe ser fofo tamb\u00e9m \u2014 brinca ela.<br \/>\u2003\u2003\u2014 Sei \u2014 diz %Keigo% e aperta levemente a bochecha dela. \u2014 Ent\u00e3o voc\u00ea aceita sair comigo?<br \/>\u2003\u2003\u2014 Aceito.<br \/>\u2003\u2003Algo crescente dentro de %Ali% a convence de que o convite de %Keigo% \u00e9 algo que realmente n\u00e3o se deve negar. A mo\u00e7a tenta decifrar do que se trata, mas seria um pouco imposs\u00edvel. Ela tem a certeza de que \u00e9 algo banal, caso seja verdade, mas a suspeita dela \u00e9 de que ela est\u00e1 apaixonada pelo %Keigo%.<br \/>\u2003\u2003Mas, como \u00e9 poss\u00edvel ela estar apaixonada apenas com uma foda? Se bem que foi <em>a foda<\/em>, mesmo assim seria algo inimagin\u00e1vel e at\u00e9 surreal ela se apaixonar pelo melhor amigo dela <em>dessa maneira<\/em>. Ou n\u00e3o seria?<br \/>\u2003\u2003%Ali% resolve ignorar esse sentimento, por enquanto, e apenas volta a aninhar-se nos bra\u00e7os aconchegantes de %Keigo%. O cheiro dele \u00e9 algo que ela realmente adora, muito mais do que o cheiro dos ingredientes que ela tanto manuseia e ama.<br \/>\u2003\u2003Um cheiro viciante, de fato.<\/p>\r\n<p align=\"right\"><em>&#8220;6 da manh\u00e3 estou sendo puxado de volta para a realidade<\/em><br \/>\u2003\u2003<em>Vou tentar de novo hoje, mesmo que tudo n\u00e3o funcione<\/em><br \/>\u2003\u2003<em>Mesmo que seja uma alegria deliciosa,<\/em><br \/>\u2003\u2003<em>estar\u00e1 ligada \u00e0 foto amanh\u00e3.&#8221;<\/em><br \/>\u2003\u2003<strong>&#8211; Image, FLOW<\/strong><\/p>\r\n<p align=\"center\"><strong>FIM<\/strong><\/p>\r\n<p>\u2003\u2003<b>Nota da autora:<\/b> Nossa, isso aqui foi REALMENTE um surto de se escrever e, sinceramente, eu gostaria de VIVER esse surto. Falei com a Quel que, se os Flow me sugerissem um menagizinho maroto eu diria SIM sem nem pensar a respeito hahahahaha AMO.<br \/>\u2003\u2003Obrigada a quem leu, obrigada a quem revisou e scriptou e obrigada Keigo por esse delegado gostos\u00e3o e ati\u00e7ador que ele foi em IMAGE!<br \/>\u2003\u2003N\u00e3o esque\u00e7am o coment\u00e1rio gostosin a\u00ed embaixo ou nas minhas redes sociais, aceito surtos haha<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>\u2003\u2003Horas antes&#8230; [\ud83d\udd25] [\ud83d\udd25] \u2003\u2003Minutos depois&#8230; [\ud83d\udd25] \u2003\u20036AM. \u2003\u2003Dias depois&#8230; \u2003\u2003Horas depois&#8230; [\ud83d\udd25] \u2003\u2003Horas depois&#8230; \u2003\u2003Minutos depois&#8230; [\ud83d\udd25] \u2003\u20038AM &#8220;6 da manh\u00e3 estou sendo puxado de volta para a realidade\u2003\u2003Vou tentar de novo hoje, mesmo que tudo n\u00e3o funcione\u2003\u2003Mesmo que seja uma alegria deliciosa,\u2003\u2003estar\u00e1 ligada \u00e0 foto amanh\u00e3.&#8221;\u2003\u2003&#8211; Image, FLOW FIM \u2003\u2003Nota da autora: Nossa, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"historias":[2011],"class_list":["post-5876","capitular","type-capitular","status-publish","format-standard","hentry","historias-image"],"acf":[],"_links":{"self":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular\/5876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular"}],"about":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/types\/capitular"}],"author":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/comments?post=5876"}],"wp:attachment":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/media?parent=5876"}],"wp:term":[{"taxonomy":"historias","embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/historias?post=5876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}