{"id":4839,"date":"2020-08-11T11:16:00","date_gmt":"2020-08-11T14:16:00","guid":{"rendered":"https:\/\/espacocriativo.net\/acervo\/historia\/historia-sem-nome\/rascunho-automatico\/"},"modified":"2025-10-11T11:21:22","modified_gmt":"2025-10-11T14:21:22","slug":"capitulo-44","status":"publish","type":"capitular","link":"https:\/\/espacocriativo.net\/acervo\/historia\/my-little-thief\/capitulo-44\/","title":{"rendered":"Cap\u00edtulo 44"},"content":{"rendered":"\r\n<p>\u2003\u2003<strong>%Nalla%<\/strong><\/p>\r\n<p><span class=\"versalete\">\u2003\u2003Me sentei na cadeira<\/span> novamente, pensando no que faria para sair dali, j\u00e1 que era vis\u00edvel estar sozinha dessa vez. N\u00e3o podia ligar para o Dean, menos ainda ligar para Siwon, certamente tomaria as dores do irm\u00e3o. Estava percebendo que somente a senhora Mary havia me perdoado naquela fam\u00edlia.<br \/>\u2003\u2003\u2014 Conseguiu fazer a liga\u00e7\u00e3o? \u2014 perguntou Smith ao entrar na sala.<br \/>\u2003\u2003\u2014 Sim. \u2014 estiquei o celular para ela ao me levantar da cadeira. \u2014 Obrigada.<br \/>\u2003\u2003\u2014 N\u00e3o, eu que agrade\u00e7o. \u2014 ele retirou uma correntinha do bolso, mostrando discretamente a pequena medalha que estava preso a ele. \u2014 Bem, pequenas coisas podem ser insignificantes para uns, por\u00e9m para outros representam sua honra.<br \/>\u2003\u2003Eu estava me lembrando daquele objeto, era a mesma medalha que havia resgatado em Portugal, como poderia esquecer daquele servi\u00e7o, afinal, foi nele que conheci o meu agente preferido. Por essa eu realmente n\u00e3o esperava, tenho que admitir que jamais me importava em saber quem eram os clientes que Dean arrumava para mim, mas descobrir que um deles era inspetor da Interpol me deixava curiosa para saber quem eram os outros, j\u00e1 foram tantos.<br \/>\u2003\u2003\u2014 Algumas pessoas prezam bastante a honra. \u2014 respirei fundo mantendo meu olhar na medalha. \u2014 Fico feliz que saiba preservar a sua.<br \/>\u2003\u2003\u2014 Assim como voc\u00ea preserva a sua. \u2014 ele me olhou com tranquilidade enquanto guardava sua medalha no bolso novamente. \u2014 Bem, devemos conversar sobre o erro do nosso agente, novamente pe\u00e7o desculpas por toda a ag\u00eancia, o agente Choi ser\u00e1 punido de acordo com as normas da empresa e iremos\u2026<br \/>\u2003\u2003\u2014 Sinceramente, eu n\u00e3o queria que o agente Choi fosse demitido. \u2014 intervi com plena raz\u00e3o. \u2014 Errar \u00e9 humano, mesmo que eu tenha sa\u00eddo prejudicada, o que importa \u00e9 que tudo foi esclarecido e minha ficha continua limpa.<br \/>\u2003\u2003\u2014 Vou considerar suas palavras. \u2014 ele estendeu a m\u00e3o em dire\u00e7\u00e3o a sa\u00edda. \u2014 Por aqui, por favor.<br \/>\u2003\u2003\u2014 Me levar\u00e1 at\u00e9 a sa\u00edda? \u2014 perguntei olhando novamente para as algemas que Cedric havia deixado em cima da mesa.<br \/>\u2003\u2003\u2014 Sim, a senhorita est\u00e1 liberada para ir. \u2014 assentiu ele.<br \/>\u2003\u2003\u2014 Tudo bem. \u2014 sorri de leve e o segui pelo corredor.<br \/>\u2003\u2003A cada passo que dava era um suspiro de alegria, eu estava livre daquele lugar e ainda mais confiante que tudo ficaria bem. Assim que chegamos na porta girat\u00f3ria do pr\u00e9dio, Smith se desculpou mais uma vez e perguntou se queria que ele chamasse o t\u00e1xi para mim, por\u00e9m recusei sua oferta, n\u00e3o queria nem por um segundo depender ainda mais dele. Fiquei me perguntando se esse inspetor tinha algum envolvimento nisso tudo.<br \/>\u2003\u2003\u2014 Finalmente livre. \u2014 disse me espregui\u00e7ando assim que sa\u00ed do pr\u00e9dio e senti o sol tocar minha pele.<br \/>\u2003\u2003\u2014 Parab\u00e9ns, n\u00e3o vai agradecer seu marido? \u2014 disse ele. \u2014 Ou devo dizer outra defini\u00e7\u00e3o?<br \/>\u2003\u2003\u2014 Ainda quer ser meu marido? \u2014 me virei e o olhei. \u2014 Pensei que n\u00e3o viria, %Suho%.<br \/>\u2003\u2003\u2014 Eu disse que n\u00e3o viria? \u2014 seu olhar um pouco sarc\u00e1stico estava ali.<br \/>\u2003\u2003\u2014 Hum\u2026 Tamb\u00e9m n\u00e3o disse que viria. \u2014 mantive meu olhar nele.<br \/>\u2003\u2003%Suho% tomou impulso e pegando em minha m\u00e3o me puxou para perto dele, me abra\u00e7ando como se estivesse matando a saudade, meu corpo paralisou e meu c\u00e9rebro n\u00e3o conseguia assimilar o que estava acontecendo, logo meu cora\u00e7\u00e3o acelerou ao sentir seu perfume.<br \/>\u2003\u2003\u2014 %Suho%\u2026. \u2014 sussurrei. \u2014 O que est\u00e1\u2026<br \/>\u2003\u2003\u2014 Nosso agente est\u00e1 nos olhando do lado de dentro do pr\u00e9dio. \u2014 sussurrou ele. \u2014 Mas n\u00e3o \u00e9 somente isso, talvez eu tamb\u00e9m queira te abra\u00e7ar.<br \/>\u2003\u2003\u2014 Talvez? \u2014 eu me afastei dele, o olhando s\u00e9ria.<br \/>\u2003\u2003\u2014 Vamos para casa. \u2014 ele segurou em minha m\u00e3o entrela\u00e7ando nossos dedos.<br \/>\u2003\u2003\u2014 Ainda estamos sendo vigiados?<br \/>\u2003\u2003\u2014 N\u00e3o. \u2014 ele sorriu de leve. \u2014 Vamos deixar as perguntas e desculpas para depois, Cronos est\u00e1 com minha fam\u00edlia tamb\u00e9m.<br \/>\u2003\u2003\u2014 Como? \u2014 isso me surpreendeu.<br \/>\u2003\u2003\u2014 Descobrimos o nome do Albergue onde estava. \u2014 ele tossiu um pouco. \u2014 Para ser sincero, recebemos uma visita bem inesperada ontem.<br \/>\u2003\u2003Visita inesperada, s\u00f3 tinha um nome para definir isso: Dean. Ele havia sido essa visita, o que tinha me deixado ainda mais admirada foi seu pedido de ajuda para a fam\u00edlia de %Suho%, al\u00e9m de concordar com a exig\u00eancia da senhora Mary. Algo que realmente havia me impressionado foi ela me defender com tanta for\u00e7a, eu havia ganhado uma m\u00e3e de verdade e queria muito retribuir aquele carinho.<br \/>\u2003\u2003Ser\u00e1 que conseguiria?<br \/>\u2003\u2003N\u00e3o demorou muito at\u00e9 que %Suho% estacionou em frente a casa deles de Paris, precisei respirar fundo muitas vezes at\u00e9 que a coragem para entrar chegou em mim, mesmo com %Suho% segurando minha m\u00e3o. De todos ali presente, a pessoa que mais me deixava chateada comigo mesma por t\u00ea-los roubado \u00e9 Mary, a m\u00e3e que nunca tive.<br \/>\u2003\u2003\u2014 M\u00e3e, pai, chegamos. \u2014 disse ele assim que entramos.<br \/>\u2003\u2003\u2014 %Nalla%. \u2014 Mary veio de encontro me abra\u00e7ar sem nenhum receio, um abra\u00e7o apertado e cheio de carinho. \u2014 Que bom que est\u00e1 de volta, fiquei t\u00e3o preocupada.<br \/>\u2003\u2003\u2014 Senhora Mary, eu\u2026. \u2014 precisava encontrar palavras certas para finalmente tentar me desculpas pelo menos com ela.<br \/>\u2003\u2003\u2014 Oh querida, eu sei, n\u00e3o precisa se desculpar, j\u00e1 te perdoei por isso. \u2014 ela sorriu com gentileza para mim. \u2014 N\u00e3o ligue para esses rancorosos, sei que deve n\u00e3o ter tido escolha e se fez, foi por algum motivo.<br \/>\u2003\u2003De alguma forma ela me entendia, o que me fazia cada vez mais querer n\u00e3o decepcion\u00e1-la.<br \/>\u2003\u2003\u2014 Obrigada pelo carinho. \u2014 sorri de volta para ela.<br \/>\u2003\u2003\u2014 Voc\u00ea a perdoou, mas eu n\u00e3o. \u2014 o senhor Hwang se levantou da poltrona onde estava. \u2014 Voc\u00ea ainda est\u00e1 em falta comigo.<br \/>\u2003\u2003\u2014 Yeoboo, pare com isso. \u2014 a senhora Mary interviu.<br \/>\u2003\u2003\u2014 Mary, n\u00e3o precisa, ele est\u00e1 certo. \u2014 respirei fundo desviando meu olhar para ele. \u2014 Tem raz\u00e3o de n\u00e3o querer confiar em mim, nem eu confiaria, mas\u2026<br \/>\u2003\u2003\u2014 Mas? \u2014 Sam apareceu da porta. \u2014 Noona, se voc\u00ea arrumar uma namorada para mim, eu te perdoo.<br \/>\u2003\u2003Segurei o riso.<br \/>\u2003\u2003\u2014 Yah, menino abusado, pare de espionar a conversa. \u2014 Mary gritou com ele.<br \/>\u2003\u2003\u2014 Eu n\u00e3o quero uma namorada, mas se me pagar um jantar e me responder algumas perguntas curiosas&#8230; \u2014 Siwon estava descendo as escadas e ao olhar para mim, piscou de leve de forma sinuosa. \u2014 Bem-vinda de volta.<br \/>\u2003\u2003\u2014 Eu\u2026 N\u00e3o sei como dizer\u2026. \u2014 realmente n\u00e3o sabia, era a primeira vez que pedia desculpas sinceras para pessoas t\u00e3o importantes.<br \/>\u2003\u2003\u2014 Se fosse menos orgulhosa, saberia. \u2014 %Suho% soltou minha m\u00e3o e se dirigiu para a escada, subindo sem a menor preocupa\u00e7\u00e3o.<br \/>\u2003\u2003\u2014 Aish, esse menino mal criado. \u2014 reclamou Mary ao olhar para o filho.<br \/>\u2003\u2003N\u00e3o tinha o que falar, ele estava certo.<br \/>\u2003\u2003\u2014 Uau, me parece que o casamento de voc\u00eas est\u00e1 em crise. \u2014 comentou Siwon rindo baixo.<br \/>\u2003\u2003\u2014 Casamento? \u2014 Mary me olhou confusa.<br \/>\u2003\u2003\u2014 Bem, nos casamos em Vegas. \u2014 expliquei.<br \/>\u2003\u2003\u2014 Vegas? \u2014 Sam se jogou no sof\u00e1. \u2014 Noona, n\u00e3o sabia que casamentos em Vegas eram v\u00e1lidos.<br \/>\u2003\u2003\u2014 Alguns s\u00e3o. \u2014 Mary sorri. \u2014 Este \u00e9 mais que v\u00e1lido.<br \/>\u2003\u2003O senhor Hwang bufou um pouco e se levantando da poltrona, dirigiu-se em dire\u00e7\u00e3o ao seu escrit\u00f3rio, eu j\u00e1 imaginava que teria que pedir desculpas alguma hora, mas n\u00e3o estava muito preparada. Talvez %Suho% estivesse certo, eu era orgulhosa demais para me desculpar com as pessoas, mas pela primeira vez queria fazer isso, s\u00f3 n\u00e3o sabia como.<br \/>\u2003\u2003\u2014 N\u00e3o se preocupe, uma hora eles v\u00e3o entender. \u2014 disse Mary.<br \/>\u2003\u2003\u2014Talvez ele esteja certo, sou muito orgulhosa para fazer isso. \u2014 eu me virei em dire\u00e7\u00e3o a porta.<br \/>\u2003\u2003\u2014 Espera. \u2014 Mary segurou de leve em minha m\u00e3o. \u2014 Aonde vai, querida?<br \/>\u2003\u2003\u2014 Preciso pegar minha bolsa com o agente, minhas coisas ficaram no apartamento dele. \u2014 expliquei um pouco triste.<br \/>\u2003\u2003\u2014 Eu te levo. \u2014 disse Siwon ao retirar a chave do carro do bolso. \u2014 Assim n\u00e3o ter\u00e1 desculpas para n\u00e3o voltar.<br \/>\u2003\u2003\u2014 N\u00e3o precisa. \u2014 sorri de leve. \u2014 Meu cachorro est\u00e1 aqui, acha mesmo que n\u00e3o voltaria? E por falar nisso, onde est\u00e1 Cronos?<br \/>\u2003\u2003\u2014 Mandamos para o petshop, ele precisava relaxar. \u2014 explicou Mary.<br \/>\u2003\u2003\u2014 Seu cachorro \u00e9 muito bonito e educado. \u2014 elogiou Sam.<br \/>\u2003\u2003\u2014 Obrigada, eu o treinei muito bem.<br \/>\u2003\u2003\u2014 Vamos, cunhadinha, eu realmente irei te levar. \u2014 Siwon sorriu e pegando minha m\u00e3o me puxou para porta.<br \/>\u2003\u2003Eu o conhecia muito bem para saber que n\u00e3o desistiria de me levar, ent\u00e3o somente assenti e o segui at\u00e9 o carro.<br \/>\u2003\u2003\u2014 Est\u00e1 mesmo tudo bem agora? \u2014 perguntou ele ao ligar o carro.<br \/>\u2003\u2003\u2014 Sim, como sempre Dean pensou em tudo. \u2014 suspirei fraco.<br \/>\u2003\u2003\u2014 Voc\u00ea se lembra onde \u00e9 o apartamento do agente? \u2014 perguntou.<br \/>\u2003\u2003\u2014 Sim, mas eu n\u00e3o iria agora at\u00e9 l\u00e1. \u2014 respondi desviando meu olhar para a rua.<br \/>\u2003\u2003\u2014 Imaginei. \u2014 ele suspirou tamb\u00e9m. \u2014 Est\u00e1 assim por causa do meu irm\u00e3o.<br \/>\u2003\u2003\u2014 N\u00e3o me fa\u00e7a pensar nisso assim.<br \/>\u2003\u2003\u2014 LT, voc\u00ea realmente ama ele. \u2014 era uma confirma\u00e7\u00e3o. \u2014 Te conhecendo como conhe\u00e7o, est\u00e1 lutando contra.<br \/>\u2003\u2003\u2014 Confesso que nunca permiti que chegasse t\u00e3o longe. \u2014 ajustei o cinto de seguran\u00e7a e me encolhi.<br \/>\u2003\u2003\u2014 Como se voc\u00ea tivesse se envolvido com mais pessoas al\u00e9m de n\u00f3s dois. \u2014 ele riu baixo.<br \/>\u2003\u2003\u2014 Tem raz\u00e3o, o que me deixa ainda mais assustada. \u2014 desviei meu olhar para ele. \u2014 N\u00e3o sei o que %Suho% fez para eu gostar dele assim.<br \/>\u2003\u2003\u2014 Essa eu tamb\u00e9m quero saber. \u2014 ele deu uma gargalhada. \u2014 Ele roubou minha chance de te conquistar de verdade.<br \/>\u2003\u2003Eu ri um pouco desviando meu olhar para frente, Siwon era mesmo um bobo.<br \/>\u2003\u2003\u2014 Mesmo sendo charmoso, acho que nunca daria certo. \u2014 confessei.<br \/>\u2003\u2003\u2014 Por qu\u00ea? Sou muito quente? \u2014 ele riu mais alto. \u2014 N\u00e3o acredito que gosta de homens empacados como meu irm\u00e3o.<br \/>\u2003\u2003\u2014 Acredite ou n\u00e3o, o que me chamou a aten\u00e7\u00e3o nele foi a voz. \u2014 suspirei profundo agora. \u2014 Aquela voz\u2026<br \/>\u2003\u2003\u201c<em>Faz meu corpo arrepiar.\u201d<\/em> Completei em pensamento.<br \/>\u2003\u2003\u2014 Aquela voz? \u2014 insistiu Siwon.<br \/>\u2003\u2003\u2014 \u00c9 uma voz de impacto. \u2014 terminei disfar\u00e7ando.<br \/>\u2003\u2003\u2014 Hum, voz de impacto. \u2014 ele riu com ironia. \u2014 E eu, tenho uma voz de impacto?<br \/>\u2003\u2003\u2014 Digamos que seu ponto forte \u00e9 o olhar. \u2014 respondi tranquilamente. \u2014 Em raros momentos me pergunto como foi o romance que tiveram com aquela tal Taylor.<br \/>\u2003\u2003\u2014 Aquela tal Taylor\u2026 Hum, soou um ponta de ci\u00fames.<br \/>\u2003\u2003\u2014 Por que eu teria ci\u00fames? \u2014 o olhei.<br \/>\u2003\u2003\u2014 Est\u00e1 mesmo me fazendo esta pergunta? \u2014 Siwon riu. \u2014 N\u00e3o sei quem \u00e9 mais orgulhoso, voc\u00ea ou ele.<br \/>\u2003\u2003\u2014 Do que est\u00e1 falando. \u2014 desviei meu olhar para a janela. \u2014 N\u00e3o sou t\u00e3o orgulhosa assim.<br \/>\u2003\u2003\u2014 Sei.<br \/>\u2003\u2003\u2014 Estou sendo sincera, Siwon, s\u00f3 n\u00e3o estou acostumada com certos sentimentos. \u2014 cruzei os bra\u00e7os.<br \/>\u2003\u2003\u2014 Posso lhe dar um conselho? \u2014 perguntou.<br \/>\u2003\u2003\u2014 Claro.<br \/>\u2003\u2003\u2014 Pedir desculpas n\u00e3o \u00e9 o fim da vida, mas pode ser o come\u00e7o de uma nova. \u2014 se aquilo era algum tipo de frase feita, havia me impactado.<br \/>\u2003\u2003\u2014 Voc\u00ea adora frases de efeito. \u2014 comentei brincando.<br \/>\u2003\u2003\u2014 Fazendo efeito ou n\u00e3o, \u00e9 uma realidade que voc\u00ea pode viver. \u2014 seu tom ficou um pouco mais s\u00e9rio.<br \/>\u2003\u2003\u2014 Obrigada. \u2014 disse de repente.<br \/>\u2003\u2003\u2014 Pelo qu\u00ea?<br \/>\u2003\u2003\u2014 Por ser meu amigo, apesar de tudo. \u2014 aquilo foi sincero.<br \/>\u2003\u2003Passamos o dia todo dando algumas voltas por Paris, eu precisava daquele tempo de distra\u00e7\u00e3o e divers\u00e3o, Siwon tinha seu lado engra\u00e7ado e descontra\u00eddo que me fazia esquecer dos problemas, finalmente havia o definido como um verdadeiro amigo. O que me deixava ainda mais indecisa no que planejava para o futuro, uma fam\u00edlia era o \u00e1libi perfeito, por\u00e9m estava come\u00e7ando a se tornar um projeto de vida.<br \/>\u2003\u2003N\u00e3o demoramos muito ao passar no apartamento de Cedric, que colaborou n\u00e3o retendo meus documentos que estavam com ele, em minha bolsa. Assim que voltamos \u00e0 casa da fam\u00edlia Cho, eu senti que deveria talvez dar uma chance a frase de efeito de Siwon, ent\u00e3o assim que Mary me disse que seu marido estava no escrit\u00f3rio, decidi ter uma conversa com ele.<br \/>\u2003\u2003\u2014 Posso te incomodar? \u2014 disse ao bater na porta.<br \/>\u2003\u2003\u2014 Entre. \u2014 ele estava sentado na cadeira perto da janela.<br \/>\u2003\u2003\u2014 Acho que lhe devo algumas explica\u00e7\u00f5es, senhor Hwang. \u2014 disse fechando a porta. \u2014 E\u2026 Estou aqui para lhe dar.<br \/>\u2003\u2003\u2014 Dizer n\u00e3o vai mudar o que fez. \u2014 seu olhar era t\u00e3o observador quando o de %Suho% e Siwon, tinham a quem puxar. \u2014 Vai?<br \/>\u2003\u2003\u2014 Sei que n\u00e3o.<br \/>\u2003\u2003\u2014 Voc\u00ea entrou na minha casa, conquistou minha esposa e meus filhos, o que me entristece n\u00e3o foi trair minha confian\u00e7a, mas trair a de %Suho%. \u2014 mesmo firme e r\u00edgido na voz, seu olhar era tranquilo. \u2014 Sempre coloco os sentimentos deles antes dos meus, por isso est\u00e1 aqui, por isso ajudamos voc\u00ea, porque minha esposa a considera sua filha.<br \/>\u2003\u2003\u2014 Eu sei. \u2014 mantive meu olhar nele novamente. \u2014 Eu n\u00e3o sei como, mas quero reconquistar sua confian\u00e7a novamente, me diga como.<br \/>\u2003\u2003\u2014 Voc\u00ea sabe como.<br \/>\u2003\u2003O que era para ser um enigma me fez perceber que eu realmente sabia, at\u00e9 mesmo o senhor Hwang havia me perdoado sem que eu pedisse, mas havia um motivo para que ele n\u00e3o admitisse isso: %Suho%.<\/p>\r\n<p align=\"center\">\u201c<em>A resposta \u00e9 voc\u00ea<br \/>Minha resposta \u00e9 voc\u00ea<br \/>Eu te mostrei tudo de mim<br \/>Voc\u00ea \u00e9 o meu tudo, eu tenho certeza<br \/>Eu serei mais cuidadoso e te protegerei<br \/>Ent\u00e3o o seu cora\u00e7\u00e3o nunca ser\u00e1 machucado<br \/>Eu nunca me senti assim antes<br \/>Como se minha respira\u00e7\u00e3o fosse parar.\u201d<\/em><br \/><strong>&#8211; My Answer \/ EXO<\/strong><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>\u2003\u2003%Nalla% \u201cA resposta \u00e9 voc\u00eaMinha resposta \u00e9 voc\u00eaEu te mostrei tudo de mimVoc\u00ea \u00e9 o meu tudo, eu tenho certezaEu serei mais cuidadoso e te protegereiEnt\u00e3o o seu cora\u00e7\u00e3o nunca ser\u00e1 machucadoEu nunca me senti assim antesComo se minha respira\u00e7\u00e3o fosse parar.\u201d&#8211; My Answer \/ EXO<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"historias":[1661],"class_list":["post-4839","capitular","type-capitular","status-publish","format-standard","hentry","historias-my-little-thief"],"acf":[],"_links":{"self":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular\/4839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular"}],"about":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/types\/capitular"}],"author":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/comments?post=4839"}],"wp:attachment":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/media?parent=4839"}],"wp:term":[{"taxonomy":"historias","embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/historias?post=4839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}