{"id":4596,"date":"2025-01-21T09:48:00","date_gmt":"2025-01-21T12:48:00","guid":{"rendered":"https:\/\/espacocriativo.net\/acervo\/historia\/historia-sem-nome\/rascunho-automatico\/"},"modified":"2025-10-09T09:53:36","modified_gmt":"2025-10-09T12:53:36","slug":"capitulo-16","status":"publish","type":"capitular","link":"https:\/\/espacocriativo.net\/acervo\/historia\/mafias-paradise\/capitulo-16\/","title":{"rendered":"16"},"content":{"rendered":"\r\n<p align=\"right\"><strong>Toscana, inverno de 2020<\/strong><\/p>\r\n<p><span class=\"versalete\">\u2003\u2003Em meio ao recesso<\/span> da temporada de jogos do campeonato da liga italiana, intitulado de S\u00e9rie A, estava um casal desfrutando dos quentes cobertores, ta\u00e7as de vinho Ch\u00e2teau Cheval Blanc e muitas car\u00edcias. A vida de Matteo Ricci estava sendo um sonho do qual n\u00e3o queria acordar, afinal, era assim que ele se sentia. Sua carreira no futebol seguia promissora, jogando mais uma temporada pelo seu time de cora\u00e7\u00e3o, Fiorentina, al\u00e9m de receber muitos mimos da sua f\u00e3 n\u00famero 1.<br \/>\u2003\u2003\u2014 Hum\u2026 Fica aqui, estou com frio \u2014 resmungou a mulher, se encolhendo mais na cama.<br \/>\u2003\u2003\u2014 J\u00e1 volto \u2014 disse ele, dando um sorriso de canto.<br \/>\u2003\u2003Ao se espregui\u00e7ar, caminhou para fora do quarto e desceu as escadas. O apartamento duplex em que morava se localizava no bairro mais nobre de Floren\u00e7a, em um condom\u00ednio composto por dois pr\u00e9dios luxuosos, afastado do centro comercial. Sua inten\u00e7\u00e3o era fazer algo para matar a fome, pois suas energias haviam sido consumidas pelos desejos de sua amada. Contudo, antes mesmo de chegar \u00e0 cozinha, uma liga\u00e7\u00e3o vinda da portaria o desviou da rota. <em>O motivo?<\/em> Uma visita inesperada que o deixou est\u00e1tico a princ\u00edpio.<br \/>\u2003\u2003\u2014 Quando o porteiro me disse quem era, eu n\u00e3o acreditei \u2014 disse ele, ao abrir a porta e recepcionar sua visita.<br \/>\u2003\u2003A pessoa apenas sorriu de leve e adentrou o apartamento, o impressionando ainda mais.<br \/>\u2003\u2003\u2014 Amor, voc\u00ea est\u00e1 demorando\u2026 \u2014 A mulher que vinha do quarto, parou est\u00e1tica no meio da escada. \u2014 %Alice%?!<br \/>\u2003\u2003\u2014 Oi, Rosalia \u2014 cumprimentou a garota com um sorriso t\u00edmido.<br \/>\u2003\u2003\u2014 %Alice%! \u2014 Rosa terminou de descer os \u00faltimos degraus e correu para abra\u00e7\u00e1-la. \u2014 Amiga, por onde andou? Como nos achou aqui? Que surpresa.<br \/>\u2003\u2003\u2014 Surpresa estou eu com esse \u201c<em>amor\u201d<\/em> \u2014 ela riu ao olhar para a amiga que vestia uma camisa masculina, ent\u00e3o, desviou para Matteo \u2014 em seu vocabul\u00e1rio.<br \/>\u2003\u2003\u2014 Temos tantas coisas para te contar \u2014 comentou Matteo com um sorriso bobo.<br \/>\u2003\u2003\u2014 E voc\u00ea tamb\u00e9m para n\u00f3s \u2014 disse Rosalia em sua curiosidade pelo sumi\u00e7o da amiga. \u2014 Quando todos souberem da sua volta\u2026\u00a0<br \/>\u2003\u2003\u2014 Vai ser uma loucura \u2014 completou Matteo.<br \/>\u2003\u2003\u2014 Ningu\u00e9m pode saber que eu voltei \u2014 disse %Alice% um pouco aflita ao se lembrar do passado. \u2014 Principalmente os Magnus.<br \/>\u2003\u2003\u2014 %Ally%, voc\u00ea est\u00e1 praticamente em casa agora, toda a regi\u00e3o de Toscana \u00e9 controlada por eles. \u2014 Rosalia e seus argumentos racionais a puxaram para a realidade.<br \/>\u2003\u2003\u2014 Eu aprendi a ser discreta \u2014 disse a jovem confiante em suas palavras.<br \/>\u2003\u2003\u2014 Isso d\u00e1 para notar \u2014 brincou Matteo, rindo de leve. \u2014 Ficou fora do radar por cinco anos.<br \/>\u2003\u2003\u2014 Vim apenas por considera\u00e7\u00e3o aos meus melhores amigos. \u2014 Ela sorriu novamente. \u2014 E foi f\u00e1cil ach\u00e1-los, est\u00e3o nas revistas agora.<br \/>\u2003\u2003\u2014 Pois \u00e9, meu jogador favorito \u00e9 um craque famoso \u2014 brincou Rosa ao se afastar da amiga e ir se aninhar em Matteo.<br \/>\u2003\u2003\u2014 E qual o grau de considera\u00e7\u00e3o que a trouxe aqui, correndo o risco de se expor a todos? \u2014 indagou ele, curioso.<br \/>\u2003\u2003\u2014 Vou me casar! \u2014 %Alice% ergueu a m\u00e3o, mostrando o anel de noivado.<br \/>\u2003\u2003\u2014 O qu\u00ea? \u2014 disseram ambos, o casal, boquiabertos.<br \/>\u2003\u2003\u2014 E quero que sejam meus padrinhos \u2014 completou %Ally%, com um brilho no olhar.<br \/>\u2003\u2003Mesmo surpresos, o casal se alegrou com a felicidade da amiga e a abra\u00e7ou com felicita\u00e7\u00f5es. Os cinco anos de sil\u00eancio da parte de %Alice% haviam sido uma experi\u00eancia \u00fanica para ela, que passou a conhecer mais o mundo em que estava inserida da forma mais inesperada poss\u00edvel.<br \/>\u2003\u2003\u2014 Agora trate de sentar aqui e ir me contando tudo, senhorita. \u2014 Rosalia a puxou para o sof\u00e1, sentando com ela sob um olhar curioso. \u2014 Por onde andou todo esse tempo?<br \/>\u2003\u2003\u2014 Estive bem longe e escondida \u2014 respondeu %Alice% num tom carism\u00e1tico.<br \/>\u2003\u2003\u2014 Voc\u00ea realmente parece feliz longe de tudo aqui \u2014 comentou Matteo ao permanecer de p\u00e9, encostado na parede. \u2014 Seu rosto est\u00e1 mais reluzente.<br \/>\u2003\u2003\u2014 Isso \u00e9 o amor \u2014 comentou Rosalia seu palpite.<br \/>\u2003\u2003\u2014 N\u00e3o, \u00e9 liberdade \u2014 corrigiu %Alice%, dando um suspiro animado. \u2014 Estou t\u00e3o feliz, conheci tantas pessoas legais ao longo desses anos e\u2026 Pela primeira vez consegui ter sonhos e planos para o futuro.<br \/>\u2003\u2003\u2014 Isso \u00e9 o que importa, que esteja bem. \u2014 Assentiu Rosa, com um sorriso sutil no rosto. \u2014 E qual o nome do felizardo?<br \/>\u2003\u2003\u2014 Tom\u00e1s Coimbra \u2014 respondeu ela, soltando outro suspiro com um toque de apaixonada.<br \/>\u2003\u2003\u2014 Sobrenome portugu\u00eas, era l\u00e1 que\u00a0voc\u00ea estava? \u2014 indagou Matteo, reconhecendo a origem do sobrenome.<br \/>\u2003\u2003\u2014 Sim, como sabe? \u2014 perguntou %Alice% surpresa com sua precis\u00e3o.<br \/>\u2003\u2003\u2014 Sou jogador, j\u00e1 tive algumas partidas com times portugueses pela Europa League, conheci um jogador do Benfica com esse sobrenome \u2014 explicou ele.<br \/>\u2003\u2003\u2014 Estive morando ao norte da cidade de Braga, depois de passar por v\u00e1rias cidades aleat\u00f3rias da Europa \u2014 contou %Alice%, parte de sua hist\u00f3ria. \u2014 Foi l\u00e1 que conheci ele, era um dia de chuva e presenciei o atropelamento de um cachorro, o motorista n\u00e3o quis prestar socorro e eu, apavorada, peguei o animal e sa\u00ed correndo em busca de socorro, ele estava passando de bicicleta e me viu. Logo me apaixonei por um veterin\u00e1rio fofo.<br \/>\u2003\u2003\u2014 Que meigo. \u2014 Rosalia fez uma cara boba, imaginando a cena. \u2014 Quase uma fanfic, amiga.<br \/>\u2003\u2003\u2014 Sim. \u2014 Assentiu %Alice%.<br \/>\u2003\u2003\u2014 E quando vamos conhec\u00ea-lo? \u2014 perguntou Matteo curioso.<br \/>\u2003\u2003\u2014 Bem, convido voc\u00eas para nosso jantar de ensaio do casamento \u2014 respondeu ela. \u2014 Ser\u00e1 na pr\u00f3xima sexta, estamos planejando a cerim\u00f4nia para o final de janeiro \u2014 explicou ela, os planos do casal. \u2014 Tom\u00e1s quer passar a lua de mel no Brasil e voltar antes do carnaval.<br \/>\u2003\u2003\u2014 Que sonho! \u2014 Rosalia sentiu uma pontinha de inveja, pois j\u00e1 havia falado sobre casamento algumas vezes com Matteo, entretanto, o jogador no auge de sua carreira, optou por focar em treinos e nos jogos, n\u00e3o querendo um compromisso que lhe roubasse a aten\u00e7\u00e3o. Para ele, casamento era algo s\u00e9rio e seu momento atual estava atrelado ao esporte, o que n\u00e3o o deixaria dar a aten\u00e7\u00e3o devida a sua esposa e fam\u00edlia.<br \/>\u2003\u2003\u2014 Posso contar com voc\u00eas l\u00e1? \u2014 indagou %Alice%.<br \/>\u2003\u2003\u2014 Mas \u00e9 claro que sim, mande o endere\u00e7o, por favor \u2014 pediu Rosa, afirmando a presen\u00e7a deles. \u2014 Os jogos de Matteo est\u00e3o em recesso pelas festividades do final do ano e a primeira semana do ano nunca tem nada de especial para fazer.<br \/>\u2003\u2003\u2014 E a senhorita n\u00e3o trabalha? \u2014 perguntou %Alice% impressionada. \u2014 E por falar em trabalho, como se deu o meu shipp de inf\u00e2ncia?<br \/>\u2003\u2003\u2014 Claro que eu trabalho, e foi atrav\u00e9s do meu trabalho que este shipp aconteceu \u2014 contou ela, recordando o dia em que reviu seu melhor amigo no trabalho. \u2014 Por ironia do destino, trabalho como T.I para a FIFA, e em um dos eventos da federa\u00e7\u00e3o eu precisei participar, afinal, sendo integrante da equipe de tecnologia, n\u00e3o posso me ausentar dessas ocasi\u00f5es, e foi l\u00e1 que esbarrei no melhor jogador do Fiorentina.<br \/>\u2003\u2003\u2014 Que fofo, sempre torci por voc\u00eas, um completa o outro \u2014 disse %Alice%.\u00a0<br \/>\u2003\u2003\u2014 Antes eu vivia em Londres, mas agora eu trabalho home office s\u00f3 para termos mais tempo juntos \u2014 completou Rosalia.<br \/>\u2003\u2003\u2014 Resumindo, eu me tornei jogador e ela se apaixonou por mim, bem conforme o planejado \u2014 brincou Matteo, arrancando um olhar atravessado de sua amada.<br \/>\u2003\u2003%Alice% caiu em gargalhadas, lembrando-se da \u00e9poca da escola. No fundo, sentia falta daqueles momentos, de estar com os amigos em uma conversa saud\u00e1vel e tranquila, chegar em casa e receber um abra\u00e7o caloroso da m\u00e3e. De certa forma, ela sentia falta de partes de sua vida em Toscana.<br \/>\u2003\u2003\u2014 A conversa est\u00e1 maravilhosa, mas eu preciso ir \u2014 disse %Alice% ao se levantar do sof\u00e1. \u2014 Meu avi\u00e3o parte daqui algumas horas, tenho que voltar para Braga.<br \/>\u2003\u2003\u2014 Mas j\u00e1?! \u2014 Rosa se levantou juntamente, demonstrando tristeza por sua passagem t\u00e3o r\u00e1pida ap\u00f3s anos longe. \u2014 Dorme aqui esta noite, vamos conversar mais.<br \/>\u2003\u2003\u2014 N\u00e3o posso, prometi ao Tom\u00e1s que voltaria hoje \u2014 respondeu ela. \u2014 Mas\u2026 Te quero na segunda em Lisboa para me ajudar com a escolha do vestido.<br \/>\u2003\u2003\u2014 S\u00e9rio? \u2014 Rosa se mostrou honrada pelo convite.<br \/>\u2003\u2003\u2014 Claro, voc\u00ea \u00e9 minha madrinha de casamento \u2014 garantiu %Alice%. \u2014 Preciso de suas opini\u00f5es de moda.<br \/>\u2003\u2003\u2014 Com prazer \u2014 brincou Rosa.<br \/>\u2003\u2003%Alice%, em risos, se despediu dos amigos e retirou-se do apartamento deles. Passou alguns minutos esperando pelo elevador, at\u00e9 que o mesmo chegou ao andar vindo da cobertura. Assim que a porta abriu, o cora\u00e7\u00e3o de %Alice% gelou de imediato ao se deparar com a \u00faltima pessoa que havia tido contato no passado.<br \/>\u2003\u2003Ap\u00f3s segundos de sil\u00eancio.<br \/>\u2003\u2003\u2014 Pode entrar, eu n\u00e3o mordo e nem sou uma assombra\u00e7\u00e3o. \u2014 A voz de %Luigi% causou um frio na espinha dela, ele continuou com o dedo no bot\u00e3o, mantendo a porta aberta. \u2014 J\u00e1 voc\u00ea, %Alice%.<br \/>\u2003\u2003\u2014 Senhor Magnus. \u2014 Ela engoliu seco, dando o primeiro passo para entrar.<br \/>\u2003\u2003Ap\u00f3s tantas pesquisas e cuidados, planejamentos de como entraria e sairia de Toscana sem ser vista ou notada, ali estava ela diante de uma poss\u00edvel amea\u00e7a de exposi\u00e7\u00e3o. Ela sentiu seu corpo tr\u00eamulo pelo medo eminente, e %Luigi%, percebendo, riu de leve.<br \/>\u2003\u2003\u2014 N\u00e3o precisa se preocupar\u2026 N\u00f3s compartilhamos do mesmo segredo. \u2014 Mais uma vez ele quebrou o sil\u00eancio. \u2014 N\u00e3o vou contar ao meu irm\u00e3o\u2026 Mas voc\u00ea deveria ser mais discreta ainda, eu disse para n\u00e3o procurar por seus amigos.<br \/>\u2003\u2003\u2014 Eu apenas\u2026 \u2014 Ela respirou fundo quando se lembrou que precisava respirar.<br \/>\u2003\u2003Sabia que era arriscado estar ali, ele tinha raz\u00e3o.<br \/>\u2003\u2003\u2014 Acha mesmo que meu irm\u00e3o desistiria de vigi\u00e1-los mesmo depois de tantos anos? \u2014 perguntou %Luigi%, fazendo-a refletir.<br \/>\u2003\u2003\u2014 O que fa\u00e7o agora? \u2014 sussurrou %Ally%, quase pedindo clem\u00eancia.<br \/>\u2003\u2003\u2014 Des\u00e7a at\u00e9 o estacionamento e saia pela lateral do pr\u00e9dio, pelo acesso dos funcion\u00e1rios \u2014 disse ele, mantendo sua serenidade, como se o caso n\u00e3o fosse t\u00e3o cr\u00edtico assim.<br \/>\u2003\u2003\u2014 Por que est\u00e1 me ajudando novamente? \u2014 perguntou ela, intrigada pelas a\u00e7\u00f5es dele, lembrando-se da forma em que o ca\u00e7ula a aterrorizava quando crian\u00e7a.<br \/>\u2003\u2003%Luigi% apenas sorriu de canto e assim que o elevador parou no andar no hall de entrada, ele apertou o bot\u00e3o do estacionamento e saiu ao abrir a porta.<br \/>\u2003\u2003\u2014 Tente ser mais discreta, se ele te encontrar, n\u00e3o ter\u00e1 mais a minha ajuda. \u2014 Com essas palavras, ele manteve seu olhar s\u00e9rio para ela at\u00e9 o fechar da porta.<br \/>\u2003\u2003Com o cora\u00e7\u00e3o acelerado, %Alice% seguiu passo a passo as recomenda\u00e7\u00f5es do Magnus ca\u00e7ula, conseguindo com sucesso chegar ao aeroporto e embarcar em seu voo de volta para Braga. Minutos depois de o avi\u00e3o aterrissar, soltou um suspiro de al\u00edvio ao encontrar o noivo a esperando no sagu\u00e3o de desembarque.<br \/>\u2003\u2003\u2014 Desculpe a demora, o avi\u00e3o teve uma turbul\u00eancia \u2014 explicou ela ao se aproximar dele.<br \/>\u2003\u2003\u2014 Fiquei preocupado \u2014 disse ele ao abra\u00e7\u00e1-la forte. \u2014 N\u00e3o deveria ter ido sozinha, cinco horas de voo.<br \/>\u2003\u2003\u2014 O que importa \u00e9 que estou aqui. \u2014 Ela sorriu de leve. \u2014 Vamos para casa?<br \/>\u2003\u2003\u2014 Claro. \u2014 Ele pegou a mochila que estava com ela, para carregar. \u2014 Como foi rever seus amigos?<br \/>\u2003\u2003\u2014 Foi bem nost\u00e1lgico, muitas lembran\u00e7as do passado \u2014 contou %Alice%. \u2014 Como previ, Rosa e Matteo est\u00e3o juntos como casal.<br \/>\u2003\u2003\u2014 Voc\u00ea \u00e9 boa em previs\u00f5es \u2014 brincou Tom\u00e1s, lembrando-se de quando a conheceu no dia do resgate. \u2014 Tamb\u00e9m previu que seria minha esposa.<br \/>\u2003\u2003\u2014 Voc\u00ea me deixou encantada a primeiro momento, ent\u00e3o\u2026 Claro que n\u00e3o deixaria passar a oportunidade.<br \/>\u2003\u2003\u2014 Hum\u2026 Como se tivesse sido dif\u00edcil me apaixonar por voc\u00ea \u2014 comentou ele, rindo baixo, ent\u00e3o lhe roubou um beijo. \u2014 Voc\u00ea \u00e9 um encanto, %Alice% Miller.<br \/>\u2003\u2003Estrategicamente, ambos moravam no mesmo pr\u00e9dio, em andares diferentes. %Alice% na companhia do cachorro salvo de nome Xerife, e ele na companhia de seus pais j\u00e1 avan\u00e7ados de idade. Tom\u00e1s tinha mais duas irm\u00e3s, j\u00e1 casadas, e sendo tio de tr\u00eas crian\u00e7as sapecas, seu sonho de ser pai aumentava a cada dia com a expectativa do casamento. Ap\u00f3s se despedirem nas escadas, %Alice% adentrou seu apartamento solit\u00e1rio e foi recepcionada por Xerife. O c\u00e3o, mesmo velhinho, ainda tinha energia para latir como se desse boas-vindas a sua tutora.<br \/>\u2003\u2003\u2014 Est\u00e1 com fome? \u2014 perguntou ela, sorrindo para ele e seguindo at\u00e9 a cozinha. \u2014 Vamos comer um pouco.<\/p>\r\n<p>\u2003\u2003Os dias se passaram e finalmente na segunda, como combinado, as amigas estavam na loja CasArt, uma das mais conceituadas em vestidos para noivas.\u00a0<br \/>\u2003\u2003\u2014 Ah n\u00e3o, este est\u00e1 muito antiquado \u2014 reclamou Rosalia ao lhe fazer experimentar o sexto vestido consecutivo. \u2014 Precisamos de um mais moderno.<br \/>\u2003\u2003\u2014 Nenhum est\u00e1 bom o suficiente para voc\u00ea \u2014 disse %Alice%, rindo da careta da amiga. \u2014 Eu gostei do segundo.<br \/>\u2003\u2003\u2014 O segundo tem muita renda, n\u00e3o combina com sua delicada simplicidade \u2014 explicou a outra, entendendo o estilo de %Ally%.<br \/>\u2003\u2003\u2014 Que tal este aqui \u2014 disse a atendente, apresentando outra op\u00e7\u00e3o. \u2014 Sem renda, com a modelagem estilo princesa, tomara de caia, sem luvas e sem v\u00e9u.<br \/>\u2003\u2003\u2014 Perfeito, t\u00e3o sutil e nem um pouco extravagante, tenho certeza que ser\u00e1 uma linda noiva \u2014 disse Rosa, certa da escolha.<br \/>\u2003\u2003\u2014 Vou experiment\u00e1-lo ent\u00e3o. \u2014 Assentiu %Alice%.<br \/>\u2003\u2003Assim que retornou do provador, recebeu os aplausos da amiga e da atendente, fazendo-a rir de leve e se sentir a mulher mais feliz do mundo. Em um piscar de olhos, sua aten\u00e7\u00e3o se moveu para a vitrine da loja, permitindo-a focalizar a rua, por um curto espa\u00e7o de tempo, %Alice% ficou paralisada com a poss\u00edvel cena do outro lado da rua. Seus olhos pareciam reconhecer o rosto do homem a quem se escondeu todo aquele tempo, o que a fez entrar em agonia interna.<br \/>\u2003\u2003\u2014 %Alice%?! %Alice%?! \u2014 Logo a voz de Rosa chamou-a para a realidade, fazendo ela desviar a aten\u00e7\u00e3o para a amiga.<br \/>\u2003\u2003\u2014 O qu\u00ea?! \u2014 perguntou a jovem.<br \/>\u2003\u2003\u2014 O que, perguntou eu. Voc\u00ea ficou paralisada. \u2014 Rosa olhou para tr\u00e1s, analisando a vitrine. \u2014 Viu alguma coisa?<br \/>\u2003\u2003\u2014 N\u00e3o\u2026 Eu\u2026 \u2014 %Alice% voltou novamente o olhar para a mesma dire\u00e7\u00e3o anterior e viu o local vazio. \u2014 N\u00e3o \u00e9 nada, acho que s\u00f3 estresse e ansiedade pelo casamento.<br \/>\u2003\u2003No restante do dia, a jovem tentou disfar\u00e7ar sua preocupa\u00e7\u00e3o. Ser\u00e1 que o que havia visto era real, ou apenas sua mente querendo se prender novamente ao passado do qual se libertou? Precisou se esfor\u00e7ar ainda mais, para n\u00e3o demonstrar isso em seu jantar de ensaio.<\/p>\r\n<p align=\"center\"><strong>&#8212;<\/strong><\/p>\r\n<p>\u2003\u2003O dia do casamento para uma noiva sempre foi considerado um misto de emo\u00e7\u00f5es e expectativas. Para %Alice%, seria uma data especial para a qual havia se preparado durante tanto tempo. Sua prepara\u00e7\u00e3o seria no hotel, onde a cerim\u00f4nia seria realizada em seu espa\u00e7o vip, um quarto de luxo reservado para a noiva que havia aproveitado a noite anterior com sua madrinha e cunhadas, em uma despedida de solteira regada a filmes de romance na Netflix e muita pipoca doce envolvida. Rosalia parecia mais empolgada que a noiva. Logo pela manh\u00e3, todas se levantaram \u00e0s pressas por estarem atrasadas para a maquiagem e cabelo, e ap\u00f3s tudo pronto, a jovem Miller pediu para ficar sozinha por alguns minutos em sua su\u00edte.<br \/>\u2003\u2003\u2014 N\u00e3o poderei ter arrependimentos depois de hoje \u2014 sussurrou ela ao pegar o buqu\u00ea de rosas brancas e voltar seu olhar para o espelho diante dela.<br \/>\u2003\u2003%Alice% ficou est\u00e1tica de imediato quando seus olhos ficaram no reflexo da pessoa que jamais esperava ver naquele dia. Seu cora\u00e7\u00e3o acelerou pela agonia do momento, com sua mente sendo preenchida pelas mem\u00f3rias do passado.\u00a0<br \/>\u2003\u2003\u2014 Bom dia, %Alice%. \u2014 A voz grossa e fria de %Giovanni% a fez sentir uma onda de calafrio, seguido de uma fraqueza interna que a fez soltar o buqu\u00ea em sua m\u00e3o.<br \/>\u2003\u2003Aquele momento caracterizava o fim do ciclo de cinco anos\u2026<br \/>\u2003\u2003Cinco anos longe de todos que conhecia\u2026\u00a0<br \/>\u2003\u2003Cinco anos de paz e liberdade&#8230;\u00a0<br \/>\u2003\u2003Cinco anos de discri\u00e7\u00e3o\u2026<br \/>\u2003\u2003Cinco anos de segredos\u2026<br \/>\u2003\u2003Cinco anos que n\u00e3o via aquele olhar nebuloso e intenso em sua dire\u00e7\u00e3o.<\/p>\r\n<p align=\"right\">But I know I&#8217;ll be hunting high and low <br \/>High <br \/>There&#8217;s no end to the lengths I&#8217;ll go to. <br \/><strong>&#8211; Hunting High And Low \/ A-ha<\/strong><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Toscana, inverno de 2020 &#8212; But I know I&#8217;ll be hunting high and low High There&#8217;s no end to the lengths I&#8217;ll go to. &#8211; Hunting High And Low \/ A-ha<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"historias":[1611],"class_list":["post-4596","capitular","type-capitular","status-publish","format-standard","hentry","historias-mafias-paradise"],"acf":[],"_links":{"self":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular\/4596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular"}],"about":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/types\/capitular"}],"author":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/comments?post=4596"}],"wp:attachment":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/media?parent=4596"}],"wp:term":[{"taxonomy":"historias","embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/historias?post=4596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}