{"id":4587,"date":"2024-04-07T09:29:00","date_gmt":"2024-04-07T12:29:00","guid":{"rendered":"https:\/\/espacocriativo.net\/acervo\/historia\/historia-sem-nome\/rascunho-automatico\/"},"modified":"2025-10-09T09:31:52","modified_gmt":"2025-10-09T12:31:52","slug":"capitulo-10","status":"publish","type":"capitular","link":"https:\/\/espacocriativo.net\/acervo\/historia\/mafias-paradise\/capitulo-10\/","title":{"rendered":"10"},"content":{"rendered":"\r\n<p align=\"right\"><strong>Mil\u00e3o, ver\u00e3o de 2015<\/strong><\/p>\r\n<p><span class=\"versalete\">\u2003\u2003A brisa fresca de<\/span> um amanhecer de ver\u00e3o adentrava a sala de projetos da conceituada <em>Politecnico di Milano<\/em>, a universidade italiana refer\u00eancia em mobili\u00e1rio no mundo, na qual a jovem Tommaso havia conquistado uma vaga no curso de Artes e Design, com foco em Design de Produto. Aquela era a paix\u00e3o da jovem, que fora influenciada pela m\u00e3e desde crian\u00e7a a se encantar com o universo dos m\u00f3veis contempor\u00e2neos. Sabendo desde o in\u00edcio qual caminho seguiria academicamente, n\u00e3o foi surpresa quando recebeu a carta de aceita\u00e7\u00e3o de sua universidade.<br \/>\u2003\u2003Retornar para casa foi sua melhor decis\u00e3o com rela\u00e7\u00e3o aos estudos.<br \/>\u2003\u2003\u2014 Tommaso. \u2014 A voz de um dos monitores soou da porta. \u2014 Ainda aqui?<br \/>\u2003\u2003\u2014 Andreas. \u2014 Ela manteve o olhar na prancha de desenhos ao respond\u00ea-lo, demonstrando concentra\u00e7\u00e3o.<br \/>\u2003\u2003\u2014 A caloura do colegial querendo mostrar seu talento ao mundo \u2014 brincou ele, se aproximando com cuidado.<br \/>\u2003\u2003%Clarice% era um dos casos raros em que se iniciava a faculdade sem completar a idade certa, finalizando o ensino m\u00e9dio antes do tempo. A jovem era muito inteligente e esperta, conseguindo assim pular o \u00faltimo ano e avan\u00e7ar para o ensino superior.<br \/>\u2003\u2003\u2014 O que faz aqui, Riina? \u2014 perguntou ela, chamando-o pelo sobrenome, ao parar de desenhar e olh\u00e1-lo. \u2014 Pelo que sei, est\u00e1 bem longe das salas de T.I.<br \/>\u2003\u2003\u2014 Princesa, esqueceu que sou o monitor dos laborat\u00f3rios e dos ateli\u00eas de desenho? \u2014 Lembrou ele, sua fun\u00e7\u00e3o importante ali. \u2014 Estava checando as salas e percebi que n\u00e3o devolveram a chave desta.<br \/>\u2003\u2003\u2014 Hum\u2026 \u2014 Ela deu de ombros e voltou a aten\u00e7\u00e3o para a prancheta em sua frente, retornando ao desenho. \u2014 Eu tenho autoriza\u00e7\u00e3o para usar a sala durante a madrugada e j\u00e1 estou finalizando isso aqui, ent\u00e3o, pode ir.<br \/>\u2003\u2003\u2014 Que menina doida\u2026 \u2014 comentou o rapaz, com um tom de piada. \u2014 Passar a madrugada estudando, eu jamais faria isso.<br \/>\u2003\u2003\u2014 Voc\u00ea passa a noite jogando e eu n\u00e3o te critico \u2014 retrucou ela.<br \/>\u2003\u2003\u2014 Jogar \u00e9 divers\u00e3o \u2014 explicou ele, com orgulho de suas palavras.<br \/>\u2003\u2003\u2014 Hum\u2026 \u2014 Ela riu baixo. \u2014 Eu funciono melhor \u00e0 noite, s\u00f3 isso.<br \/>\u2003\u2003\u2014 Assim que terminar, feche a sala e devolva as chaves \u2014 pediu ele, se afastando novamente e seguindo para a porta.<br \/>\u2003\u2003\u2014 Fique tranquilo, querido monitor, n\u00e3o vou te prejudicar \u2014 brincou ela, rindo baixo, tra\u00e7ando mais uma linha em seu desenho.<br \/>\u2003\u2003\u2014 Ah\u2026 Antes que me esque\u00e7a, voc\u00ea vai na festa do %Luigi% no final da semana? \u2014 perguntou Andreas, curioso.<br \/>\u2003\u2003\u2014 S\u00e9rio que est\u00e1 me perguntando isso? \u2014 %Clarice% o olhou, dando a certeza de sua resposta em sua face serena.<br \/>\u2003\u2003Ela jamais faltaria em algum evento da mans\u00e3o Magnus.<br \/>\u2003\u2003Riina saiu rindo. Mais alguns minutos em sil\u00eancio e concentra\u00e7\u00e3o, at\u00e9 que ela finalizou o desenho em sua frente e, com cuidado, retirou a folha e a guardou no tubo. Recolhendo seus materiais para colocar na bolsa, o celular de %Clarice% tocou, fazendo-a atender enquanto caminhava em dire\u00e7\u00e3o \u00e0 recep\u00e7\u00e3o para devolver as chaves.<br \/>\u2003\u2003\u2014 Giorgia? \u2014 disse Tommaso ao atender.<br \/>\u2003\u2003\u2014 <em>Bongiorno, amiga!<\/em> \u2014 A voz da garota soou com entusiasmo.<br \/>\u2003\u2003\u2014 J\u00e1 chegou na It\u00e1lia? \u2014 indagou, surpresa pela liga\u00e7\u00e3o naquela hora da manh\u00e3. \u2014 Achei que seu voo chegasse no almo\u00e7o.<br \/>\u2003\u2003\u2014 <em>Sim, eu consegui adiantar<\/em> \u2014 explicou a outra, tentando se conter na empolga\u00e7\u00e3o. \u2014 <em>Estava ansiosa para te contar as novidades, para colocarmos o assunto em dia e saber como est\u00e1 minha amiga na faculdade.<\/em><br \/>\u2003\u2003\u2014 Eu estou muito bem, obrigada por se preocupar. \u2014 %Clarice% riu um pouco, ajeitando a bolsa no ombro e pegando o tubo em seguida. \u2014 E voc\u00ea? Animada para rever todo mundo no final de semana? Nossas f\u00e9rias de ver\u00e3o come\u00e7am oficialmente com a festa do %Luigi%.<br \/>\u2003\u2003\u2014 <em>Mas \u00e9 claro que estou super animada, com meu cora\u00e7\u00e3o a mil para v\u00ea-lo de novo.<\/em> \u2014 contou Giorgia, soltando um suspiro bobo em seguida.<br \/>\u2003\u2003\u2014 Voc\u00ea ainda nutre essa paixonite pelo %Luigi%? \u2014 perguntou Tommaso, se preocupando com a amiga.\u00a0<br \/>\u2003\u2003Ao finalmente chegar \u00e0 recep\u00e7\u00e3o, apenas mostrou as chaves ao atendente, e continuou com sua aten\u00e7\u00e3o \u00e0 liga\u00e7\u00e3o, enquanto assinava o recibo de devolu\u00e7\u00e3o.\u00a0\u00a0<br \/>\u2003\u2003\u2014 <em>Juro que tentei, mas depois que perdi minha virgindade com ele h\u00e1 dois anos, n\u00e3o consigo esquec\u00ea-lo<\/em> \u2014 choramingou ela, sua realidade sentimental.<br \/>\u2003\u2003\u2014 Eu disse para n\u00e3o fazer isso. \u2014 %Clarice% soltou um suspiro cansado ao parar no centro do corredor, lembrando-se das muitas vezes que recebeu liga\u00e7\u00f5es da amiga, com desabafos regados a l\u00e1grimas.<br \/>\u2003\u2003Giorgia, para surpresa dos pais, havia escolhido seguir carreira m\u00e9dica para seu futuro acad\u00eamico, por isso, agora seguia terminando o ensino m\u00e9dio em um col\u00e9gio preparat\u00f3rio de Oxford. Morar em uma rep\u00fablica se tornou a maior aventura que ela imaginaria viver longe de casa, ainda que soubesse que no pr\u00f3ximo ano, seu tempo livre seria ocupado pelos estudos intensos que seu curso lhe exigiria.<br \/>\u2003\u2003\u2014 <em>N\u00e3o \u00e9 tempo de repreens\u00e3o, j\u00e1 temos dezessete anos e muitos erros para viver <\/em>\u2014 brincou ela, soltando uma gargalhada maliciosa.<br \/>\u2003\u2003\u2014 Com quem voc\u00ea tem andado ultimamente? \u2014 %Clarice% n\u00e3o estava reconhecendo sua miga pelas palavras que ela pronunciava.<br \/>\u2003\u2003Dando impulso no corpo, Tommaso voltou a caminhar em dire\u00e7\u00e3o \u00e0 sa\u00edda.<br \/>\u2003\u2003\u2014 <em>Fiz algumas amizades com a elite de Oxford ap\u00f3s me mudar para l\u00e1<\/em> \u2014 contou Giorgia, voltando \u00e0 anima\u00e7\u00e3o. \u2014 <em>Minhas colegas de rep\u00fablica s\u00e3o bem animadas.<\/em><br \/>\u2003\u2003\u2014 Deu para sentir\u2026 \u2014 %Clarice% parou em frente ao seu carro e retirou a chave do bolso da cal\u00e7a pantalona que vestia. \u2014 Vou dirigir agora, terei que desligar.<br \/>\u2003\u2003\u2014 <em>Nos vemos apenas no s\u00e1bado, ent\u00e3o?<\/em> \u2014 indagou Giorgia, num tom desanimado.<br \/>\u2003\u2003\u2014 Eu passei a noite em claro, desenhando\u2026 Preciso dormir agora, mas se quiser, podemos fazer a noite das garotas \u2014 sugeriu, pensando em algumas programa\u00e7\u00f5es noturnas. \u2014 Se ainda estiver no aeroporto, pegue um jatinho e venha a Mil\u00e3o.<br \/>\u2003\u2003\u2014 <em>Gostei da ideia, te encontro onde? <\/em>\u2014 perguntou a amiga, ao parar diante do t\u00e1xi que iria pegar.<br \/>\u2003\u2003\u2014 Pub <strong><em>Del Fiore<\/em><\/strong> \u2014 disse convicta de que sua noite com a amiga seria divertida e cheia de aventuras.<br \/>\u2003\u2003\u2014 <em>Me aguarde l\u00e1<\/em>. \u2014 Assentiu ela, prontamente.<br \/>\u2003\u2003%Clarice% soltou uma risada boba ao encerrar a liga\u00e7\u00e3o, estava mesmo sentindo falta da amiga que antes t\u00edmida, agora n\u00e3o parecia nem um pouco a garota medrosa que n\u00e3o queria morar na Inglaterra sozinha. Assim que Tommaso ergueu a m\u00e3o com a chave e apertou o bot\u00e3o para destravar o carro, uma m\u00e3o masculina tomou as chaves dela, deixando-a surpresa.<br \/>\u2003\u2003\u2014 O que pensa que est\u00e1 fazendo?! \u2014 indagou ela ao homem que se colocou em sua frente.<br \/>\u2003\u2003\u2014 A senhorita passou a noite em claro desenhando, n\u00e3o possui capacidade motora para enfrentar o volante, ent\u00e3o, n\u00e3o posso permitir que dirija neste estado \u2014 respondeu o homem com serenidade, mantendo o olhar fixo nela.<br \/>\u2003\u2003\u2014 N\u00e3o o pago para que me d\u00ea sua permiss\u00e3o \u2014 reclamou a garota ao tentar retirar as chaves do carro das m\u00e3os do rapaz, sem sucesso.<br \/>\u2003\u2003\u2014 Claro que n\u00e3o, senhorita Tommaso \u2014 confirmou ele, calmamente \u2014, eu sou pago pelo seu pai para garantir sua prote\u00e7\u00e3o, principalmente de si mesma.<br \/>\u2003\u2003%Clarice% bufou, ao sentir uma ponta de sarcasmo vindo dele.\u00a0<br \/>\u2003\u2003\u2014 Do que est\u00e1 falando? Eu jamais me colocaria em risco, senhor Salvatore \u2014 retrucou ela, deixando sobressair seu olhar empoderado.<br \/>\u2003\u2003\u2014 Por isso, a senhorita n\u00e3o se importar\u00e1 em entrar no banco de tr\u00e1s. \u2014 Ele abriu a porta de imediato para que ela entrasse.<br \/>\u2003\u2003%Clarice% respirou fundo, controlando sua raiva. Estava cansada demais para discutir com seu novo seguran\u00e7a e precisava de horas de sono para aplacar a dor de cabe\u00e7a que sentia h\u00e1 horas. Assentindo, ainda contrariada, ela adentrou o carro e ajustou o cinto de seguran\u00e7a. Para a jovem, n\u00e3o havia necessidade de ter um seguran\u00e7a vinte e quatro horas a vigiando, por\u00e9m, este havia sido um acordo feito com o pai, em troca de seu direito a escolha pelo curso de gradua\u00e7\u00e3o.<br \/>\u2003\u2003Para sua surpresa, o funcion\u00e1rio rec\u00e9m-contratado seguia demonstrando completa efici\u00eancia e profissionalismo, principalmente na parte em que entregava um detalhado relat\u00f3rio di\u00e1rio ao chefe Elio Tommaso, de todos os passos da filha. Se o objetivo de %Vincenzo% Salvatore era irritar a princesinha de Mil\u00e3o e ganhar a confian\u00e7a do chefe, ele certamente estava no caminho certo.<\/p>\r\n<hr \/>\r\n<p>\u2003\u2003%Clarice% nunca teve problemas em escolher uma roupa de acordo com a ocasi\u00e3o, suas no\u00e7\u00f5es de moda sempre foram de causar inveja na irm\u00e3 mais nova, e arrancar elogios da mais velha. Ap\u00f3s menos de um minuto se encarando no espelho como se estivesse se imaginando com os poss\u00edveis looks do closet, ela escolheu um leve vestido floral para aproveitar a brisa fresca da esta\u00e7\u00e3o, uma sand\u00e1lia nos p\u00e9s e a bolsa da Colcci, j\u00e1 equipada com o biqu\u00edni que comprou em sua \u00faltima visita a Paris. Com os \u00f3culos de sol nas m\u00e3os e o celular na outra, saiu do quarto e seguiu pelo corredor em dire\u00e7\u00e3o \u00e0s escadas para chegar ao hall de entrada da mans\u00e3o.\u00a0<br \/>\u2003\u2003Uma perfeita princesa da m\u00e1fia pronta para aproveitar seu primeiro dia de f\u00e9rias de ver\u00e3o com os amigos. No meio do caminho, seu iphone vibrou indicando uma mensagem de Giorgia. Uma risada boba, por saber o qu\u00e3o ansiosa a amiga estaria naquela manh\u00e3, a fez lembrar da reuni\u00e3o do grupo para celebrar o anivers\u00e1rio de casamento de Paolo Gasparri e Serena Gasparri, padrasto e m\u00e3e das g\u00eameas Angela e Teresa.<\/p>\r\n<div style=\"width: 60%; margin: auto;\">\r\n<p>\u2003\u2003<em>\u201cVoc\u00ea ainda vem me buscar, amiga?<\/em> <br \/>\u2003\u2003<em>Estou te esperando\u2026<\/em> <br \/>\u2003\u2003<em>Ahhh\u2026\u00a0<\/em> <br \/>\u2003\u2003<em>Voc\u00ea j\u00e1 acordou?<\/em> <br \/>\u2003\u2003<em>queen, n\u00e3o esquece de mim.\u201d<\/em><\/p>\r\n<\/div>\r\n\u2003\u2003Ela esperou mais alguns minutos at\u00e9 come\u00e7ar a digitar a resposta, sabendo muito bem o real motivo da ansiedade de Giorgia.\r\n<div style=\"width: 60%; margin: auto;\">\r\n<p align=\"right\"><em>J\u00e1 estou a caminho.<\/em><\/p>\r\n<\/div>\r\n<p>\u2003\u2003Em um s\u00e1bado ensolarado, %Luigi% havia convidado o grupo de amigos para um banho de piscina regado a divers\u00e3o e um impec\u00e1vel desjejum preparado por Carmen, a melhor cozinheira do mundo, segundo a fam\u00edlia Magnus. Ap\u00f3s meses focados em suas respectivas responsabilidades universit\u00e1rias ou colegiais, precisavam mesmo iniciar as f\u00e9rias de ver\u00e3o em grande estilo. Com todos vivendo a fase pr\u00e9-adulta de suas vidas e espalhados pelo mundo, mesmo com a aproxima\u00e7\u00e3o da tecnologia, os dias n\u00e3o eram os mesmos com a elite dos herdeiros da m\u00e1fia separados.<br \/>\u2003\u2003Apenas Clarisse e Andreas haviam retornado para casa, escolhendo uma universidade italiana para cursar. Giorgia mantinha seu foco em Oxford; j\u00e1 as g\u00eameas Gasparri, ap\u00f3s finalizarem os estudos no col\u00e9gio Constance, pretendiam seguir a carreira da moda, na <em>Parsons School of Design<\/em> em Manhattan. Robert havia optado por seguir o caminho do pai, na \u00e1rea comercial, iniciando o curso de marketing na <em>Yonsei University<\/em>, uma indica\u00e7\u00e3o de sua namorada coreana.<br \/>\u2003\u2003Quanto aos irm\u00e3os Magnus\u2026 %Luigi% seguia bem longe dos olhos carrascos de seu pai, sua escolha pelo curso de design na mesma universidade de %Giovanni% havia sido uma surpresa para a fam\u00edlia, principalmente para o irm\u00e3o mais velho. O ca\u00e7ula, como um bom Magnus, tinha seus segredos e talentos escondidos, e desenhar era um deles. Claro que inicialmente o pai se op\u00f4s, o que rendeu duas noites de recupera\u00e7\u00e3o no hospital, ap\u00f3s um grito de clem\u00eancia por parte do irm\u00e3o mais velho.<br \/>\u2003\u2003J\u00e1 %Giovanni%, o bom filho, seguia para a conclus\u00e3o de seu curso de administra\u00e7\u00e3o na cidade de Cambridge, em Harvard University, como esperado e sonhado pelos pais. Em seu \u00faltimo ano acad\u00eamico, tinha que dividir suas preocupa\u00e7\u00f5es entre os estudos, os neg\u00f3cios da fam\u00edlia, a especializa\u00e7\u00e3o que faria em Floren\u00e7a, dentre outras coisas. Todas, sempre ficando em segundo plano, quando seus pensamentos eram invadidos pela imagem de %Alice% e o gosto do beijo proibido. A filha da empregada que lhe causava constantes ins\u00f4nias.<br \/>\u2003\u2003\u2014 Sobrinha querida! \u2014 Marcella deixou seu tom surpreso sobressair, ao ver %Clarice% descendo as escadas. \u2014 Acordada t\u00e3o cedo?<br \/>\u2003\u2003\u2014 Bom dia para a senhora tamb\u00e9m, titia. \u2014 %Clarice% for\u00e7ou um sorriso gentil para ela, por obriga\u00e7\u00e3o e apar\u00eancia. \u2014 Impressionada estou eu, por v\u00ea-la em casa numa manh\u00e3 de s\u00e1bado.<br \/>\u2003\u2003Para a menina, a tia nunca lhe convenceu com aquele jeito falso de se preocupar com os sobrinhos e fingir uma dedica\u00e7\u00e3o que nunca existiu. Ela sabia, pelos muitos coment\u00e1rios soltos dos empregados, que Marcella sempre foi apaixonada pelo patriarca Tommaso, sentindo-se frustrada por ele ter desposado a falecida irm\u00e3 em seu lugar.<br \/>\u2003\u2003\u2014 E onde mais eu estaria? \u2014 indagou a tia, curiosa pelas palavras da sobrinha.<br \/>\u2003\u2003\u2014 No clube do livro, \u00e9 claro \u2014 respondeu %Clarice% com serenidade, fazendo-a se lembrar do nobre compromisso das senhoras da elite.<br \/>\u2003\u2003A <strong><em>Concetto di Libro<\/em><\/strong>, como era denominada a associa\u00e7\u00e3o das mulheres da elite da regi\u00e3o da Toscana, promovia todos os s\u00e1bados de manh\u00e3 uma reuni\u00e3o com suas membras para discutir e compartilhar ideias para os mais importantes eventos da regi\u00e3o, j\u00e1 que a maioria das senhoras associadas eram de fam\u00edlias da m\u00e1fia, mulheres de pol\u00edticos ou grandes empres\u00e1rios.<br \/>\u2003\u2003\u2014 Pelo que sei, a senhora \u00e9 a dama que representa nossa fam\u00edlia. \u2014 O tom de ironia escorreu com suavidade na voz da menina, n\u00e3o negando sua irrita\u00e7\u00e3o pela perman\u00eancia da tia naquela casa.<br \/>\u2003\u2003Era dif\u00edcil para %Clarice% esquecer das muitas vezes que presenciou, escondida, a tia humilhar sua m\u00e3e doente, dizendo que tomaria seu lugar ap\u00f3s a morte de Franci.<br \/>\u2003\u2003\u2014 Ah sim\u2026 Nosso encontro de hoje precisou ser cancelado, j\u00e1 que nossa presidente est\u00e1 em viagem. \u2014 Marcella deu um sorriso fraco como forma de descontrair o ambiente. \u2014 E voc\u00ea, querida, estava indo aonde?<br \/>\u2003\u2003\u2014 Tenho um compromisso, mas diga ao papai que estarei de volta a tempo para o jantar. \u2014 %Clarice% ajeitou a bolsa no ombro e se dirigiu at\u00e9 a porta.<br \/>\u2003\u2003Em frente \u00e0 casa, Vicenzo, j\u00e1 a aguardava prontamente ao lado de sua moto. Ap\u00f3s dar as devidas orienta\u00e7\u00f5es ao homem, lhe informou que passaria primeiro na casa da amiga, entrou no carro e deu a partida. Foram necess\u00e1rios quinze minutos para que finalmente Giorgia respirasse com mais tranquilidade ao v\u00ea-la, j\u00e1 Tommaso, se mantinha serena e tranquila como de costume.<br \/>\u2003\u2003\u2014 Me desculpe pela chuva de mensagens, mas voc\u00ea sabe que eu sou mega ansiosa \u2014 disse ela, ao entrar no carro, j\u00e1 se defendendo do olhar de Tommaso.<br \/>\u2003\u2003\u2014 Eu n\u00e3o disse nada. \u2014 %Clarice% segurou o riso, observando-a colocar o cinto de seguran\u00e7a.<br \/>\u2003\u2003\u2014 Mas seu olhar me condena \u2014 reclamou a amiga, ao terminar de se acomodar. \u2014 Ent\u00e3o\u2026 Voc\u00ea n\u00e3o me contou toda a fofoca no nosso encontro no pub.<br \/>\u2003\u2003\u2014 Defina qual fofoca? \u2014 %Clarice% murmurou n\u00e3o entendendo a pergunta.<br \/>\u2003\u2003\u2014 Sua irm\u00e3\u2026 Como est\u00e3o as coisas? Voc\u00ea disse que a visitou h\u00e1 pouco tempo \u2014 indagou Giorgia, que acompanhava a triste novela da vida de Diana. \u2014 Sabe que pode compartilhar comigo, eu pelo menos sei guardar segredo, ao contr\u00e1rio das g\u00eameas. \u2014 %Clarice% soltou uma gargalhada boba.<br \/>\u2003\u2003\u2014 Voc\u00ea n\u00e3o gosta mesmo delas, n\u00e3o \u00e9? \u2014 perguntou Tommaso, dando a partida novamente.<br \/>\u2003\u2003\u2014 Claro que n\u00e3o, s\u00e3o oferecidas e n\u00e3o possuem classe e nem discri\u00e7\u00e3o. \u2014 Ela bufou um pouco ao lhe passar uma lembran\u00e7a aleat\u00f3ria envolvendo uma das irm\u00e3s.<br \/>\u2003\u2003Uma cena devastadora para Giorgia, em que %Luigi% estava em movimentos intensos com Teresa, na adega de sua mans\u00e3o, em pleno dia de a\u00e7\u00e3o de gra\u00e7as. Uma cena que causou n\u00e1useas na garota apaixonada, que se sentiu com o cora\u00e7\u00e3o partido.<br \/>\u2003\u2003\u2014 Bem, voc\u00ea precisa dar um jeito de se acostumar com elas. \u2014 Tomasso se inclinou um pouco mais no banco e voltou o olhar para o retrovisor, observando seu seguran\u00e7a seguindo-as de moto. \u2014 J\u00e1 deveria, para ser honesta.<br \/>\u2003\u2003\u2014 S\u00f3 porque a m\u00e3e delas se casou com o encantador Paolo Gasparri \u2014 um suspiro surgiu da adolescente, como se contemplasse o homem em sua mente por alguns segundos, ent\u00e3o voltando a realidade \u2014, n\u00e3o quer dizer que elas tenham o direito de fazer parte do nosso grupo, elas nem nasceram em ber\u00e7o de ouro.<br \/>\u2003\u2003\u2014 Acho que nessa altura do jogo, n\u00e3o tem importado mais quem nasce ou n\u00e3o, todos somos pe\u00f5es nesse tabuleiro \u2014 sussurrou %Clarice%, de forma enigm\u00e1tica, ao se lembrar da situa\u00e7\u00e3o da irm\u00e3.<br \/>\u2003\u2003\u2014 O que voc\u00ea disse? \u2014 Giorgia a olhou confusa.<br \/>\u2003\u2003\u2014 Nada Gia, s\u00f3 foram meus devaneios. \u2014 %Clarice% riu baixo ao ver a amiga revirar os olhos, continuando seu mon\u00f3logo sobre como as g\u00eameas Gasparri n\u00e3o tinham o direito de serem da elite.<br \/>\u2003\u2003Ao chegarem na mans\u00e3o Magnus, foram recebidas prontamente pela governanta, senhora Gertrudes Vernice, que as guiou at\u00e9 o jardim que j\u00e1 estava movimentada pelos convidados. Logo que Tommaso entrou no campo de vis\u00e3o do ca\u00e7ula Magnus, %Luigi% se afastou dos insepar\u00e1veis amigos e caminhou at\u00e9 ela, com um sorriso largo no rosto.<br \/>\u2003\u2003\u2014 Achei que n\u00e3o viesse mais \u2014 disse ele ao parar em frente \u00e0 amiga com um brilho discreto nos olhos \u2014, senhorita atrasada.<br \/>\u2003\u2003\u2014 Eu nunca estou atrasada. \u2014 Ela se aproximou do rapaz com descontra\u00e7\u00e3o e o abra\u00e7ou, beijando seu rosto em seguida. \u2014 Simplesmente sou dona dos meus hor\u00e1rios.<br \/>\u2003\u2003\u2014 E do meu cora\u00e7\u00e3o \u2014 afirmou %Luigi% em um tom de brincadeira, mas com um fundo de verdade, ignorando completamente a presen\u00e7a de Giorgia ao lado da amiga.<br \/>\u2003\u2003%Clarice% riu de leve, levando na brincadeira as palavras dele. Entretanto, para a amiga ao lado, era frustrante que o homem a quem entregou seu cora\u00e7\u00e3o no anivers\u00e1rio de quinze anos, nem mesmo lhe desse a aten\u00e7\u00e3o de anfitri\u00e3o. Para %Luigi%, aquela havia sido apenas mais uma noite de prazer com uma garota inocente que decidiu, erroneamente, usar sua pureza para conquist\u00e1-lo.<br \/>\u2003\u2003\u2014 Diz isso para todas, com certeza \u2014 brincou %Clarice%, tentando suavizar o ambiente.<br \/>\u2003\u2003\u2014 N\u00e3o para todas, apenas para as que j\u00e1 tem dono. \u2014 A voz de %Giovanni% soou atr\u00e1s dela, fazendo o corpo da garota arrepiar de leve com a entona\u00e7\u00e3o dele.<br \/>\u2003\u2003Logo, ela sentiu as m\u00e3os do primog\u00eanito tocarem sua cintura, assim como a aproxima\u00e7\u00e3o de seu corpo.<br \/>\u2003\u2003\u2014 Est\u00e1 atrasada \u2014 sussurrou %Giovanni%, no ouvido de %Clarice%.<br \/>\u2003\u2003\u2014 Eu nunca estou atrasada. \u2014 Ela se virou para o rapaz, com um sorriso sutil. \u2014 Estou no meu hor\u00e1rio.<br \/>\u2003\u2003\u2014 Olha o estraga prazeres\u2026 \u2014 %Luigi% bufou um pouco, revirando os olhos pela presen\u00e7a do irm\u00e3o.<br \/>\u2003\u2003J\u00e1 estava irritado o suficiente pelo primog\u00eanito ter se intrometido em sua brincadeira com uma das novas empregadas da casa, agora estava ainda mais frustrado por saber que o favorito certamente seria o assunto e centro das aten\u00e7\u00f5es da sua festa na piscina, pois j\u00e1 estava em seus preparativos finais para assumir oficialmente o lugar do pai.<br \/>\u2003\u2003\u2014 Deveria ser mais educado, %Luigi%, afinal, minha <strong>noiva<\/strong> n\u00e3o chegou sozinha. \u2014 %Giovanni% piscou de leve para %Clarice%, ent\u00e3o voltou a aten\u00e7\u00e3o para a menina ao seu lado. \u2014 Buongiorno, Giorgia.<br \/>\u2003\u2003\u2014 Buongiorno, Magnus \u2014 disse a garota, ainda est\u00e1tica com toda a cena, tentando esconder sua frustra\u00e7\u00e3o.<br \/>\u2003\u2003Giorgia Moretti era filha do dono da maior transportadora do pa\u00eds, que prestava servi\u00e7os terceirizados de envios e entregas para todos os neg\u00f3cios da m\u00e1fia. Com isso, sua fam\u00edlia foi ficando cada vez mais valorizada entre a realeza da Toscana. Mas \u00e9 claro que alguns ainda n\u00e3o os viam com bons olhos e nem os tratavam com o respeito que mereciam, ainda que fossem nobres entre a elite. Entretanto, a jovem, ainda que soubesse do car\u00e1ter duvidoso de %Luigi% e sendo visivelmente desprezada por ele, mesmo ap\u00f3s sua entrega precipitada de dois anos atr\u00e1s, continuava a persistir em manter sua fascina\u00e7\u00e3o pelo ca\u00e7ula Magnus.<br \/>\u2003\u2003\u2014 Fiquem \u00e0 vontade. \u2014 %Luigi% deixou seu rosto com a express\u00e3o mais s\u00e9ria, n\u00e3o escondendo a insatisfa\u00e7\u00e3o da presen\u00e7a do irm\u00e3o, e se afastou voltando para onde seus amigos estavam.<br \/>\u2003\u2003\u2014 Eu vou cumprimentar os outros \u2014 disse Giorgia, se apressando para se afastar deles e correr atr\u00e1s do anfitri\u00e3o.<br \/>\u2003\u2003Naqueles poucos segundos, %Clarice% manteve sua aten\u00e7\u00e3o em %Giovanni%, que seguia com serenidade seu olhar para o irm\u00e3o ao longe.<br \/>\u2003\u2003\u2014 Voc\u00ea realmente n\u00e3o facilita para ele \u2014 comentou ela, fazendo-o olh\u00e1-la.<br \/>\u2003\u2003Era aquele olhar misterioso e profundo, que lhe causava devaneios.<br \/>\u2003\u2003\u2014 Por que eu deveria facilitar? \u2014 indagou %Giovanni%, mantendo seu habitual tom s\u00e9rio, por\u00e9m, o rosto sereno.<br \/>\u2003\u2003\u2014 %Luigi% s\u00f3 estava brincando\u2026 Para ser honesta, ele gosta de te provocar. \u2014 Tommaso riu baixo, lembrando das muitas vezes que o cunhado se declarou para ela.<br \/>\u2003\u2003\u2014 Infelizmente, meu irm\u00e3o tem um p\u00e9ssimo h\u00e1bito de sempre querer aquilo que n\u00e3o pode ter \u2014 explicou o mais velho, o ponto chave, contudo, internamente ele tamb\u00e9m carregava aquela frase para si, sempre que lutava contra seus pensamentos relacionados \u00e0 %Alice%.<br \/>\u2003\u2003\u2014 Virei um objeto agora?! \u2014 A garota deu um passou para tr\u00e1s, encarando-o com a sobrancelha direita arqueada.<br \/>\u2003\u2003\u2014 Voc\u00ea quer ser um? \u2014 retrucou ele, ainda com as m\u00e3os em sua cintura, puxando-a de volta, beijou seu pesco\u00e7o e sussurrou. \u2014 Tommaso\u2026<br \/>\u2003\u2003\u2014 Pare de me provocar\u2026 \u2014 Ela brincou de dizer a verdade, rindo de nervoso, ao empurr\u00e1-lo novamente com mais sutileza. \u2014 Vamos esquecer isso e aproveitar o dia? Ansioso pelo seu \u00faltimo ano da faculdade?<br \/>\u2003\u2003\u2014 Eu ainda n\u00e3o\u2026 \u2014 Ele respirou fundo ao desviar o olhar rapidamente para a empregada L\u00eddia, servindo os convidados.<br \/>\u2003\u2003Por um breve momento seus pensamentos se transportaram para o dia em que a filha da empregada lhe salvou na piscina, e seu olhar que lhe causava ainda mais conflitos internos. Um momento de sua vida que n\u00e3o conseguia entender se desejava esquecer ou eternizar.<br \/>\u2003\u2003\u2014 Voc\u00ea ainda\u2026 \u2014 A voz de %Clarice% o despertou a aten\u00e7\u00e3o. \u2014 Est\u00e1 tudo bem?<br \/>\u2003\u2003\u2014 Claro que sim\u2026 Apenas algumas preocupa\u00e7\u00f5es bobas \u2014 explicou %Giovanni% com uma desculpa eventual.<br \/>\u2003\u2003\u2014 E meu noivo vai ficar me monopolizando assim? Ou posso cumprimentar nossos amigos? \u2014 indagou Tommaso, de forma provocante, ao envolver seus bra\u00e7os no pesco\u00e7o do rapaz.<br \/>\u2003\u2003\u2014 Bem\u2026 \u2014 Ele lan\u00e7ou um olhar sugestivo, espantando seus pensamentos inoportunos. \u2014 O que vou ganhar dividindo sua aten\u00e7\u00e3o com os outros?<br \/>\u2003\u2003\u2014 Hum\u2026 \u2014 Ela se aproximou mais um pouco e o beijou de leve.<br \/>\u2003\u2003Por mais que %Clarice% fosse racional e inteligente, ela havia se deixado levar pelos acordos familiares com as circunst\u00e2ncias da vida, permitindo a seu cora\u00e7\u00e3o criar sentimentos por %Giovanni%. Ambos estavam prometidos um ao outro, antes mesmo da garota nascer, ap\u00f3s o an\u00fancio de que seria mais uma menina para a fam\u00edlia Tommaso. Afinal, o sonho dos amigos Elio e Francisco sempre foi unir as fam\u00edlias em um la\u00e7o forte de matrim\u00f4nio, e como Diana era mais velha que o primog\u00eanito Magnus, havia ficado para a bela %Clarice% a miss\u00e3o de se casar com o favorito.<br \/>\u2003\u2003\u2014 Confesso que estou ansiosa para seu retorno definitivo para casa \u2014 comentou ela ao se afastar do noivo, mordiscando seu l\u00e1bio inferior. \u2014 Assim poderemos come\u00e7ar a planejar o casamento.<br \/>\u2003\u2003\u2014 Achei que quisesse esperar at\u00e9 a sua formatura. \u2014 Magnus manteve a serenidade no olhar.<br \/>\u2003\u2003\u2014 Meu pai vem falando muito no assunto, e\u2026 Al\u00e9m do mais \u2014 ela suspirou levemente \u2014, n\u00e3o v\u00e1 pensando que ficarei atr\u00e1s de voc\u00ea o tempo todo, te esperando \u2014 alertou ela ao segurar m\u00e3o dele e come\u00e7ar a andar.<br \/>\u2003\u2003\u2014 N\u00e3o se preocupe, querida, sabe que eu sou o ciumento da rela\u00e7\u00e3o \u2014 brincou %Giovanni%, arrancando algumas risadas dela.<br \/>\u2003\u2003%Clarice% assentiu ainda rindo, voltando a aten\u00e7\u00e3o para o grupo de amigos que conversava mais \u00e0 frente. Mesmo com o dia ensolarado, a brisa do outono tornou tudo ainda mais leve e descontra\u00eddo, com conversas aleat\u00f3rias e mergulhos na piscina.<br \/>\u2003\u2003Ap\u00f3s desfrutar da farta mesa do desjejum, %Clarice% e Giorgia trocaram suas roupas no quarto de h\u00f3spedes em risos e coment\u00e1rios pontuais.<br \/>\u2003\u2003\u2014 Giorgia, um conselho de amiga\u2026 \u2014 %Clarice% voltou para seu reflexo no espelho, observando a vaidade dela. \u2014 Qualquer vislumbre de esperan\u00e7a, n\u00e3o alimente\u2026 O %Luigi% \u00e9 bem complexo de entender e mais ainda de se insistir.<br \/>\u2003\u2003\u2014 Ele sempre se mostrou bem cavalheiro com voc\u00ea \u2014 retrucou ela, tentando criar um argumento, falhando miseravelmente.<br \/>\u2003\u2003\u2014 Ele me trata assim porque somos amigos desde crian\u00e7a, crescemos juntos e sou a noiva do irm\u00e3o dele \u2014 explicou Tommaso, para clarear a mente da amiga. \u2014 Voc\u00ea j\u00e1 viu a forma com que ele descarta as garotas com quem fica? Voc\u00ea j\u00e1 sofreu isso e, sinceramente, n\u00e3o quero que continue com esse sentimento masoquista.<br \/>\u2003\u2003\u2014 Mas eu n\u00e3o consigo ficar longe\u2026 Ele \u00e9 t\u00e3o fofo, com aqueles olhos de cachorro sem dono. \u2014 Giorgia se sentiu internamente derretida. \u2014 Como pode algu\u00e9m assim ser t\u00e3o frio e grosso?!<br \/>\u2003\u2003\u2014 Quanto mais se apanha da vida, mais resist\u00eancia a sentimentos voc\u00ea cria \u2014 disse Tommaso, mais uma vez em sua forma enigm\u00e1tica, sabendo dos muitos ocorridos nos por\u00f5es daquela mans\u00e3o.<br \/>\u2003\u2003\u2014 O que voc\u00ea quis dizer com isso? \u2014 indagou a amiga.<br \/>\u2003\u2003\u2014 Nada. \u2014 %Clarice% respirou fundo, reunindo mansid\u00e3o. \u2014 Apenas se cuide.\u00a0<br \/>\u2003\u2003Giorgia assentiu prontamente e se retirou primeiro do quarto. Ela estava parcialmente chateada por %Luigi% ter criado mais proximidade com Angela, a g\u00eamea mais velha, causando-lhe um pequeno sentimento de ci\u00fames.<br \/>\u2003\u2003Ainda no quarto, %Clarice% dobrou suas roupas e deixou ao lado da bolsa em cima da cama, ent\u00e3o, saindo para o corredor, notou que a porta do quarto de %Giovanni% estava entreaberta. Se aproximando mais um pouco, ela o viu um pouco desnorteado com seus pr\u00f3prios pensamentos internos, algo que o fez socar a porta do closet.<br \/>\u2003\u2003\u2014 Majestade\u2026 \u2014 A voz de %Clarice% soou com leveza, enquanto ela adentrava o espa\u00e7o com o olhar preocupado para ele. \u2014 Algum problema?<br \/>\u2003\u2003\u2014 Me deixe sozinho \u2014 pediu ele num tom \u00e1spero, sentindo sua garganta arder como se um grito estivesse preso dentro dele.<br \/>\u2003\u2003\u2014 Eu n\u00e3o vou. \u2014 Ela fechou a porta e caminhou at\u00e9 o banheiro para encontrar a caixa de primeiros socorros.<br \/>\u2003\u2003Assim como %Luigi%, ela tamb\u00e9m conhecia o mais velho muito bem para saber que se ele ficasse sozinho, poderia se machucar ainda mais. %Clarice% conhecia cada cent\u00edmetro daquela casa, desde o s\u00f3t\u00e3o at\u00e9 as passagens secretas no escrit\u00f3rio e na adega. Sua inf\u00e2ncia foi em partes na casa dos amigos de seu pai, que o apoiou com muito afinco, principalmente ap\u00f3s a morte de sua m\u00e3e.<br \/>\u2003\u2003\u2014 Me deixe cuidar de voc\u00ea \u2014 disse ela, ao tocar em sua m\u00e3o ensanguentada e o guiar at\u00e9 a cadeira para se sentar.<br \/>\u2003\u2003\u2014 Eu estou bem, n\u00e3o deveria\u2026 \u2014 Ele tentou questionar.<br \/>\u2003\u2003\u2014 Pare de me expulsar, %Giovanni%, ainda falta algum tempo, mas j\u00e1 somos noivos \u2014 explicou ela, abrindo a caixa e pegando o algod\u00e3o. \u2014 Um dia serei a sua esposa, ent\u00e3o, \u00e9 melhor treinar agora.<br \/>\u2003\u2003\u2014 N\u00e3o entendo como consegue \u2014 comentou o mais velho, impressionado com a garota a sua frente.<br \/>\u2003\u2003\u2014 Como consigo, o que? \u2014 indagou %Clarice%, curiosa, mantendo o olhar atento na ferida do rapaz.<br \/>\u2003\u2003\u2014 Ser gentil com os herdeiros mais problem\u00e1ticos da m\u00e1fia. \u2014 %Giovanni% deixou sua voz mais suave, num tom descontra\u00eddo.<br \/>\u2003\u2003\u2014 Voc\u00ea e o %Luigi% s\u00e3o as pessoas mais complexas e dif\u00edceis de decifrar que eu conhe\u00e7o, o que me leva a n\u00e3o entender o porqu\u00ea sempre se machucam quando est\u00e3o com raiva, mas\u2026 \u2014 declarou ela, abertamente. \u2014 Aprendi a gostar de voc\u00eas, exatamente como s\u00e3o.<br \/>\u2003\u2003\u2014 N\u00e3o acho que deveria gostar do meu irm\u00e3o \u2014 brincou %Giovanni% de forma debochada e sarc\u00e1stica \u2014, mas quanto a mim, n\u00e3o deveria me amar? Minha noiva.<br \/>\u2003\u2003\u2014 Vou te amar apenas ap\u00f3s o casamento \u2014 assegurou ela, com confian\u00e7a. \u2014 N\u00e3o quero sofrer por antecipa\u00e7\u00e3o.<br \/>\u2003\u2003\u2014 Racional como sempre \u2014 sussurrou ele, fazendo-a rir.<br \/>\u2003\u2003Assim que ela terminou de colocar o curativo, seu olhar singelo se voltou para ele ao sentir as m\u00e3os de %Giovanni% deslizar por sua cintura.<br \/>\u2003\u2003\u2014 N\u00e3o vai mesmo me contar suas preocupa\u00e7\u00f5es? \u2014 insistiu ela, sabendo que tinha algo mais s\u00e9rio por tr\u00e1s do surto de raiva.<br \/>\u2003\u2003\u2014 N\u00e3o s\u00e3o importantes. \u2014 Magnus encostou de leve sua cabe\u00e7a na barriga dela, logo sentindo-a acariciar seus cabelos.<br \/>\u2003\u2003\u2014 Ent\u00e3o, vai entrar na piscina comigo? \u2014 retrucou %Clarice%, tentando sutilmente detectar a causa.<br \/>\u2003\u2003\u2014 N\u00e3o gosto muito dessas programa\u00e7\u00f5es \u2014 brincou o rapaz.<br \/>\u2003\u2003\u2014 %Giovanni%, n\u00e3o me diga que ainda tem medo da \u00e1gua?! \u2014 Ela se mostrou surpresa. \u2014 \u00c9 por isso que est\u00e1 assim?<br \/>\u2003\u2003\u2014 Claro que n\u00e3o. \u2014 Ele se levantou da cadeira e se afastou dela, n\u00e3o queria dizer o real motivo, mas tamb\u00e9m n\u00e3o mentiria.<br \/>\u2003\u2003\u2014 Ent\u00e3o o que \u00e9?! O que te fez ficar assim? \u2014 A garota apontou para a m\u00e3o dele com o curativo.<br \/>\u2003\u2003%Clarice% sabia muito bem os limites entre a amizade e o compromisso que ambos tinham com suas fam\u00edlias. Ela sabia que no n\u00edvel de hierarquia patriarcal da m\u00e1fia, o papel da mulher era sempre cumprir com seus deveres de boa filha e futuramente dedicada esposa, sem jamais confrontar a autoridade da fam\u00edlia. Entretanto, seu g\u00eanio forte n\u00e3o lhe permitia abaixar a cabe\u00e7a para tudo.<br \/>\u2003\u2003\u2014 Posso apenas n\u00e3o dizer o que \u00e9?! \u2014 O olhar de %Giovanni% se voltou para ela, visivelmente segurava suas emo\u00e7\u00f5es, de raiva e frustra\u00e7\u00e3o. \u2014 N\u00e3o quero brigar com a minha melhor amiga.<br \/>\u2003\u2003\u2014 N\u00e3o vai. \u2014 Ela deixou surgir um sorriso singelo e acolhedor em sua face, ent\u00e3o se aproximou dele e o abra\u00e7ou apertado.<br \/>\u2003\u2003Por mais que %Giovanni% n\u00e3o se abrisse para ela, tanto quanto o irm\u00e3o, ela sabia que havia uma grande press\u00e3o sobre os ombros do primog\u00eanito que nem mesmo %Luigi% conseguiria carregar. Ser o preferido n\u00e3o era exatamente um privil\u00e9gio que lhe trazia o poder da liberdade, mas, assim como todos, tamb\u00e9m havia um alto pre\u00e7o a ser pago.\u00a0<br \/>\u2003\u2003O pre\u00e7o da perfei\u00e7\u00e3o.<\/p>\r\n<p align=\"right\">Deixe-me ser sua soberana (soberana) <br \/>\u2003\u2003Voc\u00ea pode me chamar de abelha-rainha <br \/>\u2003\u2003E, amor, eu vou reinar (vou reinar, vou reinar) <br \/>\u2003\u2003Deixe-me viver essa fantasia. <br \/>\u2003\u2003<strong>&#8211; Royals \/ Lorde<\/strong><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Mil\u00e3o, ver\u00e3o de 2015 \u2003\u2003\u201cVoc\u00ea ainda vem me buscar, amiga? \u2003\u2003Estou te esperando\u2026 \u2003\u2003Ahhh\u2026\u00a0 \u2003\u2003Voc\u00ea j\u00e1 acordou? \u2003\u2003queen, n\u00e3o esquece de mim.\u201d J\u00e1 estou a caminho. Deixe-me ser sua soberana (soberana) \u2003\u2003Voc\u00ea pode me chamar de abelha-rainha \u2003\u2003E, amor, eu vou reinar (vou reinar, vou reinar) \u2003\u2003Deixe-me viver essa fantasia. \u2003\u2003&#8211; Royals \/ Lorde<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":true,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"historias":[1611],"class_list":["post-4587","capitular","type-capitular","status-publish","format-standard","hentry","historias-mafias-paradise"],"acf":[],"_links":{"self":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular\/4587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular"}],"about":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/types\/capitular"}],"author":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/comments?post=4587"}],"wp:attachment":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/media?parent=4587"}],"wp:term":[{"taxonomy":"historias","embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/historias?post=4587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}