{"id":10585,"date":"2026-07-08T16:22:52","date_gmt":"2026-07-08T19:22:52","guid":{"rendered":"https:\/\/espacocriativo.net\/acervo\/historia\/historia-sem-nome\/rascunho-automatico\/"},"modified":"2026-07-08T16:24:59","modified_gmt":"2026-07-08T19:24:59","slug":"prologo","status":"publish","type":"capitular","link":"https:\/\/espacocriativo.net\/acervo\/historia\/osfilhosdaexpulsaovolume1\/prologo\/","title":{"rendered":"Pr\u00f3logo"},"content":{"rendered":"\r\n<p>\u2003\u2003<span class=\"versalete\">Em J\u00f3 38:4-7,<\/span> Deus afirma que quando lan\u00e7ou os fundamentos da Terra, todos os anjos (chamados de &#8220;filhos de Deus&#8221;) rejubilavam e cantavam de alegria. Eles n\u00e3o possuem corpo f\u00edsico original, embora possam manifestar-se em forma humana. Foram criados com livre-arb\u00edtrio, raz\u00e3o pela qual uma parte deles rebelou-se contra Deus posteriormente.<br>\u2003\u2003A B\u00edblia descreve a exist\u00eancia de milh\u00f5es de anjos organizados em diferentes fun\u00e7\u00f5es e hierarquias (como querubins e serafins).<\/p>\r\n<p>\u2003\u2003<em>No princ\u00edpio criou Deus os c\u00e9us e a terra.<\/em><br>\u2003\u2003<em>E a terra era sem forma e vazia; e havia trevas sobre a face do abismo; e o Esp\u00edrito de Deus se movia sobre a face das \u00e1guas.<\/em><br>\u2003\u2003<em>E disse Deus: Haja luz; e houve luz.<\/em><br>\u2003\u2003<em>E viu Deus que era boa a luz; e fez Deus separa\u00e7\u00e3o entre a luz e as trevas.<\/em><br>\u2003\u2003<em>E Deus chamou \u00e0 luz Dia; e \u00e0s trevas chamou Noite. E foi a tarde e a manh\u00e3, o dia primeiro.<\/em><br>\u2003\u2003<em>E disse Deus: Haja uma expans\u00e3o no meio das \u00e1guas, e haja separa\u00e7\u00e3o entre \u00e1guas e \u00e1guas.<\/em><br>\u2003\u2003<em>E fez Deus a expans\u00e3o, e fez separa\u00e7\u00e3o entre as \u00e1guas que estavam debaixo da expans\u00e3o e as \u00e1guas que estavam sobre a expans\u00e3o; e assim foi.<\/em><br>\u2003\u2003<em>E chamou Deus \u00e0 expans\u00e3o C\u00e9us, e foi a tarde e a manh\u00e3, o dia segundo.<\/em><br>\u2003\u2003<em>E disse Deus: Ajuntem-se as \u00e1guas debaixo dos c\u00e9us num lugar; e apare\u00e7a a por\u00e7\u00e3o seca; e assim foi.<\/em><br>\u2003\u2003<em>E chamou Deus \u00e0 por\u00e7\u00e3o seca Terra; e ao ajuntamento das \u00e1guas cham<\/em><br>\u2003\u2003<strong>G\u00eanesis 1:1-10 | ACF<\/strong><\/p>\r\n<p>\u2003\u2003Anu era o &#8220;senhor das constela\u00e7\u00f5es, rei dos esp\u00edritos e dos dem\u00f4nios&#8221;. Anu habitava as mais altas regi\u00f5es celestiais. Era tido tamb\u00e9m como juiz dos homens e dos deuses, tendo criado as estrelas do c\u00e9u para o servirem como seus soldados, encarregadas de perseguir e punir os criminosos. Anu era o pai dos Anun\u00e1qui (tamb\u00e9m chamados de Anunacu). Mas esta n\u00e3o \u00e9 a total hist\u00f3ria da humanidade. E era a humanidade sem forma e vazia e disse Deus, haja luz. E houve luz. E Deus viu que era bom e criou os anjos. E junto com os anjos, criou %Lucifer% seu primeiro querubim. E Deus muito amou sua cria\u00e7\u00e3o. L\u00facifer e os outros anjos eram perfeitos em sua cria\u00e7\u00e3o, eram os que mais se assemelhavam a Deus, sendo %Lucifer% o mais perfeito de todos, eles cantavam hinos de louvor a Deus e todos os anjos o admiravam. O Pai o tinha como muito estimado. %Lucifer% e os demais anjos faziam miss\u00f5es, andando pela terra com suas asas, aprendendo tudo que o Pai ensinava e auxiliando nas causas do pai. Eles completavam suas miss\u00f5es, cantavam hinos de louvor e faziam tudo perfeitamente. Havia paz no c\u00e9u. Os anjos viviam suas vidas cotidianas. A humanidade que ainda n\u00e3o era humanidade, mas sim os primeiros seres, respiravam e viviam bem. N\u00e3o havia mal, nem dor, mesmo havendo dinossauros no mundo. E assim o c\u00e9u brilhava. Deus observava sua cria\u00e7\u00e3o com um leve sorriso sereno, contemplando tudo. Ele fazia de tudo pelos anjos, cuidando para que eles se sentissem especiais. Os dias se passavam lentamente nos c\u00e9us. Tudo era muito primitivo, mas n\u00e3o menos bonito. As cidades celestiais transmitiam o suave amor de Deus e seu amor pela cria\u00e7\u00e3o. E o amor pelos seus anjos e sua harmonia. Miguel, %Lucifer%, Rafael e %Gabriel% entre eles. Os outros tr\u00eas admiravam %Lucifer%, que sempre tratava todos com respeito e entoava maravilhosos cantos de louvor a Deus. %Lucifer% entoava lindas liras e vivia tranquilamente no c\u00e9u. Dias se passaram e cada dia, um dos diversos anjos tinham uma miss\u00e3o e a completava com sucesso, enquanto Deus observava de seu trono celestial.<br>\u2003\u2003\u2014 Meu senhor \u2014 disse %Lucifer% com temor a Deus, suas asas perfeitamente alinhadas. \u2014 As m\u00fasicas de harmonia est\u00e1 completa, os anjos encontraram equil\u00edbrio e servir \u00e9 minha ess\u00eancia \u2014 diz %Lucifer% com carinho contemplando o c\u00e9u.<br>\u2003\u2003Deus observou seu querubim da guarda com afei\u00e7\u00e3o. Miguel, Gabrel, Rafael, entre outros anjos observavam tudo admirados.<br>\u2003\u2003Entretanto um dia, algo aconteceu.<br>\u2003\u2003\u2014 Por que ele \u00e9 t\u00e3o glorioso, agora precisamos nos curvar as cria\u00e7\u00f5es humanas? \u2014 se perguntou %Lucifer% certa vez, vendo que Deus planejava criar Ad\u00e3o e Eva, o primeiro casal humano depois que todas as outras cria\u00e7\u00f5es humanas foram desfeitas.<br>\u2003\u2003Uma luz divina ecoou como se o respondesse.<br>\u2003\u2003\u2014 Por que os inferiores devem ser servidos? \u2014 %Lucifer% se perguntou mais uma vez.<\/p>\r\n<p align=\"center\">******<\/p>\r\n<p>\u2003\u2003<em>C\u00c9U, IN\u00cdCIO<\/em><br>\u2003\u2003\u2014 Uriel, voc\u00ea n\u00e3o acha que devemos questionar o Criador? \u2014 perguntou %Lucifer% certa vez. \u2014 Para que nos curvar a meras representa\u00e7\u00f5es humanas.<br>\u2003\u2003\u2014 O Pai quer assim \u2014 respondeu %Gabriel% pensativo.<br>\u2003\u2003\u2014 Mas por qu\u00ea? \u2014 perguntou %Lucifer%. \u2014 Veja, n\u00f3s merecemos adora\u00e7\u00e3o e n\u00e3o esses humanos.<br>\u2003\u2003\u2014 %Lucifer% \u2014 come\u00e7ou Miguel.<br>\u2003\u2003Mas %Lucifer% continuou seguindo esse caminho, agora tendo inveja no cora\u00e7\u00e3o. Um sorriso frio substituiu seu rosto at\u00e9 ent\u00e3o sereno.<br>\u2003\u2003N\u00e3o demorou muito para que o c\u00e9u sentisse esse contraste. O c\u00e9u estremecia como se a situa\u00e7\u00e3o fosse tensa. Agora, %Lucifer% silenciosamente come\u00e7ava a fazer pequenas reuni\u00f5es com anjos. Ele tentava colecionar aliados, contra Ad\u00e3o e Eva, que come\u00e7avam a ser criados na terra como homem e mulher. Agora no \u00c9den, Ad\u00e3o e Eva come\u00e7avam a habitar ali. J\u00e1 %Lucifer% fazia pequenas reuni\u00f5es incentivando anjos a se rebelarem contra Deus. Com muita dificuldade, mas igual carisma, %Lucifer% com sua beleza e charme, consegue conquistar alguns para sua causa. %Lucifer% certo dia, aparece diante de Deus e diz:<br>\u2003\u2003\u2014 Pai, venho n\u00e3o como s\u00fadito, mas como um ser que merece o trono a seu lado, verdadeira igualdade e submiss\u00e3o dos outros.<br>\u2003\u2003\u2014 %Lucifer%, j\u00e1 lhe dei tudo \u2014 argumenta a voz divina.<br>\u2003\u2003\u2014 N\u00e3o \u00e9 suficiente! \u2014 ele sorri friamente.<\/p>\r\n<p align=\"center\"><em>E houve batalha no c\u00e9u: Miguel e os seus anjos batalhavam contra o drag\u00e3o; e batalhavam o drag\u00e3o e os seus anjos, mas n\u00e3o prevaleceram; nem mais o seu lugar se achou nos c\u00e9us.<\/em><br><em>E foi precipitado o grande drag\u00e3o, a antiga serpente, chamada o diabo e Satan\u00e1s, que engana todo o mundo; ele foi precipitado na terra, e os seus anjos foram lan\u00e7ados com ele.<\/em><\/p>\r\n<p align=\"center\">*********<\/p>\r\n<p>\u2003\u2003Uma mulher humana observava o jardim do \u00c9den com interesse crescente. A mulher chamada Lilith, era jovem e extremamente bela. Ela via seu antigo companheiro agora feliz ao lado de Eva. Um sentimento de cobi\u00e7a e at\u00e9 mesmo ressentimento a incomodava. Ela sabia que n\u00e3o poderia ser feliz. %Lucifer% vendo que a mulher parece triste, a observa com olhar calculista. Se aproxima cautelosamente, com a apar\u00eancia de um jovem bonito, Samael e a aborda:<br>\u2003\u2003\u2014 O que a bela dama olha? \u2014 perguntou.<br>\u2003\u2003\u2014 Olho Ad\u00e3o e Eva \u2014 respondeu ela simplesmente.<br>\u2003\u2003\u2014 Eu vejo \u2014 respondeu Samael com um sorriso que n\u00e3o alcan\u00e7ava seus olhos. \u2014 Talvez quisesse o lugar de Eva.<br>\u2003\u2003\u2014 N\u00e3o \u00e9 isso \u2014 se defendeu Lilith.<br>\u2003\u2003\u2014 Eu poderia ajudar, tamb\u00e9m n\u00e3o gosto deles \u2014 diz %Lucifer%.<br>\u2003\u2003\u2014 Como? \u2014 pergunta Lilith. \u2014 Tentei tudo.<br>\u2003\u2003\u2014 Nem tudo, querida \u2014 responde %Lucifer% com um sorriso renovado.<\/p>\r\n<p align=\"center\">******<\/p>\r\n<p>\u2003\u2003<em>Ora, a serpente era mais astuta que todos os animais do campo que o Senhor Deus tinha feito. E esta disse \u00e0 mulher: \u00c9 assim que Deus disse: N\u00e3o comereis de toda a \u00e1rvore do jardim?<\/em><br>\u2003\u2003<em>E disse a mulher \u00e0 serpente: Do fruto das \u00e1rvores do jardim comeremos,<\/em><br>\u2003\u2003<em>Mas do fruto da \u00e1rvore que est\u00e1 no meio do jardim, disse Deus: N\u00e3o comereis dele, nem nele tocareis para que n\u00e3o morrais.<\/em><br>\u2003\u2003<em>Ent\u00e3o a serpente disse \u00e0 mulher: Certamente n\u00e3o morrereis.<\/em><br>\u2003\u2003<em>Porque Deus sabe que no dia em que dele comerdes se abrir\u00e3o os vossos olhos, e sereis como Deus, sabendo o bem e o mal.<\/em><br>\u2003\u2003<em>E viu a mulher que aquela \u00e1rvore era boa para se comer, e agrad\u00e1vel aos olhos, e \u00e1rvore desej\u00e1vel para dar entendimento; tomou do seu fruto, e comeu, e deu tamb\u00e9m a seu marido, e ele comeu com ela.<\/em><br>\u2003\u2003<em>Ent\u00e3o foram abertos os olhos de ambos, e conheceram que estavam nus; e coseram folhas de figueira, e fizeram para si aventais.<\/em><br>\u2003\u2003<strong>G\u00eanesis 3:1-7 | ACF<\/strong><br>\u2003\u2003<strong>B\u00edblia Online<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>\u2003\u2003No princ\u00edpio criou Deus os c\u00e9us e a terra.\u2003\u2003E a terra era sem forma e vazia; e havia trevas sobre a face do abismo; e o Esp\u00edrito de Deus se movia sobre a face das \u00e1guas.\u2003\u2003E disse Deus: Haja luz; e houve luz.\u2003\u2003E viu Deus que era boa a luz; e fez Deus separa\u00e7\u00e3o entre [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":0,"parent":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"_members_access_role":[],"_members_access_error":""},"historias":[2728],"class_list":["post-10585","capitular","type-capitular","status-publish","format-standard","hentry","historias-osfilhosdaexpulsaovolume1"],"acf":[],"_links":{"self":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular\/10585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/capitular"}],"about":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/types\/capitular"}],"author":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/comments?post=10585"}],"wp:attachment":[{"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/media?parent=10585"}],"wp:term":[{"taxonomy":"historias","embeddable":true,"href":"https:\/\/espacocriativo.net\/acervo\/wp-json\/wp\/v2\/historias?post=10585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}